{"id":8427,"date":"1941-08-20T17:54:17","date_gmt":"1941-08-20T16:54:17","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?p=8427"},"modified":"2017-05-10T19:53:19","modified_gmt":"2017-05-10T17:53:19","slug":"son-aviones-que-para-malasia-no-dejan-nada-que-desear","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1941\/08\/20\/son-aviones-que-para-malasia-no-dejan-nada-que-desear\/","title":{"rendered":"\u00abSon aviones que para Malasia no dejan nada que desear\u00bb"},"content":{"rendered":"<h3><strong><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/08\/brewsterbuffalorafsingapur1942.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8432 size-full\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/08\/brewsterbuffalorafsingapur1942.jpg\" alt=\"brewsterbuffalorafsingapur1942\" width=\"2965\" height=\"978\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/08\/brewsterbuffalorafsingapur1942.jpg 2965w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/08\/brewsterbuffalorafsingapur1942-300x99.jpg 300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/08\/brewsterbuffalorafsingapur1942-768x253.jpg 768w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/08\/brewsterbuffalorafsingapur1942-1024x338.jpg 1024w\" sizes=\"(max-width: 2965px) 100vw, 2965px\" \/><\/a><\/strong><\/h3>\n<p>&nbsp;<\/p>\n<h3><strong>Un Brewster Buffalo de la Fuerza A\u00e9rea Australiana en Singapur, a finales de 1941.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>El mariscal del aire Sir Robert Brooke-Popham, comandante en jefe brit\u00e1nico para Extremo Oriente, expres\u00f3 en diciembre de 1941 su ilimitada confianza en el potencial de los aviones Brewster Buffalo para dominar el medio ambiente colonial del sudeste asi\u00e1tico[i]: \u201cSon aviones que para Malasia no dejan nada que desear\u201d. El gobernador hab\u00eda respondido al general Percival unos d\u00edas antes antes, cuando \u00e9ste le informaba del desembarco del ej\u00e9rcito japon\u00e9s en Kota Bahru, \u201cBien, supongo que ustedes se encargar\u00e1n de echar de ah\u00ed a esos hombrecillos\u201d. El staff brit\u00e1nico de Informaci\u00f3n Militar cre\u00eda firmemente que los aviadores japoneses eran incapaces de volar sin visibilidad, y que los aviones japoneses \u201cno eran precisamente del \u00faltimo modelo\u201d.<\/p>\n<p>En realidad los japoneses disfrutaron durante un breve momento de una delantera tecnol\u00f3gica estirada al l\u00edmite, cuando se cruzaron los caminos del \u00faltimo y refinado producto de la factor\u00eda Mitsubishi y del primer y casi \u00fanico avi\u00f3n dise\u00f1ado y fabricado por la casa Brewster de Johnsonville, Pennsylvania. Era el mundo al rev\u00e9s: se supon\u00eda que los pueblos no-blancos eran extra\u00f1os a la tecnolog\u00eda. El choque Zeros-Buffalos fue muy desigual. Los aviones japoneses pod\u00edan casi volar en c\u00edrculos alrededor del pesado avi\u00f3n de fabricaci\u00f3n norteamericana. Los pilotos del imperio brit\u00e1nico y holand\u00e9s eran enviados a la destrucci\u00f3n desde el momento en que despegaban del suelo.<\/p>\n<p>Varios factores contribuyeron a la significativa derrota a\u00e9rea de Europa en Extremo Oriente: el Buffalo era el primer monoplano encargado y adquirido por la Marina de los Estados Unidos, lo que ayudaba a pasar por alto sus defectos (queda como inc\u00f3gnita como un fabricante sin ninguna experiencia obtuvo el contrato con un dise\u00f1o tan flojo), y los gobiernos brit\u00e1nico y holand\u00e9s de 1940 compraban cualquier avi\u00f3n que saliera al mercado.<\/p>\n<p>Adem\u00e1s, de la misma forma en que el poder a\u00e9reo alem\u00e1n tend\u00eda ser sobreestimado, el equivalente japon\u00e9s era infraestimado por un simple complejo mental racista. Que se trataba de unas espesas anteojeras quedaba patente porque, a la fecha, el servicio de informaci\u00f3n militar brit\u00e1nico pose\u00eda informes del rendimiento del Zero en China e incluso del an\u00e1lisis de un ejemplar derribado. Naturalmente, China era otro pa\u00eds no-blanco y la Uni\u00f3n Sovi\u00e9tica \u2013otro pa\u00eds contra cuyas fuerzas a\u00e9reas hab\u00eda peleado el ej\u00e9rcito japon\u00e9s\u2013 un pa\u00eds blanco s\u00f3lo en apariencia, como se\u00f1alaban claramente los ojillos asi\u00e1ticos que los dibujantes de la prensa de Londres no se olvidaban de pintar en las caricaturas de Lenin y Stalin.<\/p>\n<p>[i] Barber, La ca\u00edda de Singapur (1976)<\/p>\n<p>&nbsp;<br \/>\n[codepeople-post-map cat=\u00bb-1&#8243;]<br \/>\n&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Un Brewster Buffalo de la Fuerza A\u00e9rea Australiana en Singapur, a finales de 1941. &nbsp; El mariscal del aire Sir Robert Brooke-Popham, comandante en &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":8432,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":[]},"categories":[663,530,2160,270,93],"tags":[2087],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/08\/brewsterbuffalorafsingapur1942.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-2bV","jetpack-related-posts":[{"id":8703,"url":"https:\/\/aeropinakes.com\/wordpress\/1941\/09\/15\/los-curioso-exito-de-los-buffalos-finlandeses\/","url_meta":{"origin":8427,"position":0},"title":"El curioso \u00e9xito de los Buffalos finlandeses","date":"1941","format":false,"excerpt":"\u00a0 Un Brewster Buffalo de la fuerza a\u00e9rea finlandesa en los primeros a\u00f1os de la segunda guerra mundial. La Fuerza A\u00e9rea Finlandesa utiliz\u00f3 la esv\u00e1stica azul desde su creaci\u00f3n en 1918 durante la guerra civil hasta 1945. \u00a0 El avi\u00f3n que dej\u00f3 tan mal recuerdo en la aviaci\u00f3n colonial brit\u00e1nica\u2026","rel":"","context":"En \u00ab1941\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/09\/brewsterbuffaloaereofinlandia1940.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":10194,"url":"https:\/\/aeropinakes.com\/wordpress\/1969\/05\/21\/los-ultimos-aviones-al-este-de-suez\/","url_meta":{"origin":8427,"position":1},"title":"Los \u00faltimos aviones al este de Suez","date":"1969","format":false,"excerpt":"\u00a0 Avro (Hawker Siddeley) Andover de una unidad de transporte de la RAF basada en Singapur, 1969. \u00a0 A comienzos de la d\u00e9cada de 1960, la RAF plante\u00f3 la necesidad de un transporte t\u00e1ctico de tama\u00f1o medio pero con carga trasera directa, lo que permitir\u00eda usarlo para llevar cargas voluminosas\u2026","rel":"","context":"En \u00ab1969\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/05\/avrohs748andover1969.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7057,"url":"https:\/\/aeropinakes.com\/wordpress\/1941\/02\/06\/la-luftwaffe-en-irak-1941\/","url_meta":{"origin":8427,"position":2},"title":"La Luftwaffe en\u00a0Irak","date":"1941","format":false,"excerpt":"\u00a0 Heinkel He 111\u00a0de la FA iraqu\u00ed (FA alemana en Irak, 1941) \u00a0 En 1941 Irak era un pa\u00eds independiente, pero sometido de facto al poder imperial brit\u00e1nico. A comienzos de ese a\u00f1o un golpe de estado expuls\u00f3 del poder al gobierno angl\u00f3filo existente y lo sustituy\u00f3 por un gabinete\u2026","rel":"","context":"En \u00ab1941\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2014\/10\/heinkelhe111iraq1941.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":12553,"url":"https:\/\/aeropinakes.com\/wordpress\/1941\/01\/23\/cuando-filipinas-se-enfrento-a-japon-con-doce-aviones-anticuados\/","url_meta":{"origin":8427,"position":3},"title":"Cuando Filipinas se enfrent\u00f3 a Jap\u00f3n con doce aviones anticuados","date":"1941","format":false,"excerpt":"\u00a0 \u00a0 Un Boeing P-26 del Philippine Army Air Corps\u00a0 en el verano de 1941. \u00a0 Filipinas hab\u00eda sido colonia norteamericana desde 1898. A mediados de la d\u00e9cada de 1930 fue transformada en Commonwealth of Philippines, con instituciones propias de gobierno\u00a0 y se fij\u00f3 la fecha de la independencia del\u2026","rel":"","context":"En \u00ab1941\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/01\/boeingp26filipinas1940.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":12511,"url":"https:\/\/aeropinakes.com\/wordpress\/1955\/01\/19\/la-furgoneta-aerea-de-la-raf-en-la-emergencia-malaya\/","url_meta":{"origin":8427,"position":4},"title":"La furgoneta a\u00e9rea de la RAF en la Emergencia Malaya","date":"1955","format":false,"excerpt":"\u00a0 Un Scottish Aviation Pioneer de la RAF en Malasia, en la segunda mitad de la d\u00e9cada de 1950.\u00a0 \u00a0 Inspirada tal vez por las agrestes condiciones de las tierras altas de Escocia y sus islas, donde hab\u00eda cierta tradici\u00f3n de empleo de aviones para enlazar localidades mal servidas por\u2026","rel":"","context":"En \u00ab1955\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/01\/scottishaviationpioneerrafmalasia1958.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8062,"url":"https:\/\/aeropinakes.com\/wordpress\/1918\/07\/06\/masacre-en-nablus\/","url_meta":{"origin":8427,"position":5},"title":"Masacre en Nablus","date":"1918","format":false,"excerpt":"\u00a0 Bristol F.2B Fighter - Cuerpo a\u00e9reo australiano en Palestina, 1918 \u00a0 A principios de 1918 la unidad a\u00e9rea australiana que formaba la parte principal de la aviaci\u00f3n aliada en la regi\u00f3n recibi\u00f3 por fin Bristol Fighter y otros tipos de aviones avanzados, y los brit\u00e1nicos y los Dominios \u00a0disfrutaron\u2026","rel":"","context":"En \u00ab1918\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/07\/bristolf2bpalestina1918.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/8427"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=8427"}],"version-history":[{"count":0,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/8427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/8432"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=8427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=8427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=8427"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=8427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}