{"id":8086,"date":"2004-07-08T19:05:17","date_gmt":"2004-07-08T17:05:17","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?p=8086"},"modified":"2017-03-24T17:41:14","modified_gmt":"2017-03-24T16:41:14","slug":"la-aerolinea-de-nunavut","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/2004\/07\/08\/la-aerolinea-de-nunavut\/","title":{"rendered":"La aerol\u00ednea de Nunavut"},"content":{"rendered":"<h3><strong><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/07\/beechcraftkingairairnunavut.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8075 size-full\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/07\/beechcraftkingairairnunavut.jpg\" alt=\"beechcraftkingairairnunavut\" width=\"2486\" height=\"755\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/07\/beechcraftkingairairnunavut.jpg 2486w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/07\/beechcraftkingairairnunavut-300x91.jpg 300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/07\/beechcraftkingairairnunavut-768x233.jpg 768w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/07\/beechcraftkingairairnunavut-1024x311.jpg 1024w\" sizes=\"(max-width: 2486px) 100vw, 2486px\" \/><\/a><\/strong><\/h3>\n<p>&nbsp;<\/p>\n<h3><\/h3>\n<h3><strong>Un Beechcraft Super King Air de Air Nunavut a mediados de la d\u00e9cada de 2000<\/strong>.<\/h3>\n<p>&nbsp;<\/p>\n<p>Nunavut tiene una extensi\u00f3n equivalente a la de Alemania, Francia, Italia, Espa\u00f1a y Reino Unido juntas, con una poblaci\u00f3n 8.000 veces inferior. A cada familia le toca una extensi\u00f3n de territorio similar a la de la ciudad de Londres entera.<\/p>\n<p>Varias aerol\u00edneas prestan el servicio de transporte p\u00fablico en este vasto pa\u00eds, aunque s\u00f3lo una, radicada en la capital de Nunavut, Iqaluit, lleva el nombre del territorio.<\/p>\n<p>Medio siglo atr\u00e1s Iqaluit, cuando se llamaba todav\u00eda Frobisher Bay, fue una de las bases de la impresionante l\u00ednea DEW (Distant Early Warning) en el \u00c1rtico, una cadena de radares servida por millares de hombres que se enfrentaba a la amenaza comunista desde la tundra del norte de Canad\u00e1, esperando la llegada de las flotas de bombarderos sovi\u00e9ticos a trav\u00e9s del Polo Norte.<\/p>\n<p>&nbsp;<br \/>\n[codepeople-post-map cat=\u00bb-1&#8243;]<br \/>\n&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Un Beechcraft Super King Air de Air Nunavut a mediados de la d\u00e9cada de 2000. &nbsp; Nunavut tiene una extensi\u00f3n equivalente a la de &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":8075,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":[]},"categories":[854,544,2094,596],"tags":[2095],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/07\/beechcraftkingairairnunavut.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-26q","jetpack-related-posts":[{"id":8096,"url":"https:\/\/aeropinakes.com\/wordpress\/1956\/07\/08\/carguero-para-la-dew\/","url_meta":{"origin":8086,"position":0},"title":"Carguero para la DEW","date":"1956","format":false,"excerpt":"\u00a0 Un Douglas Globemaster II del servicio de transporte a\u00e9reo militar de los Estados Unidos, a mediados de la d\u00e9cada de 1950. \u00a0 Entre 1955 y 1957, cientos de aviones militares y civiles volaron a la profunda soledad del \u00c1rtico en la mayor operaci\u00f3n de transporte a\u00e9reo desde el puente\u2026","rel":"","context":"En \u00ab1956\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/07\/douglasc124globemaster1956.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":10015,"url":"https:\/\/aeropinakes.com\/wordpress\/1990\/04\/26\/la-fuerza-aerea-de-hong-kong\/","url_meta":{"origin":8086,"position":1},"title":"La fuerza a\u00e9rea de Hong Kong","date":"1990","format":false,"excerpt":"\u00a0 Un King Air de la RHKAAF (Royal Hong Kong Auxiliary Air Force) a comienzos de la d\u00e9cada de 1990. Los dos King Air de la RHKAAF sustituyeron a un Britten Norman Islander y se dedican sobre todo a vigilancia, b\u00fasqueda y rescate. \u00a0 La distancia m\u00e1s larga que se\u2026","rel":"","context":"En \u00ab1990\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/04\/beechcraftkingairRHKAAF1990.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7403,"url":"https:\/\/aeropinakes.com\/wordpress\/1933\/05\/30\/ambulancia-aerea-en-la-guerra-del-chaco\/","url_meta":{"origin":8086,"position":2},"title":"Ambulancia a\u00e9rea en la guerra del Chaco","date":"1933","format":false,"excerpt":"\u00a0 Uno de los dos Travel Air 6000 usados como ambulancias a\u00e9reas por las fuerzas paraguayas. Este lleva pintado en el fuselaje una referencia a las batallas de Nanawa, libradas en la primera mitad de 1933, en las que el ej\u00e9rcito paraguayo resisti\u00f3 un ataque masivo boliviano. \u00a0 Aunque hubo\u2026","rel":"","context":"En \u00ab1933\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/05\/travelair6000paraguay1933.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":10413,"url":"https:\/\/aeropinakes.com\/wordpress\/1990\/06\/17\/un-aviocar-para-venda\/","url_meta":{"origin":8086,"position":3},"title":"Un Aviocar para Venda","date":"1990","format":false,"excerpt":"\u00a0 Un CASA Aviocar de la Unidad A\u00e9rea de la Fuerza de Defensa de Venda (Venda Defence Force - Air Wing) hacia 1990. \u00a0 Venda, en el noreste de Sud\u00e1frica, fue uno de los cuatro bantustanes (oficialmente homelands u \"hogares nacionales\"\u00a0declarados independientes dentro del territorio sudafricano, aunque no reconocidos por\u2026","rel":"","context":"En \u00abAviocar\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/06\/aviocarvenda1990.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":971,"url":"https:\/\/aeropinakes.com\/wordpress\/1953\/05\/29\/the-queens-air-forces-middle-east-and-far-east\/","url_meta":{"origin":8086,"position":4},"title":"The Queen&#8217;s Air Forces &#8211; Middle East and Far East","date":"1953","format":false,"excerpt":"The Queen's Air Forces - Middle East and Far East by H.F. King, M.B.E. Flight, 29 de mayo de 1953 Un documento pdf profusamente ilustrado (19 p\u00e1gs.) \u00a0","rel":"","context":"En \u00ab1953\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1953\/05\/quee.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8400,"url":"https:\/\/aeropinakes.com\/wordpress\/1966\/08\/18\/los-buques-carboneros-del-sac\/","url_meta":{"origin":8086,"position":5},"title":"Los buques carboneros del SAC","date":"1966","format":false,"excerpt":"\u00a0 Boeing KC-135 del Mando A\u00e9reo Estrat\u00e9gico de la USAF, a mediados de la d\u00e9cada de 1960. \u00a0 La idea general del despliegue del SAC consist\u00eda en responder a cualquier ataque sovi\u00e9tico haciendo despegar varias docenas de escuadrones de B-52 cargados de bombas H, que se dirigir\u00edan raudos a territorio\u2026","rel":"","context":"En \u00ab1966\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1966\/08\/boeingKC135stratotanker1966.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/8086"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=8086"}],"version-history":[{"count":0,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/8086\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/8075"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=8086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=8086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=8086"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=8086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}