{"id":7799,"date":"1988-06-26T19:38:14","date_gmt":"1988-06-26T17:38:14","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?p=7799"},"modified":"2016-06-26T19:41:44","modified_gmt":"2016-06-26T17:41:44","slug":"el-modelo-el-al-de-aerolinea-civil-en-guerra","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1988\/06\/26\/el-modelo-el-al-de-aerolinea-civil-en-guerra\/","title":{"rendered":"El modelo El Al de aerol\u00ednea civil en estado de guerra permanente"},"content":{"rendered":"<h3><strong><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/boeing747elal1988.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7791 size-full\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/boeing747elal1988.jpg\" alt=\"boeing747elal1988\" width=\"2410\" height=\"619\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/boeing747elal1988.jpg 2410w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/boeing747elal1988-300x77.jpg 300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/boeing747elal1988-768x197.jpg 768w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/boeing747elal1988-1024x263.jpg 1024w\" sizes=\"(max-width: 2410px) 100vw, 2410px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><\/a>Un Boeing 747 de El Al, la aerol\u00ednea de bandera de Israel.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Otra de las muchas consecuencias del ataque terrorista del 11 de septiembre fue que el modelo El Al de aerol\u00ednea civil en guerra permanente se extendi\u00f3 paulatinamente por todo el mundo. El sistema de seguridad de la aerol\u00ednea nacional israel\u00ed, que le cuesta una enorme cantidad de dinero, cubierto en un 70% por el gobierno, es reputado como el m\u00e1s intensivo del mundo.<\/p>\n<p>Basado principalmente en la desconfianza extrema, cada pasajero es interrogado exhaustivamente. \u201cSi el primer oficial de seguridad no queda satisfecho con las respuestas, se llama a otro m\u00e1s experimentado. Si tampoco \u00e9ste queda satisfecho, el equipaje del pasajero ser\u00e1 registrado minuciosamente\u201d (Algunos turistas se quejan de la \u201cnaturaleza personal\u201d de las preguntas). La carga comercial es colocada previamente en una c\u00e1mara de descompresi\u00f3n, para activar cualquier mecanismo de detonaci\u00f3n sensible a la altura.<\/p>\n<p>En consecuencia, el moderno pasajero a\u00e9reo sabe que llega a una zona de guerra en cuanto entra en un aeropuerto. Ser\u00e1 registrado minuciosamente y tendr\u00e1 que dejar atr\u00e1s cualquier objeto capaz de convertirse en un arma, incluso una lima de u\u00f1as. Cualquier actitud sospechosa o comentario desafortunado ser\u00e1 investigado cuidadosamente y castigado implacablemente si es necesario. Los aviones mismos fortifican la cabina de los pilotos, y se est\u00e1 planeando en serio dotarlos de medidas contramisiles. No prosper\u00f3 la idea de dotar a los pilotos mismos con pistolas, aunque parece que se extiende la de incluir un agente armado camuflado entre el pasaje.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Un Boeing 747 de El Al, la aerol\u00ednea de bandera de Israel. &nbsp; Otra de las muchas consecuencias del ataque terrorista del 11 de &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":7791,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":[]},"categories":[838,926,232],"tags":[2029],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/boeing747elal1988.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-21N","jetpack-related-posts":[{"id":13064,"url":"https:\/\/aeropinakes.com\/wordpress\/1954\/05\/26\/cat-la-aerolinea-con-una-cara-oculta\/","url_meta":{"origin":7799,"position":0},"title":"CAT, la aerol\u00ednea con una cara oculta","date":"1954","format":false,"excerpt":"\u00a0 Un Curtiss C-46 Commando de Civil Air Transport a mediados de la d\u00e9cada de 1950. \u00a0 Civil Air Transport (CAT) naci\u00f3 en China durante la \u00faltima fase de la guerra civil y emigr\u00f3 a Taiw\u00e1n con el resto de las fuerzas derrotadas nacionalistas. Los veinte a\u00f1os siguientes funcion\u00f3 como\u2026","rel":"","context":"En \u00ab1954\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/05\/curtisscommandocatindochina1954.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14705,"url":"https:\/\/aeropinakes.com\/wordpress\/1979\/03\/10\/la-aerolinea-que-resurgio-tres-veces-y-cada-vez-en-un-pais-distinto\/","url_meta":{"origin":7799,"position":1},"title":"La aerol\u00ednea que resurgi\u00f3 tres veces, y cada vez en un pa\u00eds distinto","date":"1979","format":false,"excerpt":"\u00a0 \u00a0 Arriba, un DC-10 de JAT en 1979. Abajo, en 1996. Fundada como Aeroput en 1927 como aerol\u00ednea nacional del Reino de Yugoslavia, en 1941 debi\u00f3 interrumpir sus operaciones por la invasi\u00f3n alemana. En 1945 las reanud\u00f3, ya como Rep\u00fablica Federal Popular de Yugoslavia, en 1947 cambi\u00f3 su nombre\u2026","rel":"","context":"En \u00abDC-10\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/03\/douglasdc10jat1979.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14784,"url":"https:\/\/aeropinakes.com\/wordpress\/1973\/09\/17\/el-ultimo-reactor-sovietico-de-egyptair\/","url_meta":{"origin":7799,"position":2},"title":"El \u00faltimo reactor sovi\u00e9tico de Egyptair","date":"1973","format":false,"excerpt":"\u00a0 Un Tupolev Tu-154 de Egyptair en 1973. El avi\u00f3n fue encargado por Aeroflot para sustituir a sus airliners de medio radio y entr\u00f3 en servicio en 1972 en la gran aerol\u00ednea sovi\u00e9tica y, posteriormente, en muchos estados de la \u00f3rbita de la URSS, incluyendo Egipto. En el verano de\u2026","rel":"","context":"En \u00ab1973\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/11\/tupolevtu154egyptair1973.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":17854,"url":"https:\/\/aeropinakes.com\/wordpress\/1995\/07\/27\/la-aerolinea-hermetica\/","url_meta":{"origin":7799,"position":3},"title":"La aerol\u00ednea herm\u00e9tica","date":"1995","format":false,"excerpt":"Un Iliuschin Il-18 de Air Koryo a mediados de la d\u00e9cada de 1990. \u00a0 Air Koryo (Air Corea), acompa\u00f1a a la Rep\u00fablica Democr\u00e1tica Popular de Corea, (m\u00e1s conocida como Corea del Norte) desde pocos a\u00f1os despu\u00e9s de su fundaci\u00f3n en 1948. A mediados de la d\u00e9cada de 1950 el nuevo\u2026","rel":"","context":"En \u00ab1995\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2020\/07\/ilyuschinil18airkoryo1995.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":10205,"url":"https:\/\/aeropinakes.com\/wordpress\/1931\/05\/21\/la-conexion-africana-de-junkers\/","url_meta":{"origin":7799,"position":4},"title":"La conexi\u00f3n africana de Junkers","date":"1931","format":false,"excerpt":"\u00a0 Un Junkers A50 Junior de South West African Airways (SWAA), en 1931. Para ver lo que se ve\u00eda desde este avi\u00f3n volando sobre Namibia, click aqu\u00ed. \u00a0 A 8.300 km de distancia en vuelo directo\u00a0de Windhoek,\u00a0la ciudad alemana de Dessau, o mejor dicho la casa Junkers, gan\u00f3 la competici\u00f3n\u2026","rel":"","context":"En \u00ab1930\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/05\/junkersa50juniorSWAA1930.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3633,"url":"https:\/\/aeropinakes.com\/wordpress\/1940\/02\/17\/dc-2-republicanos-para-la-aerolinea-nacional\/","url_meta":{"origin":7799,"position":5},"title":"DC-2 republicanos para la aerol\u00ednea nacional","date":"1940","format":false,"excerpt":"\u00a0 Un DC-2 de Iberia a comienzos de la d\u00e9cada de 1940, pintado todav\u00eda con los colores corporativos de Lufthansa. \u00a0 Los cuatro DC-2 de LAPE, la aerol\u00ednea republicana, resultaron una herencia bienvenida para la flota de Iberia, que estaba compuesta por media docena de Junkers Ju-52, cuatro Dragon Rapide\u2026","rel":"","context":"En \u00ab1940\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/02\/douglasdc2iberia1940.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/7799"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=7799"}],"version-history":[{"count":0,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/7799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/7791"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=7799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=7799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=7799"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=7799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}