{"id":7790,"date":"1981-06-26T19:01:29","date_gmt":"1981-06-26T17:01:29","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?p=7790"},"modified":"2017-02-20T19:55:52","modified_gmt":"2017-02-20T18:55:52","slug":"un-carguero-para-las-guerras-de-libia","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1981\/06\/26\/un-carguero-para-las-guerras-de-libia\/","title":{"rendered":"Un carguero para las guerras de Libia"},"content":{"rendered":"<h3><strong><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/aleniag222libia1981.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7793 size-full\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/aleniag222libia1981.jpg\" alt=\"aleniag222libia1981\" width=\"2462\" height=\"1014\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/aleniag222libia1981.jpg 2462w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/aleniag222libia1981-300x124.jpg 300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/aleniag222libia1981-768x316.jpg 768w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/aleniag222libia1981-1024x422.jpg 1024w\" sizes=\"(max-width: 2462px) 100vw, 2462px\" \/><\/a><\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Un Alenia G222 de la Fuerza A\u00e9rea Libia a comienzos de la d\u00e9cada de 1980.<br \/>\n&nbsp;<\/p>\n<p>A comienzos de la d\u00e9cada de 1960, los planificadores de la OTAN se pusieron en lo peor y pidieron a la industria aeron\u00e1utica europea dise\u00f1os de cazas capaces de despegar en vertical, dando por supuesto que las pistas de las bases a\u00e1reas habr\u00edan sido inutilizadas por un primer ataque sovi\u00e9tico. Una petici\u00f3n paralela fue de un carguero tambi\u00e9n VTOL para atender las necesidades de estos nuevos aviones. No sali\u00f3 nada en claro de aquello, salvo varios propotipos fallidos que se pueden ver en los museos de aviaci\u00f3n, el precedente para el famoso Harrier brit\u00e1nico y el G222.<\/p>\n<p>El gobierno italiano asumi\u00f3 el proyecto de un carguero mediano ya no de despegue vertical, pero s\u00ed corto (STOL) para reemplazar a los C-119 Flying Boxcar de la Aeronautica Militare y el G222 que result\u00f3 finalmente fue un avi\u00f3n muy vers\u00e1til, que vol\u00f3 por primera vez en 1970, capaz de llevar 9 toneladas de carga a aeropuertos poco preparados. Esta caracter\u00edstica lo ha hecho un habitual de los aeropuertos del Tercer Mundo.<\/p>\n<p>En 1977 el Gobierno libio compr\u00f3 20 unidades de este avi\u00f3n. Result\u00f3 que Libia estaba en al lista de estados rufianes del Gobierno de los Estados Unidos, por lo que los aviones tuvieron que ser minuciosamente despojados de toda la tecnolog\u00eda made in USA que llevaban antes de hacer efectiva la venta. El cambio principal fue el de los motores, pues los General Electric originales fueron sustituidos por turbopropulsores Rolls Royce. Algo muy parecido ocurrir\u00eda 30 a\u00f1os despu\u00e9s, cuando el Gobierno espa\u00f1ol intent\u00f3 vender unos cuantos CN-235 a la Rep\u00fablica Bolivariana de Venezuela.<\/p>\n<p>El gobierno libio necesitaba estos aviones de carga para responder a su creciente implicaci\u00f3n en actuaciones militares internacionales, que llegaron hasta Tanzania en cierta ocasi\u00f3n. La m\u00e1s importante de todas fue la larga guerra civil del Chad, en la que Libia y el norte estaban a un lado y Francia y el sur al otro.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Un Alenia G222 de la Fuerza A\u00e9rea Libia a comienzos de la d\u00e9cada de 1980. &nbsp; A comienzos de la d\u00e9cada de 1960, los &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":7793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":[]},"categories":[831,1911,321],"tags":[1802],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/aleniag222libia1981.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-21E","jetpack-related-posts":[{"id":7294,"url":"https:\/\/aeropinakes.com\/wordpress\/1994\/05\/19\/rrita\/","url_meta":{"origin":7790,"position":0},"title":"El concepto RRITA","date":"1994","format":false,"excerpt":"\u00a0 Un C-27 Spartan en Panam\u00e1, a finales de la d\u00e9cada de 1990. La Zona del Canal de Panam\u00e1 dej\u00f3 de ser colonia estadounidense en 1999. \u00a0 A comienzos de la d\u00e9cada de 1960, los planificadores de la OTAN se pusieron en lo peor y pidieron a la industria aeron\u00e1utica\u2026","rel":"","context":"En \u00ab1994\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/05\/aleniag222c27spartanpanama1997.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8204,"url":"https:\/\/aeropinakes.com\/wordpress\/1974\/08\/10\/un-carguero-para-la-guerra-de-chipre\/","url_meta":{"origin":7790,"position":1},"title":"Un carguero para la guerra de Chipre","date":"1974","format":false,"excerpt":"\u00a0 Un Transall C-160 de la fuerza a\u00e9rea turca a mediados de la d\u00e9cada de 1970. \u00a0 Los Transall ayudaron a proyectar el poder de Turqu\u00eda hasta Chipre, en un conflicto que tuvo alguna similitud con la guerra de las Malvinas\/Falklands: la junta militar griega decidi\u00f3 dar un golpe de\u2026","rel":"","context":"En \u00ab1974\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/08\/transallturquia1974.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7042,"url":"https:\/\/aeropinakes.com\/wordpress\/1928\/02\/04\/el-fascismo-sobre-libia\/","url_meta":{"origin":7790,"position":2},"title":"El fascismo sobre Libia","date":"1928","format":false,"excerpt":"\u00a0 \u00a0 IMAM (Meridionali) Ro.1 (Fokker C.V) de la fuerza a\u00e9rea italiana sobre libia (1928). \u00a0 La guerra a\u00e9rea sobre la colonia italiana de Libia dur\u00f3 desde 1922 a 1932, y fue una parte muy importante de lo que se llam\u00f3 la riconquista della Libia. Aunque las operaciones comenzaron antes\u2026","rel":"","context":"En \u00ab1928\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/02\/fokkercvimamromeoro1libia1928.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2762,"url":"https:\/\/aeropinakes.com\/wordpress\/1953\/01\/08\/nord-noratlas\/","url_meta":{"origin":7790,"position":3},"title":"Nord Noratlas: avi\u00f3n multiconflictos","date":"1953","format":false,"excerpt":"\u00a0 Un Nord Noratlas de la Fuerza A\u00e9rea de Ruanda, en 1986 \u00a0 En la segunda mitad de la d\u00e9cada de 1940, el Ej\u00e9rcito del Aire franc\u00e9s ten\u00eda como \u00fanicos aviones de transporte grandes cantidades de Junkers Ju-52 (fabricados en Francia bajo licencia con el nombre Toucan) y algunos Dakota\u2026","rel":"","context":"En \u00ab1953\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1953\/01\/nordnordatlasfaruanda1986.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8799,"url":"https:\/\/aeropinakes.com\/wordpress\/1978\/10\/09\/la-fuerza-aerea-ugandesa-en-tiempos-de-idi-amin-de-israel-a-libia\/","url_meta":{"origin":7790,"position":4},"title":"La fuerza a\u00e9rea ugandesa en tiempos de Idi Amin: de Israel a Libia","date":"1978","format":false,"excerpt":"\u00a0 Un MiG-17 de la fuerza a\u00e9rea ugandesa a mediados de la d\u00e9cada de 1970. \u00a0 Los MiG-17 estaban en Uganda como estaban en otra veintena de pa\u00edses africanos: como una manifestaci\u00f3n de la nueva pol\u00edtica sovi\u00e9tica que sigui\u00f3 a la muerte de Stalin, de retornar a la visi\u00f3n de\u2026","rel":"","context":"En \u00ab1978\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/10\/mig17uganda1978.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6634,"url":"https:\/\/aeropinakes.com\/wordpress\/2011\/02\/01\/un-siglo-despues-guerra-aerea-sobre-libia\/","url_meta":{"origin":7790,"position":5},"title":"Un siglo despu\u00e9s, guerra a\u00e9rea sobre Libia","date":"2011","format":false,"excerpt":"\u00a0 Panavia Tornado de la fuerza a\u00e9rea brit\u00e1nica, Libia, 2011. \u00a0 La revuelta en Libia hab\u00eda comenzado a mediados de febrero de 2011 y pronto se hab\u00eda hecho fuerte en el este del pa\u00eds, en torno a la gran ciudad de Bengasi. En una primera arremetida, los rebeldes consiguieron dominar\u2026","rel":"","context":"En \u00ab2011\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/10\/panaviatornadoidsraf2011dg.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/7790"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=7790"}],"version-history":[{"count":0,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/7790\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/7793"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=7790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=7790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=7790"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=7790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}