{"id":7443,"date":"2006-06-01T19:26:47","date_gmt":"2006-06-01T17:26:47","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?p=7443"},"modified":"2017-03-25T12:13:08","modified_gmt":"2017-03-25T11:13:08","slug":"un-caza-de-cuarta-generacion-para-la-aviacion-militar-bolivariana","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/2006\/06\/01\/un-caza-de-cuarta-generacion-para-la-aviacion-militar-bolivariana\/","title":{"rendered":"Un caza de cuarta generaci\u00f3n para la Aviaci\u00f3n Militar Bolivariana"},"content":{"rendered":"<h3><strong><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/sujoisu30venezuela2006.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7428 size-full\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/sujoisu30venezuela2006.jpg\" alt=\"sujoisu30venezuela2006\" width=\"1717\" height=\"408\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/sujoisu30venezuela2006.jpg 1717w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/sujoisu30venezuela2006-300x71.jpg 300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/sujoisu30venezuela2006-768x182.jpg 768w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/sujoisu30venezuela2006-1024x243.jpg 1024w\" sizes=\"(max-width: 1717px) 100vw, 1717px\" \/><br \/>\n&nbsp;<br \/>\n<\/a>Un Sujoi Su-27 de la Aviaci\u00f3n Militar\u00a0Venezolana (Aviaci\u00f3n Militar Bolivariana desde 2007) pintado con una decoraci\u00f3n especial en la cola.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Apropiadamente, el Grupo de caza n\u00ba 13 Libertador Sim\u00f3n Bol\u00edvar es la unidad de la Fuerza A\u00e9rea Venezolana (Aviaci\u00f3n Militar Bolivariana) que alberga los Su-30. Los aviones, de los que se compraron 24, empezaron a llegar en 2006. El gobierno venezolano zanj\u00f3 as\u00ed a\u00f1os de forcejeos con los Estados Unidos sobre su flota de F-16, de los que tambi\u00e9n se compraron 24. Como se encarg\u00f3 de poner de relieve el Gobierno Bolivariano de Venezuela, con el Su-30 la fuerza a\u00e9rea dispone de un avi\u00f3n de guerra ultra-\u00e1gil capaz de volar a 2.500 km\/h, con un alcance de 3.000 km y llevando ocho toneladas de armamento. No hay nada igual en toda Latinoam\u00e9rica, e incluso puede que el F-15 norteamericano no est\u00e9 a la altura.<br \/>\n&nbsp;<br \/>\n[codepeople-post-map cat=\u00bb-1&#8243;]<br \/>\n&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Un Sujoi Su-27 de la Aviaci\u00f3n Militar\u00a0Venezolana (Aviaci\u00f3n Militar Bolivariana desde 2007) pintado con una decoraci\u00f3n especial en la cola. &nbsp; Apropiadamente, el Grupo &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":7428,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":[]},"categories":[856,1943,317],"tags":[1941],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/sujoisu30venezuela2006.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-1W3","jetpack-related-posts":[{"id":7427,"url":"https:\/\/aeropinakes.com\/wordpress\/1921\/06\/01\/un-avion-para-el-dictador\/","url_meta":{"origin":7443,"position":0},"title":"Un avi\u00f3n para el dictador","date":"1921","format":false,"excerpt":"\u00a0 Un Caudron G.3 de la aviaci\u00f3n militar venezolana en la d\u00e9cada de 1920. \u00a0 Juan Vicente G\u00f3mez ten\u00eda 63 a\u00f1os y era dictador de Venezuela desde hac\u00eda doce cuando se convirti\u00f3 en un fan\u00e1tico de la aviaci\u00f3n. La culpa la tuvo el piloto italiano Cosme Renella, que tambi\u00e9n tuvo\u2026","rel":"","context":"En \u00ab1921\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/caudrong3venezuela1921.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7438,"url":"https:\/\/aeropinakes.com\/wordpress\/1996\/06\/01\/un-avion-antiguerrilla-para-venezuela\/","url_meta":{"origin":7443,"position":1},"title":"Un avi\u00f3n antiguerrilla para Venezuela","date":"1996","format":false,"excerpt":"\u00a0 Un Rockwell Bronco de la fuerza a\u00e9rea venezolana a finales de la d\u00e9cada de 1990. \u00a0 El Bronco, uno de los pocos aviones especializado en la contra-insurgencia, lleg\u00f3 a Venezuela a mediados de la d\u00e9cada de 1970. No obstante, en comparaci\u00f3n con otros estados de Latinoam\u00e9rica, especialmente su vecino,\u2026","rel":"","context":"En \u00ab1996\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1996\/06\/rockwellbroncofav1996.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7440,"url":"https:\/\/aeropinakes.com\/wordpress\/1998\/06\/01\/el-avion-de-guerra-mas-moderno-de-latinoamerica\/","url_meta":{"origin":7443,"position":2},"title":"El avi\u00f3n de guerra m\u00e1s moderno de Latinoam\u00e9rica","date":"1998","format":false,"excerpt":"\u00a0 Un General Dynamics \/ Lockheed Martin F-16 Fighting Falcon de la Fuerza A\u00e9rea Venezolana a finales del siglo XX. \u00a0 Caus\u00f3 cierta sorpresa que el gobierno venezolano, en 1981, quisiera comprar F-16 para su aviaci\u00f3n militar (FAV). Ning\u00fan pa\u00eds latinoamericano los ten\u00eda, y Washington no deseaba ninguna fuerza a\u00e9rea\u2026","rel":"","context":"En \u00ab1998\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/lockheedmartinf16venezuela1998.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7500,"url":"https:\/\/aeropinakes.com\/wordpress\/2001\/06\/12\/safari-supporter-mushshak\/","url_meta":{"origin":7443,"position":3},"title":"Safari, Supporter, Mushshak","date":"2001","format":false,"excerpt":"\u00a0 Un PAC (Saab-MFI) Mushshak (competente, capaz en urdu) de la aviaci\u00f3n militar pakistan\u00ed, hacia el a\u00f1o 2000. \u00a0 Dise\u00f1ado hace medio siglo (1961) por MFI (Malm\u00f6 Flygindustri, luego absorbida por Saab) como avi\u00f3n ligero de uso general, el Saab-MFI 17 se ha ido escorando para uso militar, como entrenador,\u2026","rel":"","context":"En \u00ab2001\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/saabmushshakpaf2001.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":708,"url":"https:\/\/aeropinakes.com\/wordpress\/1925\/09\/25\/aviacion-militar-espanola-en-marruecos-nuevo\/","url_meta":{"origin":7443,"position":4},"title":"La aviaci\u00f3n militar en la campa\u00f1a de Marruecos","date":"1925","format":false,"excerpt":"Aviaci\u00f3n militar espa\u00f1ola en Marruecos Nuevo Mundo, 25 de septiembre de 1925","rel":"","context":"En \u00ab1925\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2012\/07\/tumblr_m75pgg1iye1rbnd77o1_1280.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8703,"url":"https:\/\/aeropinakes.com\/wordpress\/1941\/09\/15\/los-curioso-exito-de-los-buffalos-finlandeses\/","url_meta":{"origin":7443,"position":5},"title":"El curioso \u00e9xito de los Buffalos finlandeses","date":"1941","format":false,"excerpt":"\u00a0 Un Brewster Buffalo de la fuerza a\u00e9rea finlandesa en los primeros a\u00f1os de la segunda guerra mundial. La Fuerza A\u00e9rea Finlandesa utiliz\u00f3 la esv\u00e1stica azul desde su creaci\u00f3n en 1918 durante la guerra civil hasta 1945. \u00a0 El avi\u00f3n que dej\u00f3 tan mal recuerdo en la aviaci\u00f3n colonial brit\u00e1nica\u2026","rel":"","context":"En \u00ab1941\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/09\/brewsterbuffaloaereofinlandia1940.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/7443"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=7443"}],"version-history":[{"count":0,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/7443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/7428"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=7443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=7443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=7443"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=7443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}