{"id":7347,"date":"1990-05-26T19:55:15","date_gmt":"1990-05-26T17:55:15","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?p=7347"},"modified":"2017-03-22T17:25:12","modified_gmt":"2017-03-22T16:25:12","slug":"los-aviones-carniceros","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1990\/05\/26\/los-aviones-carniceros\/","title":{"rendered":"Los aviones carniceros"},"content":{"rendered":"<h3><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/05\/boeingb17frireyesbolivia1990.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7348 size-full\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/05\/boeingb17frireyesbolivia1990.jpg\" alt=\"boeingb17(frireyes)bolivia1990\" width=\"3034\" height=\"887\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/05\/boeingb17frireyesbolivia1990.jpg 3034w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/05\/boeingb17frireyesbolivia1990-300x88.jpg 300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/05\/boeingb17frireyesbolivia1990-768x225.jpg 768w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/05\/boeingb17frireyesbolivia1990-1024x299.jpg 1024w\" sizes=\"(max-width: 3034px) 100vw, 3034px\" \/><br \/>\n&nbsp;<\/p>\n<p><\/a><strong>Frigor\u00edfico Reyes fue la \u00fanica empresa de aviones carniceros que us\u00f3 bombarderos B-17 reconvertidos \u00a1y los mantuvo en vuelo hasta 1990!<\/strong><\/h3>\n<p>&nbsp;<br \/>\nFrigor\u00edfico Reyes fue una de la media docena de empresas de transporte a\u00e9reo que se dedicaron en Bolivia al transporte de carne fresca. Hay hasta 1.000 km de distancia entre La Paz, a m\u00e1s de 4.000 metros de altura, y las tierras bajas del Departamento del Beni, donde est\u00e1n las grandes fincas ganaderas, y elevadas cimas de la cordillera de los Andes est\u00e1n en medio. El transporte a\u00e9reo era por lo tanto una buena opci\u00f3n, pero sal\u00eda muy caro. Tras la segunda guerra mundial, parte de los enormes excedentes de aviones militares de transporte llegaron a Bolivia a muy buenos precios, y pudo comenzar en serio el transporte de carne desde las tierras bajas del noreste hasta La Paz y otras ciudades del altiplano. Las reses eran muertas a pie de avi\u00f3n, que aterrizaba en pistas improvisadas en las haciendas ganaderas. Se cargaban los cuartos de las reses en la cabina y se estibaban de la mejor manera posible, formando la extra\u00f1a y sangrienta imagen de un mont\u00f3n de carne como pasaje a\u00e9reo. Luego comenzaba el viaje de vuelta a La Paz, muchas veces dif\u00edcil por el mal tiempo en la cordillera. Los aviones ten\u00edan una instrumentaci\u00f3n muy rudimentaria y los pilotos deb\u00edan echarle mucho valor y mucha habilidad para llegar sanos y salvos a su destino en La Paz. Con el tiempo las buenas carreteras y los camiones frigor\u00edficos, as\u00ed como la competencia de los H\u00e9rcules de la fuerza a\u00e9rea boliviana, terminaron con el negocio a\u00e9reo del transporte de carne (1).<\/p>\n<p>(1) AviacionBoliviana.net<\/p>\n<p>&nbsp;<br \/>\n[codepeople-post-map cat=\u00bb-1&#8243;]<br \/>\n&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Frigor\u00edfico Reyes fue la \u00fanica empresa de aviones carniceros que us\u00f3 bombarderos B-17 reconvertidos \u00a1y los mantuvo en vuelo hasta 1990! &nbsp; Frigor\u00edfico Reyes &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":7348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":[]},"categories":[840,1922,370],"tags":[1923],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/05\/boeingb17frireyesbolivia1990.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-1Uv","jetpack-related-posts":[{"id":14433,"url":"https:\/\/aeropinakes.com\/wordpress\/1976\/09\/16\/arava-un-autobus-aereo-israeli-para-latinoamerica\/","url_meta":{"origin":7347,"position":0},"title":"Arava, un autob\u00fas a\u00e9reo israel\u00ed para Latinoam\u00e9rica","date":"1976","format":false,"excerpt":"\u00a0 Uno de los primeros IAI Arava en llegar, el TAM-75. Parece ser que vol\u00f3 por cuenta de la fuerza a\u00e9rea boliviana con el cl\u00e1sico esquema de camuflaje de la fuerza a\u00e9rea israel\u00ed de arena, marr\u00f3n apagado y verde desva\u00eddo. En junio de 1975 un comunicado de prensa de IAI\u2026","rel":"","context":"En \u00ab1976\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1976\/09\/iaiaravatambolivia1976.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2674,"url":"https:\/\/aeropinakes.com\/wordpress\/1932\/01\/06\/aviones-bolivianos-para-la-guerra-del-chaco\/","url_meta":{"origin":7347,"position":1},"title":"Aviones bolivianos para la guerra del Chaco","date":"1932","format":false,"excerpt":"\u00a0 Un Junkers W.34 del Lloyd A\u00e9reo Boliviano a comienzos de la d\u00e9cada de 1930. Los aviones del Lloyd fueron militarizados ya en 1928. Un soldado del altiplano del norte del pa\u00eds le pregunta a su sargento, en aymara: \u201cPues, jefe, \u00bfqui\u00e9nes son nuestros enemigos? \u00bfSer\u00e1n los cochabambinos?\u201d (1). Para\u2026","rel":"","context":"En \u00ab1932\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/01\/junkersw34lab1932.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":10229,"url":"https:\/\/aeropinakes.com\/wordpress\/1929\/05\/26\/transporte-aereo-pesado-para-la-guerra-contra-sandino\/","url_meta":{"origin":7347,"position":2},"title":"Transporte a\u00e9reo pesado para la guerra contra Sandino","date":"1929","format":false,"excerpt":"\u00a0 \u00a0 Un Ford\u00a0TriMotor del cuerpo de marines de los Estados Unidos, Nicaragua, 1929. \u00a0 Los marines estadounidenses en Nicaragua recibieron sus primeros aviones de transporte\u00a0en diciembre de 1927, seis meses\u00a0despu\u00e9s de la batalla de Ocotal, en la que sus de Havilland DH.4 hab\u00edan obligado a\u00a0la retirada de la fuerza\u2026","rel":"","context":"En \u00ab1929\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/05\/fordtrimotorUSMCnicaragua1929.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2684,"url":"https:\/\/aeropinakes.com\/wordpress\/1926\/01\/06\/una-red-pionera-de-transporte-aereo-en-el-altiplano\/","url_meta":{"origin":7347,"position":3},"title":"Una red pionera de transporte a\u00e9reo en el altiplano","date":"1926","format":false,"excerpt":"\u00a0 Junkers F.13 \"Illimani\" del Lloyd A\u00e9reo Boliviano, a finales de la d\u00e9cada de 1920. \u00a0 Un pa\u00eds de m\u00e1s de un mill\u00f3n de kil\u00f3metros cuadrados de extensi\u00f3n y con pocas carreteras y ferrocarriles deber\u00eda ser un lugar prometedor para la aviaci\u00f3n de transporte, y as\u00ed sucede actualmente en Bolivia.\u2026","rel":"","context":"En \u00ab1926\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/01\/junkersf13lab1926.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8096,"url":"https:\/\/aeropinakes.com\/wordpress\/1956\/07\/08\/carguero-para-la-dew\/","url_meta":{"origin":7347,"position":4},"title":"Carguero para la DEW","date":"1956","format":false,"excerpt":"\u00a0 Un Douglas Globemaster II del servicio de transporte a\u00e9reo militar de los Estados Unidos, a mediados de la d\u00e9cada de 1950. \u00a0 Entre 1955 y 1957, cientos de aviones militares y civiles volaron a la profunda soledad del \u00c1rtico en la mayor operaci\u00f3n de transporte a\u00e9reo desde el puente\u2026","rel":"","context":"En \u00ab1956\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/07\/douglasc124globemaster1956.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9791,"url":"https:\/\/aeropinakes.com\/wordpress\/1936\/03\/21\/aviones-mineros-en-nueva-guinea\/","url_meta":{"origin":7347,"position":5},"title":"Aviones mineros en Nueva Guinea","date":"1936","format":false,"excerpt":"\u00a0 Un Ford Trimotor de Guinea Airways en Nueva Guinea, a mediados de la d\u00e9cada de 1930. \u00a0 La miner\u00eda de oro comenz\u00f3 en Pap\u00faa Nueva Guinea (bajo administraci\u00f3n australiana hasta 1975) hacia 1926 en Wau y Bulolo, al este de la gran isla, y sus promotores se debieron enfrentar\u2026","rel":"","context":"En \u00ab1936\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/03\/fordtrimotorinuevaguinea1936.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/7347"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=7347"}],"version-history":[{"count":0,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/7347\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/7348"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=7347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=7347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=7347"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=7347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}