{"id":6793,"date":"1937-12-12T17:48:32","date_gmt":"1937-12-12T17:48:32","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?post_type=archive&#038;p=6793"},"modified":"2019-12-08T17:08:12","modified_gmt":"2019-12-08T16:08:12","slug":"avion-salazar","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1937\/12\/12\/avion-salazar\/","title":{"rendered":"Avi\u00f3n \u00abSalazar\u00bb"},"content":{"rendered":"<p class=\"p1\"><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/10\/1937-dec-rda2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-6755\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/10\/1937-dec-rda2.jpg\" alt=\"1937-dec-rda2\" width=\"1555\" height=\"599\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/10\/1937-dec-rda2.jpg 1555w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/10\/1937-dec-rda2-300x116.jpg 300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/10\/1937-dec-rda2-1024x394.jpg 1024w\" sizes=\"(max-width: 1555px) 100vw, 1555px\" \/><\/a>Revista do Ar &#8211; diciembre de 1937<\/p>\n<p class=\"p1\">Aero Club de Portugal<\/p>\n<p class=\"p1\"><a href=\"http:\/\/www.aecp.pt\/revista-do-ar\/\">Revista do Ar<\/a><\/p>\n<p class=\"p1\">\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Revista do Ar &#8211; diciembre de 1937 Aero Club de Portugal Revista do Ar<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":6755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":[]},"categories":[685,3275,605],"tags":[],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/10\/1937-dec-rda2.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-1Lz","jetpack-related-posts":[{"id":6795,"url":"https:\/\/aeropinakes.com\/wordpress\/1937\/12\/12\/lisboa-terreiro-do-paco-y-baixa\/","url_meta":{"origin":6793,"position":0},"title":"Lisboa, Terreiro do Pa\u00e7o y Baixa","date":"1937","format":false,"excerpt":"Revista do Ar - diciembre de 1937 Aero Club de Portugal Revista do Ar [codepeople-post-map cat=\"-1\"]","rel":"","context":"En \u00ab1937\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/10\/1937-dec-rda3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6805,"url":"https:\/\/aeropinakes.com\/wordpress\/1937\/10\/12\/la-se-de-lisboa\/","url_meta":{"origin":6793,"position":1},"title":"Aerofoto de la catedral de Lisboa","date":"1937","format":false,"excerpt":"Revista do Ar \u2013 octubre\u00a0de 1937 Aero Club de Portugal Revista do Ar","rel":"","context":"En \u00ab1937\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/10\/1937-oct-rda2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6798,"url":"https:\/\/aeropinakes.com\/wordpress\/1937\/11\/12\/sociedade-portuguesa-de-levantamentos-aereos-lda-s-p-l-a-l\/","url_meta":{"origin":6793,"position":2},"title":"Sociedade Portuguesa de Levantamentos A\u00e9reos, Lda. (S.P.L.A.L.)","date":"1937","format":false,"excerpt":"Revista do Ar \u2013 noviembre de 1937 Aero Club de Portugal Revista do Ar","rel":"","context":"En \u00ab1937\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/10\/1937-nov-rda.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6800,"url":"https:\/\/aeropinakes.com\/wordpress\/1937\/11\/12\/proteccion-aerea-proteccion-personal\/","url_meta":{"origin":6793,"position":3},"title":"Protecci\u00f3n A\u00e9rea&#8230; \u00a1Protecci\u00f3n personal!","date":"1937","format":false,"excerpt":"Revista do Ar \u2013 noviembre de 1937 L\u00e1mparas Philips contra ataques a\u00e9reos. (Un anuncio alem\u00e1n con el mismo tema, 1939) Aero Club de Portugal Revista do Ar","rel":"","context":"En \u00ab1937\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/10\/1937-nov-rda2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6803,"url":"https:\/\/aeropinakes.com\/wordpress\/1937\/10\/12\/junkers-flugzeug-und-motorenwerke-a-g-dessau\/","url_meta":{"origin":6793,"position":4},"title":"Junkers Flugzeug und Motorenwerke A.G., Dessau","date":"1937","format":false,"excerpt":"Aviones Junkers Revista do Ar \u2013 octubre de 1937 Aero Club de Portugal Revista do Ar","rel":"","context":"En \u00ab1937\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/10\/1937-oct-rda.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":171,"url":"https:\/\/aeropinakes.com\/wordpress\/1937\/05\/06\/flight-6-de-mayo-de-1937-flight-global-archive\/","url_meta":{"origin":6793,"position":5},"title":"Cuatro im\u00e1genes publicitarias del Breda Ba.65 Nibbio","date":"1937","format":false,"excerpt":"La casa Breda realiz\u00f3 un notable esfuerzo de propaganda de un producto en el que hab\u00eda puesto muchas esperanzas, el Ba.65, dise\u00f1ado como m\u00e1quina polivante para toda clase de tareas.\u00a0 \u00a0 Un Breda Ba.65 Nibbio (Milano) en un anuncio de de la firma de aviones BredaFlight, 6 de mayo de\u2026","rel":"","context":"En \u00ab1937\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2013\/05\/tumblr_mmsn1ivtok1rbnd77o1_1280.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/6793"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=6793"}],"version-history":[{"count":1,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/6793\/revisions"}],"predecessor-version":[{"id":16946,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/6793\/revisions\/16946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/6755"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=6793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=6793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=6793"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=6793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}