{"id":5670,"date":"1975-12-01T16:44:15","date_gmt":"1975-12-01T15:44:15","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?post_type=archive&#038;p=5670"},"modified":"2019-12-13T17:00:52","modified_gmt":"2019-12-13T16:00:52","slug":"lealtad","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1975\/12\/01\/lealtad\/","title":{"rendered":"El Ej\u00e9rcito del Aire acepta al rey Juan Carlos como sucesor del general Franco"},"content":{"rendered":"<p class=\"aligncenter\"><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/jc1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5668 size-full\" src=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/jc1.jpg\" alt=\"jc1\" width=\"753\" height=\"954\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/jc1.jpg 753w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/jc1-237x300.jpg 237w\" sizes=\"(max-width: 753px) 100vw, 753px\" \/><\/a><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/jc3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-5667\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/jc3.jpg\" alt=\"jc3\" width=\"754\" height=\"952\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/jc3.jpg 754w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/jc3-238x300.jpg 238w\" sizes=\"(max-width: 754px) 100vw, 754px\" \/><\/a><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/jc2.jpg\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5669 size-full\" src=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/jc2.jpg\" alt=\"jc2\" width=\"922\" height=\"930\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/jc2.jpg 922w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/jc2-150x150.jpg 150w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/jc2-297x300.jpg 297w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/jc2-100x100.jpg 100w\" sizes=\"(max-width: 922px) 100vw, 922px\" \/><\/a><\/p>\n<p>Declaraci\u00f3n del Ej\u00e9rcito del Aire publicada en su \u00f3rgano oficial en su primer n\u00famero despu\u00e9s de la muerte de Franco. Se da por sentada la continuidad de los Principios del Movimiento encarnados en el sucesor del dictador, el rey Juan Carlos, que figura de uniforme de jefe supremo del Aire.<\/p>\n<p>&nbsp;<\/p>\n<p>Revista de Aeron\u00e1utica y Astron\u00e1utica<br \/>\nPublicada por el Ministerio del Aire<br \/>\nA\u00f1o XXXV &#8211; N\u00ba 421<\/p>\n<p>Diciembre de 1975<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Declaraci\u00f3n del Ej\u00e9rcito del Aire publicada en su \u00f3rgano oficial en su primer n\u00famero despu\u00e9s de la muerte de Franco. Se da por sentada la &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":5668,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":[]},"categories":[825,559],"tags":[940],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/jc1.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s7HKWx-lealtad","jetpack-related-posts":[{"id":3780,"url":"https:\/\/aeropinakes.com\/wordpress\/1983\/02\/27\/aviojet-el-sucesor-del-saeta\/","url_meta":{"origin":5670,"position":0},"title":"Aviojet, el sucesor del Saeta","date":"1983","format":false,"excerpt":"\u00a0 \u00a0 Uno de los primeros Aviojet (A-36 Halc\u00f3n) de la Fuerza A\u00e9rea de Chile a finales de la d\u00e9cada de 1980. La FACh ha tomado considerable inter\u00e9s en el avi\u00f3n, desarrollando diversas versiones y actualizando sus sistemas electr\u00f3nicos. \u00a0 En 1975, el Ej\u00e9rcito del Aire public\u00f3 una especificaci\u00f3n t\u00e9cnica\u2026","rel":"","context":"En \u00ab1983\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1987\/02\/casaaviojetfach1987.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3722,"url":"https:\/\/aeropinakes.com\/wordpress\/1981\/01\/26\/3722\/","url_meta":{"origin":5670,"position":1},"title":"Llevando quintos a Canarias","date":"1981","format":false,"excerpt":"\u00a0 \u00a0 Un Lockheed C-130 H\u00e9rcules del Ej\u00e9rcito del Aire a mediados de la d\u00e9cada de 1980. \u00a0 En 1961, la USAF adjudic\u00f3 a CASA un contrato para la inspecci\u00f3n y reparaci\u00f3n de sus aviones C-130 Hercules. Era el avi\u00f3n m\u00e1s grande en el que hab\u00eda trabajado CASA en toda\u2026","rel":"","context":"En \u00ab1981\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1981\/01\/lockheedherculesedela1981.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4084,"url":"https:\/\/aeropinakes.com\/wordpress\/1974\/07\/01\/boeing-kc-97-stratotanker-en-el-ejercito-del-aire\/","url_meta":{"origin":5670,"position":2},"title":"Boeing KC-97 Stratotanker en el Ej\u00e9rcito del Aire","date":"1974","format":false,"excerpt":"\u00a0 Un Stratotanker del Ej\u00e9rcito del aire a mediados de la d\u00e9cada de 1970, con los reactores auxiliares eliminados. \u00a0 Las 36 unidades de Phantoms que llegaron a Espa\u00f1a en 1971\u00a0vinieron\u00a0acompa\u00f1adas de tres aviones cisterna Stratotanker (versi\u00f3n militar del Boeing Stratocruiser, a su vez la versi\u00f3n civil del B-29, el\u2026","rel":"","context":"En \u00ab1974\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/07\/boeingkc97stratotankeredela1974.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8557,"url":"https:\/\/aeropinakes.com\/wordpress\/1940\/09\/01\/la-pesadilla-aerea-del-general-yague\/","url_meta":{"origin":5670,"position":3},"title":"La pesadilla a\u00e9rea del general Yag\u00fce","date":"1940","format":false,"excerpt":"Henschel Hs 123, llamado \"Angelito\" en el Ej\u00e9rcito del Aire espa\u00f1ol, 1940. Una docena de ejemplares sirvieron en el E.A. hasta que el \u00faltimo fue dado de baja en 1953. \u00a0 En agosto de 1939, el general Juan Yag\u00fce fue nombrado el primero de los ministros del reci\u00e9n creado Ministerio\u2026","rel":"","context":"En \u00ab1940\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/09\/henschel123edela1940.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3773,"url":"https:\/\/aeropinakes.com\/wordpress\/1998\/02\/26\/el-museo-del-aire\/","url_meta":{"origin":5670,"position":4},"title":"El Museo del Aire","date":"1998","format":false,"excerpt":"\u00a0 El s\u00edmbolo a\u00e9reo del comunismo, tal como se puede ver el Museo del Aire Que se sepa, el MiG-17 nunca vol\u00f3 en Espa\u00f1a. Parece que el ejemplar representado arriba fue\u00a0un intercambio del museo de la Fuerza A\u00e9rea B\u00falgara con el Museo del Ej\u00e9rcito del Aire en Cuatro Vientos (Madrid)\u00a0(1).\u2026","rel":"","context":"En \u00ab1998\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1998\/02\/mig17comunista.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":123,"url":"https:\/\/aeropinakes.com\/wordpress\/1973\/07\/06\/linea-de-aviones-f-5-construidos-por-la-factoria\/","url_meta":{"origin":5670,"position":5},"title":"F-5 construidos en Sevilla","date":"1973","format":false,"excerpt":"\u00a0 L\u00ednea de aviones F-5 construidos por la factor\u00eda sevillana de la C.A.S.A. Espa\u00f1a, 80 a\u00f1os. Separata de \u201cFrancisco Franco, un siglo de Espa\u00f1a, de Ricardo de la Cierva - Editora Nacional (1973) - Franco y Sevilla","rel":"","context":"En \u00ab1969\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2013\/07\/tumblr_mpiube5jdl1rbnd77o1_12802.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/5670"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=5670"}],"version-history":[{"count":1,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/5670\/revisions"}],"predecessor-version":[{"id":16486,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/5670\/revisions\/16486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/5668"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=5670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=5670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=5670"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=5670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}