{"id":5315,"date":"1913-07-13T15:23:43","date_gmt":"1913-07-13T15:23:43","guid":{"rendered":"https:\/\/aeropinakes.wordpress.com\/2012\/08\/10\/aviadores-militares-en-el-sahara-alrededor-del"},"modified":"2019-12-08T19:03:41","modified_gmt":"2019-12-08T18:03:41","slug":"aviadores-militares-en-el-sahara-alrededor-del","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1913\/07\/13\/aviadores-militares-en-el-sahara-alrededor-del\/","title":{"rendered":"Aviadores militares en el Sahara"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1913\/07\/tumblr_m8jpfjgc3q1rbnd77o1_1280.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9216 size-full\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1913\/07\/tumblr_m8jpfjgc3q1rbnd77o1_1280.jpg\" alt=\"tumblr_m8jpfjgc3q1rbnd77o1_1280\" width=\"632\" height=\"421\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1913\/07\/tumblr_m8jpfjgc3q1rbnd77o1_1280.jpg 632w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1913\/07\/tumblr_m8jpfjgc3q1rbnd77o1_1280-300x200.jpg 300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1913\/07\/tumblr_m8jpfjgc3q1rbnd77o1_1280-272x182.jpg 272w\" sizes=\"(max-width: 632px) 100vw, 632px\" \/><\/a><\/p>\n<p>Aviadores militares en el Sahara<\/p>\n<p>Alrededor del mundo, 13 de julio de 1913<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Aviadores militares en el Sahara Alrededor del mundo, 13 de julio de 1913<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":9216,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":[]},"categories":[699,309,63,1],"tags":[3194],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1913\/07\/tumblr_m8jpfjgc3q1rbnd77o1_1280.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-1nJ","jetpack-related-posts":[{"id":772,"url":"https:\/\/aeropinakes.com\/wordpress\/1913\/12\/30\/el-alto-comisario-y-los-aviadores-militares-en\/","url_meta":{"origin":5315,"position":0},"title":"El Alto Comisario y los aviadores militares, en Tetu\u00e1n","date":"1913","format":false,"excerpt":"El Alto Comisario y los aviadores militares, en Tetu\u00e1n La Ilustraci\u00f3n Espa\u00f1ola y Americana, 30 de diciembre de 1913","rel":"","context":"En \u00ab1913\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2012\/07\/tumblr_m75nq6mrmg1rbnd77o1_1280.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":769,"url":"https:\/\/aeropinakes.com\/wordpress\/1913\/11\/27\/una-tragedia-en-los-aires-heroismo-de-los\/","url_meta":{"origin":5315,"position":1},"title":"Una tragedia en los aires: hero\u00edsmo de los aviadores militares espa\u00f1oles","date":"1913","format":false,"excerpt":"\u00a0 Una tragedia en los aires: hero\u00edsmo de los aviadores militares espa\u00f1oles Nuevo Mundo, 27 de noviembre de 1913","rel":"","context":"En \u00ab1913\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1913\/11\/1913-nov-27-nuevomundo-trag.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7088,"url":"https:\/\/aeropinakes.com\/wordpress\/1913\/11\/09\/la-misma-impresion-de-terror\/","url_meta":{"origin":5315,"position":2},"title":"\u201cLa misma impresi\u00f3n de terror\u201d","date":"1913","format":false,"excerpt":"\u00a0 Maurice Farman MF.7 de la aviaci\u00f3n del Ej\u00e9rcito en \u00c1frica (1913) \u00a0 En 1913, los aeronautas militares espa\u00f1oles dieron su propio paso al frente en la marcha hacia la locura en que estaba metido el pa\u00eds desde el verano de 1909. Tras casi dos a\u00f1os dedicados al entrenamiento en\u2026","rel":"","context":"En \u00ab1913\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/02\/mauricefarmanmf7ame1913.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8375,"url":"https:\/\/aeropinakes.com\/wordpress\/1924\/08\/17\/pilotos-y-observadores\/","url_meta":{"origin":5315,"position":3},"title":"Pilotos y observadores","date":"1924","format":false,"excerpt":"\u00a0 Un Avro 504 con el famoso perrito de Xaudar\u00f3 pintado en el fuselaje. Este avi\u00f3n dio la vuelta a Espa\u00f1a en 1924. \u00a0 El Avro 504 fue el principal avi\u00f3n de ense\u00f1anza de la aviaci\u00f3n mlitar espa\u00f1ola entre 1919 y 1936. Sustituy\u00f3 en esta tarea al Caudron G3, que\u2026","rel":"","context":"En \u00ab1924\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/08\/avro504xaudaro1924.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":15476,"url":"https:\/\/aeropinakes.com\/wordpress\/2013\/12\/17\/el-truco-del-generalisimo\/","url_meta":{"origin":5315,"position":4},"title":"El truco del General\u00edsimo","date":"2013","format":false,"excerpt":"En enero de 2013 la Audiencia de Barcelona admiti\u00f3 la demanda de la asociaci\u00f3n Altraitalia (Otra Italia) y dos particulares contra 22 aviadores de la Regia Aeronautica (Aviaci\u00f3n Real) que participaron en los bombardeos de Barcelona de marzo de 1938, que mataron a cientos de personas e hirieron a millares.\u2026","rel":"","context":"En \u00ab1938\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/04\/aviatoridifranco.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5286,"url":"https:\/\/aeropinakes.com\/wordpress\/1936\/08\/05\/la-actuacion-de-los-aviadores-mundo-grafico-5-de\/","url_meta":{"origin":5315,"position":5},"title":"La actuaci\u00f3n de los aviadores","date":"1936","format":false,"excerpt":"\u00a0 La actuaci\u00f3n de los aviadores Mundo Gr\u00e1fico, 5 de agosto de 1936 (www.bne.es)","rel":"","context":"En \u00ab1936\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1936\/08\/1936-08-05-mundografico.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/5315"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=5315"}],"version-history":[{"count":1,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/5315\/revisions"}],"predecessor-version":[{"id":16375,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/5315\/revisions\/16375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/9216"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=5315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=5315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=5315"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=5315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}