{"id":4870,"date":"1933-11-09T14:21:11","date_gmt":"1933-11-09T14:21:11","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?post_type=archive&#038;p=4870"},"modified":"2019-12-04T17:26:52","modified_gmt":"2019-12-04T16:26:52","slug":"el-crucero-negro","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1933\/11\/09\/el-crucero-negro\/","title":{"rendered":"El Crucero Negro"},"content":{"rendered":"<p><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/expressdumidi9nov1933.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-4871\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/expressdumidi9nov1933.jpg\" alt=\"expressdumidi9nov1933\" width=\"1010\" height=\"1592\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/expressdumidi9nov1933.jpg 1010w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/expressdumidi9nov1933-190x300.jpg 190w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/expressdumidi9nov1933-650x1024.jpg 650w\" sizes=\"(max-width: 1010px) 100vw, 1010px\" \/><\/a>El mapa de la ruta del Crucero Negro, tal como fue publicado por L&#8217;Exoress du Midi del 9 de noviembre de 1933<\/p>\n<p><a href=\"http:\/\/rosalis.bibliotheque.toulouse.fr\/\">Rosalis, Biblioth\u00e8que num\u00e9rique de Toulouse\u00a0<\/a><\/p>\n<p>[codepeople-post-map cat=\u00bb-1&#8243;]<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El mapa de la ruta del Crucero Negro, tal como fue publicado por L&#8217;Exoress du Midi del 9 de noviembre de 1933 Rosalis, Biblioth\u00e8que num\u00e9rique &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":4871,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":[]},"categories":[666,309,541,546,63,587,588,594,1001,610,614,338],"tags":[964],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/expressdumidi9nov1933.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-1gy","jetpack-related-posts":[{"id":3275,"url":"https:\/\/aeropinakes.com\/wordpress\/1933\/02\/01\/el-saludo-de-francia-a-sus-lejanos-hijos-africanos-crucero-negro-1933\/","url_meta":{"origin":4870,"position":0},"title":"El saludo de Francia a sus lejanos hijos africanos: Crucero negro, 1933","date":"1933","format":false,"excerpt":"\u00a0 El avi\u00f3n del general Vuillemin en el Crucero negro, identificable por el color rojo de la pajarita y el n\u00famero 1 pintado en la cola. N\u00f3tese que el puesto del ametrallador ha sido sustituido por otro asiento con parabrisas id\u00e9ntico al del piloto. \u00a0 Al amanecer del d\u00eda siguiente\u00a0en\u2026","rel":"","context":"En \u00ab1933\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/02\/potez25toecruceronegro.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6548,"url":"https:\/\/aeropinakes.com\/wordpress\/1933\/03\/26\/despues-del-crucero-africano-de-la-escuadra-vuillemin\/","url_meta":{"origin":4870,"position":1},"title":"Despu\u00e9s del Crucero Africano de la escuadra Vuillemin","date":"1933","format":false,"excerpt":"L'Aerophile, marzo de 1933 Gallica","rel":"","context":"En \u00ab1933\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/1934-mar-2laerophile.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11493,"url":"https:\/\/aeropinakes.com\/wordpress\/1933\/10\/04\/receptor-perfecto\/","url_meta":{"origin":4870,"position":2},"title":"Receptor perfecto","date":"1933","format":false,"excerpt":"Tras unos a\u00f1os de vacilaci\u00f3n en los que, parad\u00f3jicamente, se pensaba en el tel\u00e9fono para retransmisiones p\u00fablicas y en la radio para comunicaciones mar\u00edtimas y militares seguras y privadas, los receptores comenzaron a venderse como churros y a emitir a audiencias masivas los programas de radiodifusi\u00f3n, Blanco y Negro, 1933","rel":"","context":"En \u00ab1933\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/10\/1933radio6agobyn.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":659,"url":"https:\/\/aeropinakes.com\/wordpress\/1933\/08\/06\/el-mariscal-del-aire-de-italia-italo-balbo-en\/","url_meta":{"origin":4870,"position":3},"title":"El Mariscal del Aire de Italia, Italo Balbo, en Nueva York","date":"1933","format":false,"excerpt":"El Mariscal del Aire de Italia, Italo Balbo, en Nueva York Blanco y Negro, 6 de agosto de 1933 [codepeople-post-map cat=\"-1\"]","rel":"","context":"En \u00ab1933\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2012\/07\/tumblr_m75toeqwyi1rbnd77o1_12801.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8242,"url":"https:\/\/aeropinakes.com\/wordpress\/1933\/08\/12\/un-alarde-aereo-del-fascismo\/","url_meta":{"origin":4870,"position":4},"title":"Un alarde a\u00e9reo del fascismo","date":"1933","format":false,"excerpt":"\u00a0 Uno de los 25 Savoia Marchetti S.M.55 que participaron en el gran crucero de 1933. \u00a0 Italo Balbo comenz\u00f3 su carrera como jefe del Comisariado de Aeron\u00e1utica, a las \u00f3rdenes directas de Mussolini, que se hab\u00eda reservado el puesto de l\u00edder m\u00e1ximo de la aviaci\u00f3n italiana. Seg\u00fan Balbo, la\u2026","rel":"","context":"En \u00ab1933\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/08\/savoiamarchettism553d1933.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8192,"url":"https:\/\/aeropinakes.com\/wordpress\/2008\/08\/10\/el-avion-de-guerra-mas-grande-del-mundo\/","url_meta":{"origin":4870,"position":5},"title":"El avi\u00f3n de guerra m\u00e1s grande del mundo","date":"2008","format":false,"excerpt":"\u00a0 Tupolev Tu-160 Ilya Muromets de la aviaci\u00f3n estrat\u00e9gica rusa, hacia 2010. \u00a0 Un Tu-160 de la fuerza a\u00e9rea ucraniana, en 1998. En 1967 el North American Valkyrie norteamericano preocup\u00f3 al gobierno sovi\u00e9tico lo bastante como para lanzar su propio programa de superbombardero hipers\u00f3nico, algo reducido con respecto al original\u2026","rel":"","context":"En \u00ab1998\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2008\/08\/tupolevtu160ucrania1998.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/4870"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=4870"}],"version-history":[{"count":1,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/4870\/revisions"}],"predecessor-version":[{"id":16372,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/4870\/revisions\/16372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/4871"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=4870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=4870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=4870"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=4870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}