{"id":423,"date":"1912-07-08T15:13:00","date_gmt":"1912-07-08T15:13:00","guid":{"rendered":"https:\/\/aeropinakes.wordpress.com\/2012\/08\/10\/aerodromo-de-carabanchel-con-monoplanos-y"},"modified":"2019-12-08T19:02:53","modified_gmt":"2019-12-08T18:02:53","slug":"aerodromo-de-carabanchel-con-monoplanos-y","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1912\/07\/08\/aerodromo-de-carabanchel-con-monoplanos-y\/","title":{"rendered":"Aerodromo de Carabanchel"},"content":{"rendered":"<p><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2012\/08\/tumblr_m8joyzdhyb1rbnd77o1_1280.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-424 size-full\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2012\/08\/tumblr_m8joyzdhyb1rbnd77o1_1280.jpg\" alt=\"\" width=\"1280\" height=\"544\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2012\/08\/tumblr_m8joyzdhyb1rbnd77o1_1280.jpg 1280w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2012\/08\/tumblr_m8joyzdhyb1rbnd77o1_1280-300x128.jpg 300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2012\/08\/tumblr_m8joyzdhyb1rbnd77o1_1280-1024x435.jpg 1024w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/p>\n<p>Aerodromo de Carabanchel, con monoplanos y biplanos dispuestos para maniobrar<\/p>\n<p>La Ilustraci\u00f3n Espa\u00f1ola y Americana, 8 de julio de 1912<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Aerodromo de Carabanchel, con monoplanos y biplanos dispuestos para maniobrar La Ilustraci\u00f3n Espa\u00f1ola y Americana, 8 de julio de 1912<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":424,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":[]},"categories":[668,559,1],"tags":[878],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2012\/08\/tumblr_m8joyzdhyb1rbnd77o1_1280.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-6P","jetpack-related-posts":[{"id":4048,"url":"https:\/\/aeropinakes.com\/wordpress\/1911\/06\/20\/henri-farman-1911\/","url_meta":{"origin":423,"position":0},"title":"Henri Farman, el primer aparato de la aviaci\u00f3n militar espa\u00f1ola (1911)","date":"1911","format":false,"excerpt":"\u00a0 Un Henri Farman como los que llegaron al aer\u00f3dromo de Cuatro Vientos en 1911. Al principio, los aviones no llevaban ninguna clase de identificaci\u00f3n. \u00a0 El Henri Farman modelo 1911 era buen un producto de la tecnolog\u00eda aeron\u00e1utica de la \u00e9poca. Se pod\u00eda confiar en que despegar\u00eda del suelo,\u2026","rel":"","context":"En \u00ab1911\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/06\/henrifarman1911.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":781,"url":"https:\/\/aeropinakes.com\/wordpress\/1911\/04\/15\/practicas-de-la-aviacion-militar-en-carabanchel\/","url_meta":{"origin":423,"position":1},"title":"Pr\u00e1cticas de la aviaci\u00f3n militar en Carabanchel","date":"1911","format":false,"excerpt":"Pr\u00e1cticas de la aviaci\u00f3n militar en Carabanchel La Ilustraci\u00f3n Espa\u00f1ola y Americana, 15 de abril de 1911","rel":"","context":"En \u00ab1911\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2012\/07\/tumblr_m75nam4e4c1rbnd77o1_1280.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6246,"url":"https:\/\/aeropinakes.com\/wordpress\/1921\/12\/03\/visita-del-general-marzo-al-aerodromo-de-tetuan\/","url_meta":{"origin":423,"position":2},"title":"Visita del general Marzo al Aer\u00f3dromo de Tetu\u00e1n","date":"1921","format":false,"excerpt":"La Esfera. Ilustraci\u00f3n Mundial. -3 de diciembre de 1921 Biblioteca virtual de prensa hist\u00f3rica - Ministerio de Cultura","rel":"","context":"En \u00ab1921\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/1921-dic-3-la-esfera-ilustracion-mundial.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":778,"url":"https:\/\/aeropinakes.com\/wordpress\/1912\/01\/08\/principales-aparatos-voladores-de-la-exposicion-de\/","url_meta":{"origin":423,"position":3},"title":"Principales aparatos voladores de la exposici\u00f3n de aeron\u00e1utica de Par\u00eds","date":"1912","format":false,"excerpt":"Principales aparatos voladores de la exposici\u00f3n de aeron\u00e1utica de Par\u00eds La Ilustraci\u00f3n Espa\u00f1ola y Americana, 8 de enero de 1912","rel":"","context":"En \u00ab1912\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2012\/07\/tumblr_m75ngoj0e31rbnd77o1_1280.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":132,"url":"https:\/\/aeropinakes.com\/wordpress\/1936\/12\/01\/ilustracao-lisboa-1-de-diciembre-de-1936\/","url_meta":{"origin":423,"position":4},"title":"El aer\u00f3dromo de Getafe","date":"1936","format":false,"excerpt":"Ilustra\u00e7ao (Lisboa) 1 de diciembre de 1936 Hemeroteca Digital de Lisboa","rel":"","context":"En \u00ab1936\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2013\/06\/tumblr_mo8q91odbv1rbnd77o1_1280.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8638,"url":"https:\/\/aeropinakes.com\/wordpress\/1930\/09\/09\/se-ha-presentado-en-madrid-franco-con-su-aeroplano-a-defender-el-pais\/","url_meta":{"origin":423,"position":5},"title":"\u00abSe ha presentado en Madrid \/ Franco con su aeroplano \/ a defender el pa\u00eds\u00bb","date":"1930","format":false,"excerpt":"Un Breguet 19 de la Aviaci\u00f3n Militar, Aer\u00f3dromo de Cuatro Vientos. 15 de diciembre de 1930. \u00a0 Ya hab\u00edan fusilado a Ferm\u00edn Gal\u00e1n y a Garc\u00eda Hern\u00e1ndez, los m\u00e1rtires de la Rep\u00fablica, cuando Ram\u00f3n Franco (uno de los hombres m\u00e1s famosos de Espa\u00f1a por entonces), con un selecto grupo de\u2026","rel":"","context":"En \u00ab1930\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/09\/breguet19ame1930.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/423"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=423"}],"version-history":[{"count":1,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/423\/revisions"}],"predecessor-version":[{"id":17338,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/423\/revisions\/17338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/424"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=423"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}