{"id":4048,"date":"1911-06-20T17:29:25","date_gmt":"1911-06-20T17:29:25","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?p=4048"},"modified":"2016-02-09T19:30:30","modified_gmt":"2016-02-09T18:30:30","slug":"henri-farman-1911","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1911\/06\/20\/henri-farman-1911\/","title":{"rendered":"Henri Farman, el primer aparato de la aviaci\u00f3n militar espa\u00f1ola (1911)"},"content":{"rendered":"<h3><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/06\/henrifarman1911.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-4049\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/06\/henrifarman1911.jpg\" alt=\"henrifarman1911\" width=\"1500\" height=\"471\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/06\/henrifarman1911.jpg 3193w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/06\/henrifarman1911-300x94.jpg 300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/06\/henrifarman1911-1024x321.jpg 1024w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/a><\/h3>\n<h3><\/h3>\n<p>&nbsp;<\/p>\n<h3><strong>Un Henri Farman como los que llegaron al aer\u00f3dromo de Cuatro Vientos en 1911. Al principio, los aviones no llevaban ninguna clase de identificaci\u00f3n.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p align=\"JUSTIFY\">El Henri Farman modelo 1911 era buen un producto de la tecnolog\u00eda aeron\u00e1utica de la \u00e9poca. Se pod\u00eda confiar en que despegar\u00eda del suelo, gracias a sus generosas superficies de sustentaci\u00f3n. Otra cosa era maniobrarlo all\u00e1 arriba, pues su enorme envergadura y poco peso le daba caracter\u00edsticas aerodin\u00e1micas m\u00e1s parecidas a una gigantesca cometa que a un avi\u00f3n que surca los aires. Fue uno de los primeros aparatos que compr\u00f3 la reci\u00e9n creada aviaci\u00f3n militar espa\u00f1ola, en origen una secci\u00f3n de la unidad de globos y dirigibles (aerostaci\u00f3n), a su vez encuadrada en la ilustrada arma de Ingenieros, que formaba el Ej\u00e9rcito junto con Infanter\u00eda, Artiller\u00eda y Caballer\u00eda. Se instalaron los aviones, hangares e instructores, todo ello material franc\u00e9s, en el aer\u00f3dromo de Cuatro Vientos, y comenzaron las pr\u00e1cticas\u00a0(1).<\/p>\n<p align=\"JUSTIFY\">Seg\u00fan <a href=\"http:\/\/aeropinakes.com\/wordpress\/archive\/practicas-de-la-aviacion-militar-en-carabanchel\/\">un reportaje publicado por La Ilustraci\u00f3n Espa\u00f1ola y Americana el 15 de abril de 1911<\/a>, hab\u00eda solo dos Henri Farman en el campo de aviaci\u00f3n, alrededor de los cuales merodeaban soldados, oficiales militares, varios civiles (seguramente los instructores pilotos) y algunas se\u00f1oras, todos con expresi\u00f3n circunspecta. Un a\u00f1o despu\u00e9s las cosas hab\u00edan mejorado bastante, y <a href=\"http:\/\/aeropinakes.com\/wordpress\/archive\/aerodromo-de-carabanchel-con-monoplanos-y\/\">se pudo presentar al p\u00fablico<\/a>\u00a0(2)\u00a0una hilera de monoplanos (probablemente Bristol Prier) enfrentada a otra de biplanos Farman, diez aviones en total.<\/p>\n<div id=\"sdendnote1\">\n&nbsp;<\/p>\n<p>\u00a0(1)\u00a0Pr\u00e1cticas de la aviaci\u00f3n militar en Carabanchel. La Ilustraci\u00f3n Espa\u00f1ola y Americana, 15 de abril de 1911<\/p>\n<\/div>\n<div id=\"sdendnote2\">\n<p>(2)\u00a0Aerodromo de Carabanchel, con monoplanos y biplanos dispuestos para maniobrar La Ilustraci\u00f3n Espa\u00f1ola y Americana, 8 de julio de 1912<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Un Henri Farman como los que llegaron al aer\u00f3dromo de Cuatro Vientos en 1911. Al principio, los aviones no llevaban ninguna clase de identificaci\u00f3n. &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":4049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":[]},"categories":[698,559,1115],"tags":[878],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/06\/henrifarman1911.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-13i","jetpack-related-posts":[{"id":781,"url":"https:\/\/aeropinakes.com\/wordpress\/1911\/04\/15\/practicas-de-la-aviacion-militar-en-carabanchel\/","url_meta":{"origin":4048,"position":0},"title":"Pr\u00e1cticas de la aviaci\u00f3n militar en Carabanchel","date":"1911","format":false,"excerpt":"Pr\u00e1cticas de la aviaci\u00f3n militar en Carabanchel La Ilustraci\u00f3n Espa\u00f1ola y Americana, 15 de abril de 1911","rel":"","context":"En \u00ab1911\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2012\/07\/tumblr_m75nam4e4c1rbnd77o1_1280.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4481,"url":"https:\/\/aeropinakes.com\/wordpress\/1913\/08\/29\/maurice-farman-mf-7-aviacion-del-ejercito-frances\/","url_meta":{"origin":4048,"position":1},"title":"Maurice Farman MF.7 &#8211; Aviaci\u00f3n del ej\u00e9rcito franc\u00e9s","date":"1913","format":false,"excerpt":"\u00a0 Maurice Farman MF.7 - Aviaci\u00f3n del ej\u00e9rcito franc\u00e9s, 1913 \u00a0 La Liga Nacional A\u00e9rea francesa (Ligue Nationale A\u00e9rienne) que hab\u00eda sido creada pocos a\u00f1os antes sobre el modelo de la enorme Liga Naval alemana, empez\u00f3 a importunar al Ministerio de Colonias en 1910 sobre gran utilidad de los aviones\u2026","rel":"","context":"En \u00abArgelia\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/08\/mauricefarmanmf7argelia1913.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7088,"url":"https:\/\/aeropinakes.com\/wordpress\/1913\/11\/09\/la-misma-impresion-de-terror\/","url_meta":{"origin":4048,"position":2},"title":"\u201cLa misma impresi\u00f3n de terror\u201d","date":"1913","format":false,"excerpt":"\u00a0 Maurice Farman MF.7 de la aviaci\u00f3n del Ej\u00e9rcito en \u00c1frica (1913) \u00a0 En 1913, los aeronautas militares espa\u00f1oles dieron su propio paso al frente en la marcha hacia la locura en que estaba metido el pa\u00eds desde el verano de 1909. Tras casi dos a\u00f1os dedicados al entrenamiento en\u2026","rel":"","context":"En \u00ab1913\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/02\/mauricefarmanmf7ame1913.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6821,"url":"https:\/\/aeropinakes.com\/wordpress\/1938\/02\/12\/las-grandes-maniobras-de-ultramar-de-la-aviacion-militar-francesa\/","url_meta":{"origin":4048,"position":3},"title":"Las grandes maniobras de ultramar de la aviaci\u00f3n militar francesa","date":"1938","format":false,"excerpt":"Revista do Ar \u2013 febrero\u00a0de 1938 Aero Club de Portugal Revista do Ar","rel":"","context":"En \u00ab1938\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/10\/1938-feb-rda3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5350,"url":"https:\/\/aeropinakes.com\/wordpress\/1913\/11\/13\/1-un-grupo-de-moros-tirotea-el-avion-del-infante\/","url_meta":{"origin":4048,"position":4},"title":"Espa\u00f1a en sus h\u00e9roes","date":"1913","format":false,"excerpt":"\u00a0 (1) Un grupo de moros tirotea el avi\u00f3n del infante don Alfonso \u00a0 (2) El avi\u00f3n \u201cFarman\u201d realiza un bombardeo contra un grupo de moros durante una de las operaciones \u00a0 (3) El capit\u00e1n Barreiro y el teniente R\u00edos, transportados en brazos al puesto de socorro, momentos despu\u00e9s de\u2026","rel":"","context":"En \u00ab1913\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1913\/11\/marruecos1913.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":18024,"url":"https:\/\/aeropinakes.com\/wordpress\/1924\/12\/08\/un-bombardero-gigante-sin-ninguna-utilidad-militar-y-no-mucha-civil\/","url_meta":{"origin":4048,"position":5},"title":"Un bombardero gigante sin ninguna utilidad militar (y no mucha civil)","date":"1924","format":false,"excerpt":"El Farman F.140 Super Goliath (primer vuelo: abril de 1924) La aviaci\u00f3n militar francesa no necesitaba para nada un bombardero gigante en 1924. Ese a\u00f1o el \u00fanico enemigo concebible era Gran Breta\u00f1a, y los estados mayores de ambos pa\u00edses dise\u00f1aron los adecuados planes de contingencia en caso de conflicto. Alemania\u2026","rel":"","context":"En \u00ab1924\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2020\/12\/farmanf140supergoliath-1924.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/4048"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=4048"}],"version-history":[{"count":0,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/4048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/4049"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=4048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=4048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=4048"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=4048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}