{"id":3900,"date":"1975-02-28T20:13:18","date_gmt":"1975-02-28T19:13:18","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?p=3900"},"modified":"2017-06-05T20:15:01","modified_gmt":"2017-06-05T18:15:01","slug":"la-fuerza-aerea-argentina-contra-el-erp","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1975\/02\/28\/la-fuerza-aerea-argentina-contra-el-erp\/","title":{"rendered":"La Fuerza A\u00e9rea Argentina contra el ERP"},"content":{"rendered":"<h4><span style=\"color: #ffffff;\">&#8211;<a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1975\/02\/douglasskyhawkfaargentina1975.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-4064\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1975\/02\/douglasskyhawkfaargentina1975.jpg\" alt=\"douglasskyhawkfaargentina1975\" width=\"1500\" height=\"456\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1975\/02\/douglasskyhawkfaargentina1975.jpg 1847w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1975\/02\/douglasskyhawkfaargentina1975-300x91.jpg 300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1975\/02\/douglasskyhawkfaargentina1975-1024x312.jpg 1024w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/a><\/span><\/h4>\n<p>&nbsp;<\/p>\n<h3><strong>Un Douglas Skyhawk de la Fuerza A\u00e9rea Argentina a mediados de la d\u00e9cada de 1970.<\/strong><\/h3>\n<p>&nbsp;<br \/>\nEl 9 de noviembre de 1975, cuatro cazabombarderos Douglas A-4 Skyhawk despegaron de la base a\u00e9rea Coronel Pringles, llamada as\u00ed en honor del h\u00e9roe de Chancay, en Villa Reynolds (San Luis) y enfilaron hacia el norte. 700 km m\u00e1s tarde, al sur de la ciudad de San Miguel de Tucum\u00e1n, volaron sobre un campamento del ERP (Ej\u00e9rcito Revolucionario Popular), marcaron el blanco y dejaron caer sus bombas de fragmentaci\u00f3n y de napalm y dispararon su ca\u00f1ones sobre los guerrilleros (<a href=\"http:\/\/www.aeromilitaria.com.ar\/cmp\/subversion\/\">subversivos<\/a>, en la terminolog\u00eda oficial argentina de la \u00e9poca), hasta que por fin tomaron rumbo sur para regresar a su base.<\/p>\n<p>Las unidades del ERP fueron sometidas a este tratamiento una y otra vez hasta que, pocas semanas m\u00e1s tarde, los \u00faltimos guerrilleros de la zona huyeron, o fueron muertos, en combate o en ejecuciones sumarias tras ser capturados. A comienzos de 1976 se hab\u00edan dado por terminadas las operaciones antisubversivas en Tucum\u00e1n. Usar los cazabombarderos Skyhawk \u2013capaces de cargar cuatro toneladas y media de bombas cada uno\u2013 en la operaci\u00f3n demostr\u00f3 que los militares estaban dispuestos a llegar muy lejos en la lucha antisubversiva.<\/p>\n<p>Los Skyhawk eran el extremo de una cadena de actuaciones anti-subversivas que inclu\u00eda el empleo de otras aeronaves, como los Pucar\u00e1 (de manera experimental solamente), avionetas de reconocimiento Beech Mentor, aviones de transporte militar (uno de los cuales fue derribado por los guerrilleros) y helic\u00f3pteros Huey. En tierra fuerzas del Ej\u00e9rcito y otros cuerpos armados, hasta un total de unos 4.000 hombres, cercaban a o eran emboscadas por las unidades del ERP, que sumaban unos 400 efectivos. La idea del ERP, por alucinante que nos parezca hoy en d\u00eda, era crear un foco revolucionario en la relativamente aislada y agreste provincia de Tucum\u00e1n, a m\u00e1s de 1.000 km de Buenos Aires (el ERP tambi\u00e9n ten\u00eda unidades de guerrilla urbana en el \u00e1rea de la capital). A la inmensa escal del continente sudamericano, Tucum\u00e1n no estaba muy lejos de \u00d1ancahuaz\u00fa, en Bolivia, donde el Ch\u00e9 Guevara hab\u00eda muerto ocho a\u00f1os antes intentando crear precisamente un foco revolucionario de escala continental.<\/p>\n<p>Los Skyhawk era un tipo de arma contra la que el ERP no pod\u00eda hacer nada. En realidad, los generales argentinos eran reacios a arriesgar la vida de sus hombres en las quebradas dominadas por la guerrilla, y el poder a\u00e9reo fue un factor importante en la derrota del ERP. Adem\u00e1s, los generales hab\u00edan aprendido mucho de la experiencia norteamericana en Vietnam, seg\u00fan la cual el factor militar era menos importante que el cultural. Pero si los USA pretend\u00edan \u201cganarse los corazones y las mentes\u201d de sus enemigos, los militares argentinos prefirieron aterrar hasta el extremo a los suyos, siguiendo el modelo franc\u00e9s en Argelia. Miles de personas en San Miguel de Tucum\u00e1n y otras localidades cercanas, relacionadas o no con la guerrilla, fueron detenidas y torturadas en varios centros establecidos con este fin. Centenares murieron en aquel ensayo general del Proceso de Reorganizaci\u00f3n nacional, que finalmente tom\u00f3 el poder oficialmente en marzo de 1976. La fuerza a\u00e9rea argentina particip\u00f3 en todo aquello con cierta reticencia, pues no en vano implicaba bombardear sin gran riesgo su propio pa\u00eds. Los Skyhawk tendr\u00edan por fin la oportunidad de enfrentarse a un adversario de su talla en la guerra de las Malvinas, en 1982.<\/p>\n<p>[codepeople-post-map cat=\u00bb-1&#8243;]<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&#8211; &nbsp; Un Douglas Skyhawk de la Fuerza A\u00e9rea Argentina a mediados de la d\u00e9cada de 1970. &nbsp; El 9 de noviembre de 1975, cuatro &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":4064,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":[]},"categories":[825,529,1090],"tags":[975],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1975\/02\/douglasskyhawkfaargentina1975.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-10U","jetpack-related-posts":[{"id":3934,"url":"https:\/\/aeropinakes.com\/wordpress\/1976\/03\/01\/el-avion-argentino-de-contrainsurgencia\/","url_meta":{"origin":3900,"position":0},"title":"El avi\u00f3n argentino de contrainsurgencia","date":"1976","format":false,"excerpt":"- \u00a0 Un\u00a0FMA Pucar\u00e1 de la Fuerza A\u00e9rea Argentina a finales de la d\u00e9cada de\u00a01970 \u00a0 A comienzos de la d\u00e9cada de 1960, las Fuerzas Armadas Argentinas comenzaron a prepararse en serio para dominar su propio pa\u00eds y en 1968 encargaron a la FMA (F\u00e1brica Militar de Aviones) de C\u00f3rdoba\u2026","rel":"","context":"En \u00ab1976\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/fmapucarafaargentina1976.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14959,"url":"https:\/\/aeropinakes.com\/wordpress\/1987\/01\/06\/aviones-para-la-gendarmeria-nacional-argentina\/","url_meta":{"origin":3900,"position":1},"title":"Aviones para la Gendarmer\u00eda Nacional Argentina","date":"1987","format":false,"excerpt":"Un Piper Super Cub de la Gendarmer\u00eda Nacional Argentina en 1987. La Secci\u00f3n A\u00e9rea de la Gendarmer\u00eda Nacional Argentina se cre\u00f3 en 1955, 17 a\u00f1os despu\u00e9s de su fundaci\u00f3n en 1938. Argentina tiene cerca de tres millones de kil\u00f3metros cuadrados de territorio y 12.000 km de fronteras, por lo que\u2026","rel":"","context":"En \u00ab1987\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/01\/pipersupercubgendarmeriaargentina1987.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14831,"url":"https:\/\/aeropinakes.com\/wordpress\/1982\/07\/21\/un-avion-antisubversivo-para-uruguay\/","url_meta":{"origin":3900,"position":2},"title":"Un avi\u00f3n antisubversivo para Uruguay","date":"1982","format":false,"excerpt":"\u00a0 Un FMA Pucar\u00e1 de la Fuerza A\u00e9rea Uruguaya a comienzos de la d\u00e9cada de 1980. Los FMA Pucar\u00e1 llegaron en a Uruguay en 1981, cuando la dictadura c\u00edvico-militar llevaba ocho a\u00f1os en el poder. Por entonces hac\u00eda mucho tiempo que los tupamaros hab\u00edan sido aniquilados, as\u00ed que no hab\u00eda\u2026","rel":"","context":"En \u00ab1982\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/11\/fmapucarafauruguaya1982.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14989,"url":"https:\/\/aeropinakes.com\/wordpress\/1965\/01\/12\/plantando-la-bandera-argentina-en-el-rincon-mas-remoto-de-la-tierra-y-de-la-republica\/","url_meta":{"origin":3900,"position":3},"title":"Plantando la bandera argentina en el rinc\u00f3n m\u00e1s remoto de la Tierra (y de la Rep\u00fablica)","date":"1965","format":false,"excerpt":"\u00a0 El de Havilland Canada Beaver del Grupo A\u00e9reo Ant\u00e1rtico de la Fuerza A\u00e9rea, que particip\u00f3 en la expedici\u00f3n a\u00e9rea que plant\u00f3 la bandera argentina en el Polo Sur, el 4 de noviembre de 1965 (1). La FA adquiri\u00f3 seis Beavers para su aviaci\u00f3n ant\u00e1rtica y la Marina aport\u00f3 dos\u2026","rel":"","context":"En \u00ab1965\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/01\/dehavillandcanadabeavergaaargentina1962ov.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7566,"url":"https:\/\/aeropinakes.com\/wordpress\/1971\/06\/17\/tecnologia-germano-argentina-para-la-india\/","url_meta":{"origin":3900,"position":4},"title":"Tecnolog\u00eda germano-argentina para la India","date":"1971","format":false,"excerpt":"\u00a0 Un Marut de la Fuerza A\u00e9rea India, hacia 1970. \u00a0 En 1956, un a\u00f1o despu\u00e9s de la conferencia de pa\u00edses no alineados de Bandung \u2013que dio origen al concepto de Tercer Mundo, y en la que tuvo un gran papel Jawaharlal Nehru\u2013 comenzaron los trabajos para dise\u00f1ar el primer\u2026","rel":"","context":"En \u00ab1971\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/hindustanmarut1971.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":22,"url":"https:\/\/aeropinakes.com\/wordpress\/1947\/09\/25\/publicidad-de-fama-flota-aerea-mercante\/","url_meta":{"origin":3900,"position":5},"title":"FAMA","date":"1947","format":false,"excerpt":"Publicidad de FAMA - Flota A\u00e9rea Mercante Argentina Flight, 25 de septiembre de 1947 Ver en Aeropinakes","rel":"","context":"En \u00ab1947\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2014\/04\/tumblr_n3m7eqsywh1rbnd77o1_12801.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/3900"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=3900"}],"version-history":[{"count":0,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/3900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/4064"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=3900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=3900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=3900"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=3900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}