{"id":3769,"date":"1995-02-26T19:13:38","date_gmt":"1995-02-26T18:13:38","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?p=3769"},"modified":"2015-09-01T19:06:09","modified_gmt":"2015-09-01T17:06:09","slug":"hornets-para-la-democracia-espanola","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1995\/02\/26\/hornets-para-la-democracia-espanola\/","title":{"rendered":"Hornets para la democracia espa\u00f1ola"},"content":{"rendered":"<h4 style=\"text-align: left;\" align=\"CENTER\"><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/02\/mcdonnelldouglashornetedela1995.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-3771\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/02\/mcdonnelldouglashornetedela1995.jpg\" alt=\"mcdonnelldouglashornetedela1995\" width=\"800\" height=\"163\" \/><\/a><\/h4>\n<h4 style=\"text-align: left;\" align=\"CENTER\"><\/h4>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: left;\" align=\"CENTER\"><strong>Un\u00a0McDonnell Douglas F-18 Hornet\u00a0del Ej\u00e9rcito del Aire, como los enviados a la base a\u00e9rea de Aviano (Italia) por cuenta de la OTAN, y que tomaron parte en las guerras de la antigua Yugoslavia (1995).<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\">La gran decisi\u00f3n acerca del nuevo caza moderno que necesitaba el prestigio militar espa\u00f1ol se tom\u00f3 en la primera mitad\u00a0 de la d\u00e9cada de 1980 en paralelo a la decisi\u00f3n, con refer\u00e9ndum incluido, de integrar Espa\u00f1a en la OTAN. El ganador fue el McDonnell Douglas F-18 Hornet. A diferencia de los aviones norteamericanos recibidos durante la dictadura franquista, que eran pr\u00e9stamos,\u00a0regalos y en todo caso\u00a0no demasiado caros, la joven democracia espa\u00f1ola tuvo que pagar una enorme cantidad de dinero por las 70 unidades\u2028encargadas al fabricante.<\/p>\n<p style=\"text-align: left;\">Ya no se trataba de recibir aviones norteamericanos de segunda mano, sino de un minucioso programa de evaluaci\u00f3n de todo lo disponible en el mercado, desde el Mirage 2000\u00a0al F-16, que se llam\u00f3 Programa FACA (Futuro Avi\u00f3n de Caza\u00a0y Ataque) y durante el cual los representantes del Ej\u00e9rcito del Aire disfrutaron de lo lindo. El gobierno socialista tuvo un gesto con los militares, financi\u00e1ndoles un avi\u00f3n tan caro y sofisticado, que vino bien para limar asperezas tan poco tiempo despu\u00e9s del intento de golpe de estado del 23 de febrero. La idea impl\u00edcita era que los militares espa\u00f1oles, provistos de medios de alta tecnolog\u00eda para ejercer su profesi\u00f3n, pod\u00edan olvidarse de su turbio pasado y servir con lealtad a la democracia. Desde entonces el F-18 ha participado en todas las guerras en que ha intervenido Espa\u00f1a con aviones, empezando en la antigua Yugoslavia en 1995 y terminando en la extra\u00f1a guerra de Libia de 2011.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Un\u00a0McDonnell Douglas F-18 Hornet\u00a0del Ej\u00e9rcito del Aire, como los enviados a la base a\u00e9rea de Aviano (Italia) por cuenta de la OTAN, y que &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":3771,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":[]},"categories":[845,559,1063],"tags":[940],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/02\/mcdonnelldouglashornetedela1995-e1424974871635.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-YN","jetpack-related-posts":[{"id":8695,"url":"https:\/\/aeropinakes.com\/wordpress\/1975\/09\/15\/el-azote-de-las-bardenas\/","url_meta":{"origin":3769,"position":0},"title":"El azote de las Bardenas","date":"1975","format":false,"excerpt":"\u00a0 Un F-4C (McDonnell Douglas F-4 Phantom II) del Ej\u00e9rcito del Aire espa\u00f1ol a mediados de la d\u00e9cada de 1970. \u00a0 El Desfile de la Victoria n\u00ba 36 ser\u00eda el \u00faltimo presidido por el general Franco. El Caudillo ten\u00eda las facultades f\u00edsicas muy mermadas despu\u00e9s de la grave enfermedad que\u2026","rel":"","context":"En \u00ab1975\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/09\/mcdonnellphantomedela1975.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8447,"url":"https:\/\/aeropinakes.com\/wordpress\/1965\/08\/22\/mach-2-para-el-franquismo\/","url_meta":{"origin":3769,"position":1},"title":"Mach 2 para el franquismo","date":"1965","format":false,"excerpt":"\u00a0 Lockheed F-104 Starfighter del Ej\u00e9rcito del Aire, hacia 1965. \u00a0 Con el tiempo, muchos de los pa\u00edses de lo que se llamaba entonces Mundo Libre utilizaron este avi\u00f3n. En 1964, le toc\u00f3 a Espa\u00f1a el turno de unirse al club de peticionarios del Starfighter. Los militares norteamericanos no entend\u00edan\u2026","rel":"","context":"En \u00ab1965\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/08\/lockheedstarfighterspain1964.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":509,"url":"https:\/\/aeropinakes.com\/wordpress\/1959\/11\/16\/ejercicio-milano-aeroplano-n-13-1995\/","url_meta":{"origin":3769,"position":2},"title":"Ejercicio \u201cMilano\u201d","date":"1959","format":false,"excerpt":"Ejercicio \u201cMilano\u201d Aeroplano, n\u00ba 13 (1995) (http:\/\/www.mde.es)","rel":"","context":"En \u00ab1959\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2012\/07\/tumblr_m79o8za0oc1rbnd77o1_1280.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":123,"url":"https:\/\/aeropinakes.com\/wordpress\/1973\/07\/06\/linea-de-aviones-f-5-construidos-por-la-factoria\/","url_meta":{"origin":3769,"position":3},"title":"F-5 construidos en Sevilla","date":"1973","format":false,"excerpt":"\u00a0 L\u00ednea de aviones F-5 construidos por la factor\u00eda sevillana de la C.A.S.A. Espa\u00f1a, 80 a\u00f1os. Separata de \u201cFrancisco Franco, un siglo de Espa\u00f1a, de Ricardo de la Cierva - Editora Nacional (1973) - Franco y Sevilla","rel":"","context":"En \u00ab1969\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2013\/07\/tumblr_mpiube5jdl1rbnd77o1_12802.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7224,"url":"https:\/\/aeropinakes.com\/wordpress\/1965\/03\/25\/centinelas-del-aire-pilotos-de-reactor\/","url_meta":{"origin":3769,"position":4},"title":"Centinelas del aire (pilotos de reactor)","date":"1965","format":false,"excerpt":"Documental del NODO de 1965, filmado en la base de Sabres de Talavera la Real","rel":"","context":"En \u00ab1965\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/03\/centinelasaire.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8700,"url":"https:\/\/aeropinakes.com\/wordpress\/1962\/09\/15\/disparando-sobre-el-generalisimo\/","url_meta":{"origin":3769,"position":5},"title":"Disparando sobre el General\u00edsimo","date":"1962","format":false,"excerpt":"\u00a0 North American F-86 Sabre de la patrulla acrob\u00e1tica Ascua del Ej\u00e9rcito del Aire espa\u00f1ol, a comienzos de la d\u00e9cada de 1960. \u00a0 En una exhibici\u00f3n de la Patrulla Ascua en la base a\u00e9rea de Manises, el verano de 1962, alguien tuvo la precauci\u00f3n de advertir al Caudillo del n\u00famero\u2026","rel":"","context":"En \u00ab1962\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/09\/northamericansabreascua1962.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/3769"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=3769"}],"version-history":[{"count":0,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/3769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/3771"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=3769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=3769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=3769"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=3769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}