{"id":2564,"date":"2015-01-03T18:31:26","date_gmt":"2015-01-03T17:31:26","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?p=2564"},"modified":"2017-02-17T15:27:59","modified_gmt":"2017-02-17T14:27:59","slug":"pilatus-pc-7-pc-9-y-beechcraft-texan-ii-informacion-general","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/2015\/01\/03\/pilatus-pc-7-pc-9-y-beechcraft-texan-ii-informacion-general\/","title":{"rendered":"Pilatus PC-7, PC-9 y Beechcraft Texan II: entrenadores cuasireactores y aviones COIN"},"content":{"rendered":"<h4><\/h4>\n<p>A partir de un avi\u00f3n de entrenamiento turboh\u00e9lice fabricado por la firma suiza Pilatus durante la d\u00e9cada de 1970, el PC-7, se desarroll\u00f3 una variante m\u00e1s sofisticada que tambi\u00e9n tuvo bastante \u00e9xito, el PC-9 y por \u00faltimo una versi\u00f3n muy modificada de la firma Beechcraft (con un motor mucho m\u00e1s potente) que es actualmente el avi\u00f3n de entrenamiento b\u00e1sico general de todas las fuerzas a\u00e9reas de los Estados Unidos. El uso del motor turboh\u00e9lice permite simular el entrenamiento con un reactor a un coste inferior. Como todos los entrenadores, estos aviones se han usado mucho como aparatos de contrainsurgencia\u00a0en guerras contra enemigos desprovistos de aviaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>A partir de un avi\u00f3n de entrenamiento turboh\u00e9lice fabricado por la firma suiza Pilatus durante la d\u00e9cada de 1970, el PC-7, se desarroll\u00f3 una variante &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":[]},"categories":[924,619,923],"tags":[],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-Fm","jetpack-related-posts":[{"id":7452,"url":"https:\/\/aeropinakes.com\/wordpress\/1994\/06\/02\/la-fam-contra-el-ezln\/","url_meta":{"origin":2564,"position":0},"title":"La FAM contra el EZLN","date":"1994","format":false,"excerpt":"\u00a0 Un PC-7 de la Fuerza A\u00e9rea Mexicana, circa 1995. \u00a0 El Pilatus PC-7 y derivados es tecnolog\u00eda suiza a buen precio en forma de aviones de instrucci\u00f3n, pero que terminan a veces convirti\u00e9ndose en aviones contra-insurgencia en pa\u00edses de baja renta por habitante. As\u00ed sucedi\u00f3 en M\u00e9xico, cuando la\u2026","rel":"","context":"En \u00ab1994\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/pilatuspc7famexicana1994.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2556,"url":"https:\/\/aeropinakes.com\/wordpress\/2013\/01\/03\/texan-ii-para-la-nueva-fuerza-aerea-iraqui\/","url_meta":{"origin":2564,"position":1},"title":"Texan II para la nueva fuerza a\u00e9rea iraqu\u00ed","date":"2013","format":false,"excerpt":"\u00a0 Un Texan II de la fuerza a\u00e9rea iraqu\u00ed a comienzos de los 2010s. \u00a0 Despu\u00e9s de sus tres destrucciones casi completas en 1941, 1991 y 2003, la fuerza a\u00e9rea iraqu\u00ed se est\u00e1 volviendo a crear estos \u00faltimos a\u00f1os con material exclusivamente norteamericano, principalmente aviones ligeros, transportes y aparatos de\u2026","rel":"","context":"En \u00ab2013\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/01\/pilatuspc9-beechtexaniiiraq.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3240,"url":"https:\/\/aeropinakes.com\/wordpress\/1960\/01\/31\/pilatus-porter-un-avion-de-montana-para-el-todo-mundo\/","url_meta":{"origin":2564,"position":2},"title":"Pilatus Porter: un avi\u00f3n de monta\u00f1a para todo el mundo","date":"1960","format":false,"excerpt":"\u00a0 La s\u00f3lida estructura del Porter y su respetable tama\u00f1o le aseguraron larga vida como avi\u00f3n para todo uso. \u00a0 \"El avi\u00f3n ideal para transporte de pasajeros, rescate y servicios generales en los Alpes suizos\" Esta era la opini\u00f3n recogida en Flight (1) en 1960, cuando el Porter fue presentado\u2026","rel":"","context":"En \u00ab1960\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1960\/01\/pilatuspc6porterbp.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7703,"url":"https:\/\/aeropinakes.com\/wordpress\/2007\/06\/21\/una-navaja-suiza-de-la-contrainsurgencia\/","url_meta":{"origin":2564,"position":3},"title":"Una navaja suiza de la contrainsurgencia","date":"2007","format":false,"excerpt":"\u00a0 Un Fairchild AU-23 Peacemaker (algo as\u00ed como Pacificador) (Pilatus PC-6 Porter) de la fuerza a\u00e9rea tailandesa, a mediados de la d\u00e9cada de 2000. \u00a0 En 1971, con la guerra de Vietnam perdida, las fuerzas a\u00e9reas norteamericanas trabajaron en un programa para dotar a la fuerza a\u00e9rea de la Rep\u00fablica\u2026","rel":"","context":"En \u00ab2007\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/pilatusporterfairchildpeacemakertai2007.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4689,"url":"https:\/\/aeropinakes.com\/wordpress\/2014\/09\/01\/pilatus-pc-7\/","url_meta":{"origin":2564,"position":4},"title":"Pilatus PC-7","date":"2014","format":false,"excerpt":"Portada del folleto informativo del Pilatus PC-7 MK II. Ilustraci\u00f3n: Pilatus","rel":"","context":"En \u00ab2014\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/PilatusPC7MKII-Factsheet_P\u00e1gina_1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8774,"url":"https:\/\/aeropinakes.com\/wordpress\/1975\/09\/28\/texan-coin\/","url_meta":{"origin":2564,"position":5},"title":"Texan COIN","date":"1975","format":false,"excerpt":"\u00a0 Un North American Texan de una unidad de entrenamiento del Ej\u00e9rcito del Aire. \u00a0 El Texan se recibi\u00f3 en gran n\u00famero como parte del programa de ayuda militar de los Estados Unidos y fue el entrenador b\u00e1sico del Ej\u00e9rcito del Aire durante a\u00f1os. Con aviones comprados a Francia se\u2026","rel":"","context":"En \u00ab1975\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/09\/northamericantexanejercitodelaire1975-.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/2564"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=2564"}],"version-history":[{"count":0,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/2564\/revisions"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=2564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=2564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=2564"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=2564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}