{"id":18404,"date":"2022-02-12T17:51:15","date_gmt":"2022-02-12T16:51:15","guid":{"rendered":"https:\/\/aeropinakes.com\/wordpress\/?p=18404"},"modified":"2022-09-30T19:32:02","modified_gmt":"2022-09-30T17:32:02","slug":"los-aviones-del-terror-la-historia-insolita-de-una-tecnologia-cruel","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/2022\/02\/12\/los-aviones-del-terror-la-historia-insolita-de-una-tecnologia-cruel\/","title":{"rendered":"Los aviones del terror: la historia ins\u00f3lita de una tecnolog\u00eda cruel"},"content":{"rendered":"<p><a href=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2022\/02\/losavionesdelterror.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18386 size-large\" src=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2022\/02\/losavionesdelterror-683x1024.jpg\" alt=\"\" width=\"683\" height=\"1024\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2022\/02\/losavionesdelterror-683x1024.jpg 683w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2022\/02\/losavionesdelterror-200x300.jpg 200w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2022\/02\/losavionesdelterror.jpg 800w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Los visitantes del Museo Nacional de del Aire y el Espacio, Washington DC, Estados Unidos, pueden ver un objeto pol\u00e9mico de 30 metros de largo y 34 toneladas de peso. Es el Boeing B-29 <em>Enola Gay<\/em>, el avi\u00f3n que lanz\u00f3 la bomba at\u00f3mica sobre Hiroshima que mat\u00f3 a decenas de miles de personas en un instante. Desde su colocaci\u00f3n en el museo, la controversia no ha cesado. Un intento de dar voz a las v\u00edctimas del bombardeo at\u00f3mico mediante paneles explicativos asociados al avi\u00f3n fracas\u00f3, pues se aleg\u00f3 que tal informaci\u00f3n presentar\u00eda a los pilotos norteamericanos como asesinos.<\/p>\n<p>El enorme aparato sigue ah\u00ed, dominando una sala entera del museo, sometido a protestas espor\u00e1dicas, como un enorme s\u00edmbolo del arma m\u00e1s cruel de todas, utilizada para aniquilar ciudades y acabar con la resistencia de la poblaci\u00f3n civil: el bombardero estrat\u00e9gico.<\/p>\n<p>Los bombarderos fueron considerados tan peligrosos que se realizaron repetidos esfuerzos para prohibirlos legalmente a escala internacional, esfuerzos que comenzaron mucho antes de que el primer avi\u00f3n levantara del suelo. Cuando la prohibici\u00f3n se revel\u00f3 imposible, se intent\u00f3 limitar al menos las consecuencia destructivas de su empleo contra las ciudades.<\/p>\n<p>La maquinaria militar-industrial, mientras tanto, dise\u00f1\u00f3 y fabric\u00f3 m\u00e1quinas cada vez m\u00e1s mort\u00edferas, las armas m\u00e1s complejas creadas en la historia de la humanidad. Paso a paso, se puso a punto una tecnolog\u00eda letal que culmin\u00f3 en las masacres de Hamburgo, Dresde, Tokio e Hiroshima. Y la historia no acab\u00f3 ah\u00ed, ni mucho menos. Ya como parte de la guerra fr\u00eda, se siguieron fabricando bombarderos gigantes, capaces de performances disparatadas en t\u00e9rminos de velocidad, distancia y carga mort\u00edfera lanzable.<\/p>\n<p>La l\u00ednea de los aviones del terror va desde el Ily&#8217;a Muromets ruso de 1913, lejano descendiente de la m\u00e1quina voladora imaginada por Julio Verne en <em>Robur el conquistador<\/em>, hasta el Xian H-20, que ser\u00e1 el primer bombardero estrat\u00e9gico dise\u00f1ado y fabricado en China.<\/p>\n<p>Con el apoyo de 139 ilustraciones, muchas de ellas perfiles in\u00e9ditos, <a href=\"https:\/\/www.melusina.com\/libro.php?idg=52980\"><em><strong>Los aviones del terror &#8211; Historia de los bombarderos\u00a0<\/strong><\/em><strong>(Editorial Melusina, 2022)<\/strong><\/a> habla de estos y de muchos otros aviones, desgranando historias en las que se unen decisiones pol\u00edticas, empujones a los l\u00edmites de la tecnolog\u00eda, y la creaci\u00f3n de una letal cultura del bombardeo que requiri\u00f3 y requiere todav\u00eda recursos ingentes del complejo militar industrial.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Los visitantes del Museo Nacional de del Aire y el Espacio, Washington DC, Estados Unidos, pueden ver un objeto pol\u00e9mico de 30 metros de &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":18386,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":[]},"categories":[1],"tags":[],"Asuntos":[3373],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2022\/02\/losavionesdelterror.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-4MQ","jetpack-related-posts":[{"id":8962,"url":"https:\/\/aeropinakes.com\/wordpress\/1962\/11\/13\/el-avion-de-ho-chi-minh\/","url_meta":{"origin":18404,"position":0},"title":"El avi\u00f3n de Ho Chi Minh","date":"1962","format":false,"excerpt":"\u00a0 Iliuschin Il-14 n\u00ba C-482, tal como se exhibe en el museo de historia militar de Vietnam. \u00a0 Esta hist\u00f3rica m\u00e1quina se puede ver en el Museo de Historia Militar de Vietnam, que est\u00e1 precisamente en el n\u00ba 28A de la calle Dien Bien Phu, Hanoi. Una placa escrita en\u2026","rel":"","context":"En \u00ab1962\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/11\/ilyuschinil14hochiminh1962.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2688,"url":"https:\/\/aeropinakes.com\/wordpress\/1919\/01\/06\/junkers-f-13-el-primer-avion-comercial-de-la-historia\/","url_meta":{"origin":18404,"position":1},"title":"Junkers F.13: el primer avi\u00f3n comercial de la historia","date":"1919","format":false,"excerpt":"\u00a0 Un Junkers F.13 yemen\u00ed en 1926, todav\u00eda con la matr\u00edcula alemana. \u00a0 Todo empez\u00f3 en 1915, \u00a0cuando el ingeniero Hugo Junkers present\u00f3 su primer modelo de avi\u00f3n, el J1, un monoplano completamente met\u00e1lico sin cables ni riostras por ninguna parte, solamente alas unidas s\u00f3lidamente a un fuselaje. En 1919\u2026","rel":"","context":"En \u00ab1919\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1919\/01\/junkersf13yemen1926.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14802,"url":"https:\/\/aeropinakes.com\/wordpress\/2019\/07\/23\/una-ominosa-presencia-en-el-gran-museo-de-aviacion\/","url_meta":{"origin":18404,"position":2},"title":"Una ominosa presencia en el gran museo de aviaci\u00f3n","date":"2019","format":false,"excerpt":"\u00a0 El Boeing B-29 Silverplate (modificado para llevar la bomba at\u00f3mica) Enola Gay, el bombardero de Hiroshima Hiroshima y Auschwitz van con frecuencia en la misma frase \u2013\"el siglo de Hiroshima y Auschwitz\"\u2013 y se pueden comparar sus restos desde el mismo punto de vista. Auschwitz es actualmente un museo\u2026","rel":"","context":"En \u00ab1995\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/11\/boeingb29hiroshima1945.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3773,"url":"https:\/\/aeropinakes.com\/wordpress\/1998\/02\/26\/el-museo-del-aire\/","url_meta":{"origin":18404,"position":3},"title":"El Museo del Aire","date":"1998","format":false,"excerpt":"\u00a0 El s\u00edmbolo a\u00e9reo del comunismo, tal como se puede ver el Museo del Aire Que se sepa, el MiG-17 nunca vol\u00f3 en Espa\u00f1a. Parece que el ejemplar representado arriba fue\u00a0un intercambio del museo de la Fuerza A\u00e9rea B\u00falgara con el Museo del Ej\u00e9rcito del Aire en Cuatro Vientos (Madrid)\u00a0(1).\u2026","rel":"","context":"En \u00ab1998\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1998\/02\/mig17comunista.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8281,"url":"https:\/\/aeropinakes.com\/wordpress\/1939\/08\/14\/el-caza-principal-de-polonia-el-ano-de-la-invasion-alemana\/","url_meta":{"origin":18404,"position":4},"title":"El caza principal de Polonia, el a\u00f1o de la invasi\u00f3n alemana","date":"1939","format":false,"excerpt":"\u00a0 Un PZL P.11 de la Fuerza A\u00e9rea Polaca, pintado como el ejemplar expuesto en el Museo\u00a0Polaco de la Aviaci\u00f3n, en Cracovia. \u00a0 El PZL P.11 era el principal avi\u00f3n de caza de la fuerza a\u00e9rea polaca en septiembre de 1939. Ten\u00eda 200 km\/h menos de velocidad punta y aproximadamente\u2026","rel":"","context":"En \u00ab1939\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/08\/pzlp111939.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8708,"url":"https:\/\/aeropinakes.com\/wordpress\/1958\/09\/15\/el-simbolo-aereo-del-franquismo\/","url_meta":{"origin":18404,"position":5},"title":"El s\u00edmbolo a\u00e9reo del franquismo","date":"1958","format":false,"excerpt":"El CASA 352 (Junkers Ju-52) que se puede ver en el Museo del Aire.\u00a0El Ju-52 fue fabricado despu\u00e9s de la guerra civil en Espa\u00f1a, como CASA 352. Durante muchos a\u00f1os fue el principal avi\u00f3n de transporte militar. \u00a0 En Ifni, noviembre de 1957, el ej\u00e9rcito espa\u00f1ol se encontr\u00f3 con \u201celementos\u2026","rel":"","context":"En \u00ab1958\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/09\/CASA352Ju521978.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/18404"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=18404"}],"version-history":[{"count":6,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/18404\/revisions"}],"predecessor-version":[{"id":18410,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/18404\/revisions\/18410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/18386"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=18404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=18404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=18404"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=18404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}