{"id":17874,"date":"1911-11-06T16:23:43","date_gmt":"1911-11-06T16:23:43","guid":{"rendered":"https:\/\/aeropinakes.com\/wordpress\/?p=17874"},"modified":"2020-08-07T19:21:31","modified_gmt":"2020-08-07T17:21:31","slug":"el-primer-ataque-aereo-visto-desde-abajo","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1911\/11\/06\/el-primer-ataque-aereo-visto-desde-abajo\/","title":{"rendered":"El primer ataque a\u00e9reo, visto desde abajo"},"content":{"rendered":"<h3><\/h3>\n<h3><a href=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2020\/08\/1911-17-nov-lasocurrencias.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17875 size-full\" src=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2020\/08\/1911-17-nov-lasocurrencias.jpg\" alt=\"\" width=\"1200\" height=\"1764\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2020\/08\/1911-17-nov-lasocurrencias.jpg 1200w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2020\/08\/1911-17-nov-lasocurrencias-204x300.jpg 204w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2020\/08\/1911-17-nov-lasocurrencias-697x1024.jpg 697w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>Portada de <em>Las ocurrencias<\/em> del 17 de noviembre de 1911. El texto que la acompa\u00f1a, a tres d\u00e9cadas de distancia de Hamburgo, Dresde e Hiroshima, acierta plenamente en su predicci\u00f3n de \u00abun porvenir de espantosas carnicer\u00edas\u00bb. La imagen y el texto describen una masacre que probablemente no ocurri\u00f3, aunque la conmoci\u00f3n de los turcos fue muy real.<\/h3>\n<p>\u00abNUESTRA PORTADA<\/p>\n<p><strong>La guerra en los aires <\/strong><\/p>\n<p>Por primera vez un aeroplano ha sido utilizado como m\u00e1quina de guerra, sembrando la desolaci\u00f3n y la muerte. El sencillo aparato a\u00e9reo, gloria del ingenio humano, se convierte en arma asesina y exterminadora.<\/p>\n<p>Es un oficial italiano, el teniente de Ingenieros Gavotti quien ha realizado la proeza, lanz\u00e1ndose en los aires con su m\u00e1quina, pasando como un meteoro sobre el campamento de los turcos y arroj\u00e1ndoles bombas de picrita, un explosivo nuevo m\u00e1s mort\u00edfero que la dinamita.<\/p>\n<p>Se ha iniciado de esta forma la guerra desde los aires, \u00e1 la que seguir\u00e1 seguramente al guerra en los aires. Las dos son terribles en sus efectos, y preludian un porvenir de espantosas carnicer\u00edas.<\/p>\n<p>El teniente Gavotti sali\u00f3 de Tr\u00edpoli remont\u00e1ndose en los aires con su aeroplano en direcci\u00f3n al Oasis de Ain-Zara. Quer\u00eda sorprender a los turcos en su campamento, arrojando sobre ellos cuatro bombas cargadas de picrita, cada una de ellas del tama\u00f1o de una naranja.<\/p>\n<p>Los turcos y \u00e1rabos, llenos de terror, vieron acercarse al extra\u00f1o p\u00e1jaro; y de improviso, entre los grupos de soldados, estallaron dos bombas. La explosi\u00f3n fu\u00e9 terrible, causando grandes estragos; vi\u00f3se caer \u00e1 muchos hombres muertos y heridos, y el p\u00e1nico producido por aquella lluvia de metralla que ca\u00eda del cielo atemoriz\u00f3 \u00e1 los m\u00e1s valientes.<\/p>\n<p>Los ofic\u00edales turcos dieron orden \u00e1 sus mejores tiradores de que disparasen contra el enemigo a\u00e9reo, pero era muy dif\u00edcil alcanzarle, pues el aeroplano evolucion\u00f3 con extraordinaria rapidez, retornando de nuevo \u00e1 Tr\u00edpoli. Gavotti, antes de alejarse, lanz\u00f3 otras dos bombas, causando m\u00e1s de un centenar de v\u00edctimas.<\/p>\n<p>Este primer ensayo del aeroplano, como arma de combate, plantea definitivamente el problema de la resistencia, pues \u00e1 la m\u00e1quina a\u00e9rea s\u00f3lo se la puede vencer con otro artefacto semejante.<\/p>\n<p>Ahora los italianos, disponen de una flotilla a\u00e9rea, con la que descubren los movimientos del ej\u00e9rcito enemigo\u00bb.<\/p>\n<p>Las ocurrencias, 17 de noviembre de 1911. <a href=\"http:\/\/www.bne.es\/es\/Catalogos\/HemerotecaDigital\/\">Biblioteca Nacional &#8211; Hemeroteca Digital<\/a>.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Portada de Las ocurrencias del 17 de noviembre de 1911. El texto que la acompa\u00f1a, a tres d\u00e9cadas de distancia de Hamburgo, Dresde e Hiroshima, &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":17875,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":[]},"categories":[698,3083,570,138,321,2848],"tags":[1333],"Asuntos":[2520],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2020\/08\/1911-17-nov-lasocurrencias.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-4Ei","jetpack-related-posts":[{"id":1923,"url":"https:\/\/aeropinakes.com\/wordpress\/1912\/12\/14\/bleriot-xi-y-la-invasion-de-libia\/","url_meta":{"origin":17874,"position":0},"title":"\u201cItalia es vuestro padre\u201d","date":"1912","format":false,"excerpt":"\u00a0 \u00a0 Un Bl\u00e9riot XI de la fuerza a\u00e9rea italiana en Libia, hacia 1912. \u00a0 \u201cLos aviadores italianos han sacado, en la terrible realidad de la guerra, todo el partido que se podr\u00eda esperar de la nueva m\u00e1quina [a\u00e9rea]\u201d \u2013informaba L\u2019Aerophile\u00a0(1)\u00a0en enero de 1912. La guerra era la conquista italiana\u2026","rel":"","context":"En \u00ab1912\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2014\/12\/bleriotxilibia1912.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":12526,"url":"https:\/\/aeropinakes.com\/wordpress\/1911\/11\/20\/33-anos-antes-de-hiroshima\/","url_meta":{"origin":17874,"position":1},"title":"33 a\u00f1os antes de Hiroshima","date":"1911","format":false,"excerpt":"\u00a0 Un Etrich Taube que podr\u00eda haber sido el de Giulio Gavotti, en Tr\u00edpoli en 1911. Los aviones de la expedici\u00f3n italiana a Libia, al parecer, no llevaban ning\u00fan tipo de identificaci\u00f3n.\u00a0 \u00a0 El 1 de noviembre es (desde 1994) el D\u00eda Mundial Vegano, pero deber\u00eda ser tambi\u00e9n el D\u00eda\u2026","rel":"","context":"En \u00ab1911\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/01\/etrichtaubelibia1911.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3773,"url":"https:\/\/aeropinakes.com\/wordpress\/1998\/02\/26\/el-museo-del-aire\/","url_meta":{"origin":17874,"position":2},"title":"El Museo del Aire","date":"1998","format":false,"excerpt":"\u00a0 El s\u00edmbolo a\u00e9reo del comunismo, tal como se puede ver el Museo del Aire Que se sepa, el MiG-17 nunca vol\u00f3 en Espa\u00f1a. Parece que el ejemplar representado arriba fue\u00a0un intercambio del museo de la Fuerza A\u00e9rea B\u00falgara con el Museo del Ej\u00e9rcito del Aire en Cuatro Vientos (Madrid)\u00a0(1).\u2026","rel":"","context":"En \u00ab1998\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1998\/02\/mig17comunista.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4604,"url":"https:\/\/aeropinakes.com\/wordpress\/1941\/12\/01\/4604-2\/","url_meta":{"origin":17874,"position":3},"title":"Una semana antes del ataque a Pearl Harbour","date":"1941","format":false,"excerpt":"Un B-17 rampante en la portada de Life del 1 de diciembre de 1941, justo una semana antes de la entrada en guerra de los Estados Unidos tras el ataque de Pearl\u00a0Harbour. La foto anunciaba un extenso reportaje sobre el creciente poder\u00edo a\u00e9reo de los Estados Unidos, de los que\u2026","rel":"","context":"En \u00ab1941\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/08\/life.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4481,"url":"https:\/\/aeropinakes.com\/wordpress\/1913\/08\/29\/maurice-farman-mf-7-aviacion-del-ejercito-frances\/","url_meta":{"origin":17874,"position":4},"title":"Maurice Farman MF.7 &#8211; Aviaci\u00f3n del ej\u00e9rcito franc\u00e9s","date":"1913","format":false,"excerpt":"\u00a0 Maurice Farman MF.7 - Aviaci\u00f3n del ej\u00e9rcito franc\u00e9s, 1913 \u00a0 La Liga Nacional A\u00e9rea francesa (Ligue Nationale A\u00e9rienne) que hab\u00eda sido creada pocos a\u00f1os antes sobre el modelo de la enorme Liga Naval alemana, empez\u00f3 a importunar al Ministerio de Colonias en 1910 sobre gran utilidad de los aviones\u2026","rel":"","context":"En \u00abArgelia\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/08\/mauricefarmanmf7argelia1913.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14818,"url":"https:\/\/aeropinakes.com\/wordpress\/1919\/07\/18\/junkers-d-i-j-9-100-metal\/","url_meta":{"origin":17874,"position":5},"title":"Junkers D.I (J 9): 100% metal","date":"1919","format":false,"excerpt":"\u00a0 Un Junkers D.I (J 9) del Servicio A\u00e9reo Imperial Alem\u00e1n, a finales de 1918. Cuando los aliados encontraron algunos Junkers D.I abandonados en campos de aviaci\u00f3n, despu\u00e9s del Armisticio, se quedaron pasmados ante esos extra\u00f1os aviones compactos cubiertos de chapa ondulada, sin un solo cable tensor al viento. Los\u2026","rel":"","context":"En \u00ab1918\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/11\/junkersdi1918.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/17874"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=17874"}],"version-history":[{"count":2,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/17874\/revisions"}],"predecessor-version":[{"id":17877,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/17874\/revisions\/17877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/17875"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=17874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=17874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=17874"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=17874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}