{"id":15823,"date":"1940-06-17T18:49:49","date_gmt":"1940-06-17T17:49:49","guid":{"rendered":"https:\/\/aeropinakes.com\/wordpress\/?p=15823"},"modified":"2019-12-09T19:29:32","modified_gmt":"2019-12-09T18:29:32","slug":"viviendas-para-braceros-y-para-labradores","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1940\/06\/17\/viviendas-para-braceros-y-para-labradores\/","title":{"rendered":"Viviendas para braceros y para labradores"},"content":{"rendered":"<p><a href=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/06\/1940-dic-14-fotos1500.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15824 size-full\" src=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/06\/1940-dic-14-fotos1500.jpg\" alt=\"\" width=\"1500\" height=\"1985\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/06\/1940-dic-14-fotos1500.jpg 1500w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/06\/1940-dic-14-fotos1500-227x300.jpg 227w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/06\/1940-dic-14-fotos1500-774x1024.jpg 774w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/a><\/p>\n<p>Reportaje gr\u00e1fico sobre la entrega de viviendas en Viso del Marqu\u00e9s, al sur de la provincia de Ciudad Real (Fotos, 14 de diciembre de 1940). El censo de 1940 daba m\u00e1s 5.500 habitantes al pueblo y casi 1.400 hogares (actualmente apenas supera los 2.500 habitantes). De las fotos de abajo, las de la izquierda parecen corresponder a labradores (con granero en el piso de arriba y compuerta) y las de la derecha, de un solo piso, a braceros. Los reportajes de entrega de viviendas a las clases populares asolaron la prensa durante el franquismo inferior. Cosa extra\u00f1a, en este reportaje falta el elemento fundamental, que era la foto del jefe local del movimiento, gobernador civil o incluso el Caudillo en persona, entregando los t\u00edtulos de propiedad en mano a los beneficiarios. Falto de este elemento de propaganda pol\u00edtica, el reportaje adquiere un tono algo desolado y metaf\u00edsico.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Reportaje gr\u00e1fico sobre la entrega de viviendas en Viso del Marqu\u00e9s, al sur de la provincia de Ciudad Real (Fotos, 14 de diciembre de 1940). &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":15826,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":[]},"categories":[662,3083,3214],"tags":[],"Asuntos":[2730],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/06\/1940-dic-14-fotosdestacada.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-47d","jetpack-related-posts":[{"id":15171,"url":"https:\/\/aeropinakes.com\/wordpress\/1940\/02\/22\/como-un-stuka-sobre-los-docks-del-tamesis\/","url_meta":{"origin":15823,"position":0},"title":"\u00abComo un \u00abStuka\u00bb sobre los docks del T\u00e1mesis\u00bb","date":"1940","format":false,"excerpt":"\"De pronto, como un \u00abStuka\u00bb sobre los docks del T\u00e1mesis, me lanc\u00e9 a fondo\". Esta frase de una escena de declaraci\u00f3n de amor incluida en La pasi\u00f3n de Don Oroncio, un cuento de Jes\u00fas Huarte publicado en la revista Fotos el 30 de noviembre de 1940, demuestra la gran popularidad\u2026","rel":"","context":"En \u00ab1940\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/02\/1940-oct-5-fotos.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":15160,"url":"https:\/\/aeropinakes.com\/wordpress\/1940\/02\/17\/una-escena-de-el-senor-de-los-anillos-tarde-de-toros-en-el-pueblo\/","url_meta":{"origin":15823,"position":1},"title":"Una escena de El se\u00f1or de los anillos: tarde de toros en el pueblo","date":"1940","format":false,"excerpt":"La mayor\u00eda de las fotos del reportaje \"Tarde de toros en el pueblo\" enfocan a los toreros aficionados y a las presidentas, que eran las hijas, esposas y novias de los notables de la comunidad de veraneantes de un pueblo sin identificar de la sierra de Madrid. Solo una foto\u2026","rel":"","context":"En \u00ab1940\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/02\/31ago1940-unica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":18793,"url":"https:\/\/aeropinakes.com\/wordpress\/2026\/03\/24\/rub-al-jali-queda-inaugurada-la-espana-vaciada\/","url_meta":{"origin":15823,"position":2},"title":"Rub Al Jali: queda inaugurada la Espa\u00f1a vaciada","date":"2026","format":false,"excerpt":"De un reportaje publicado en Pueblo, 17 de diciembre de 1969. El gobernador civil y jefe provincial del Movimiento de Zamora, Jos\u00e9 Murillo de Valdivia, visit\u00f3 tres pueblos abandonados el 14 de agosto de 1956 y fue recibido por una multitud en todos ellos. Este misterio tiene una explicaci\u00f3n. Hasta\u2026","rel":"","context":"En \u00abBlog\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2026\/03\/1969-sevendencincopueblosdestacada\u00a1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":18706,"url":"https:\/\/aeropinakes.com\/wordpress\/2025\/10\/27\/el-golem-el-monstruo-de-ladrillo\/","url_meta":{"origin":15823,"position":3},"title":"El Golem (el monstruo de ladrillo)","date":"2025","format":false,"excerpt":"Pisos y tiendas en el barrio del Pilar, Madrid. Anuncio publicado en el Diario Pueblo, 20 de abril de 1965. El 19 de agosto de 1957, Jos\u00e9 Luis Arrese, ministro de la Vivienda, inaugur\u00f3 la Era del Ladrillo en Espa\u00f1a lanzando un tractor enorme, conducido por \u00e9l mismo, contra varias\u2026","rel":"","context":"En \u00abBlog\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2025\/10\/1965-04-20-022-barriodelpilar-diariopueblo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":18067,"url":"https:\/\/aeropinakes.com\/wordpress\/1940\/12\/22\/de-guernica-a-londres\/","url_meta":{"origin":15823,"position":4},"title":"De Guernica a Londres","date":"1940","format":false,"excerpt":"Un Heinkel He-111 del escuadr\u00f3n n\u00ba 53 \u201cLegion Condor\u201d, destacado en Francia para el ataque a Inglaterra en la segunda mitad de 1940. El origen del Heinkel He-111, como bombardero disfrazado de avi\u00f3n civil, no era solamente un camuflaje del rearme nazi, sino una caracter\u00edstica habitual en su \u00e9poca que\u2026","rel":"","context":"En \u00ab1940\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2020\/12\/heinkelhe111luftwaffe1940.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":18804,"url":"https:\/\/aeropinakes.com\/wordpress\/2026\/05\/07\/una-idea-de-la-ciudad-para-el-movimiento-nacional\/","url_meta":{"origin":15823,"position":5},"title":"Una idea de la ciudad para el Movimiento Nacional\u00a0","date":"2026","format":false,"excerpt":"De la portada de la Revista Nacional de Arquitectura, n\u00ba 113-114, monogr\u00e1fico dedicado al Gran San Blas, 1968. El g\u00e9nero \u201cHitler victorioso\u201d es bastante popular, y produce regularmente relatos, novelas, ejercicios de historia alternativa, pel\u00edculas y series. Responde a una inquietante pregunta: \u00bfQu\u00e9 habr\u00eda pasado si el Tercer Reich hubiera\u2026","rel":"","context":"En \u00abBlog\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2026\/05\/1968-gransanblasdestacada.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/15823"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=15823"}],"version-history":[{"count":1,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/15823\/revisions"}],"predecessor-version":[{"id":17223,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/15823\/revisions\/17223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/15826"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=15823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=15823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=15823"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=15823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}