{"id":14738,"date":"1989-07-21T19:07:23","date_gmt":"1989-07-21T17:07:23","guid":{"rendered":"https:\/\/aeropinakes.com\/wordpress\/?p=14738"},"modified":"2019-07-22T11:43:01","modified_gmt":"2019-07-22T09:43:01","slug":"el-ultimo-grito-de-la-union-sovietica","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1989\/07\/21\/el-ultimo-grito-de-la-union-sovietica\/","title":{"rendered":"El \u00faltimo grito de la Uni\u00f3n Sovi\u00e9tica"},"content":{"rendered":"<p><a href=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/10\/antonovmriya1989.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14739 size-full\" src=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/10\/antonovmriya1989.jpg\" alt=\"\" width=\"3153\" height=\"637\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/10\/antonovmriya1989.jpg 3153w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/10\/antonovmriya1989-300x61.jpg 300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/10\/antonovmriya1989-1024x207.jpg 1024w\" sizes=\"(max-width: 3153px) 100vw, 3153px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h3>El Antonov An-225 Mriia en tiempos de su primer vuelo, a finales de 1988.<\/h3>\n<p>Como una especie de m\u00e1s dif\u00edcil todav\u00eda, la casa Antonov, despu\u00e9s de sacar en 1985 el Rusl\u00e1n, el carguero m\u00e1s capaz del mundo, present\u00f3 al p\u00fablico en 1989 el Mriia (Sue\u00f1o, en ucraniano). El monstruo de seis motores pod\u00eda llevar 250 toneladas de carga y despegar con 600 toneladas de peso total. Med\u00eda 88 metros de envergadura y 84 de longitud. La prensa sovi\u00e9tica inform\u00f3 que pod\u00eda dar cabida en su interior a 80 turismos Lada y que, a diferencia del Rusl\u00e1n, pod\u00eda llevar enormes cargas externas de hasta 10 metros de di\u00e1metro y 70 de largo, por ejemplo equipos de perforaci\u00f3n de petr\u00f3leo y gas completos, listos para funcionar en cualquier conf\u00edn de la URSS.<\/p>\n<p>El Mriia se mov\u00eda a base de\u00a0 quemar cantidades enormes de queroseno (aunque el coste energ\u00e9tico de transporte por tonelada era el m\u00e1s bajo de todos los aviones existentes) y se dise\u00f1\u00f3 con las necesidades de exploraci\u00f3n y explotaci\u00f3n de combustible f\u00f3sil en las zonas m\u00e1s apartadas del pa\u00eds. El otro requerimiento de dise\u00f1o era la capacidad de poder transportar\u00a0 en su lomo el transbordador espacial sovi\u00e9tico Bur\u00e1n. Toda la t\u00e9cnica aeron\u00e1utica m\u00e1s avanzada de la URSS se emple\u00f3 en el nuevo avi\u00f3n: \u00abnuevas aleaciones de aluminio, acero superresistente y laminados sint\u00e9ticos\u00bb (1).<\/p>\n<p>Al estilo de <em>America Builds an Aeroplane<\/em>, en la construcci\u00f3n del Mriia particip\u00f3 todo el pa\u00eds: los turboreactores fueron fabricados en Zaporozhie, las alas en Tashkent, el tren de aterrizaje en Gorki, otras partes se fabricaron en Mosc\u00fa, Leningrado y Uli\u00e1novsk. Menos de un a\u00f1o despu\u00e9s del primer vuelo del Mriiia, en diciembre de 1988, el muro de Berl\u00edn era hecho pedacitos por la multitud y se acababa a efectos pr\u00e1cticos la Uni\u00f3n de Rep\u00fablicas Socialistas Sovi\u00e9ticas. Pero el avi\u00f3n, tras unos a\u00f1os de desconcierto en que qued\u00f3 almacenado y desmotorizado, sobrevivi\u00f3 y comenz\u00f3 a realizar un valuable servicio como carguero de cargas especiales. Actualmente se baraja la posibilidad de construir m\u00e1s ejemplares.<\/p>\n<h5>(1) Un avi\u00f3n de carga que parece un sue\u00f1o. Sputnik, agosto de de 1989.<\/h5>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; El Antonov An-225 Mriia en tiempos de su primer vuelo, a finales de 1988. Como una especie de m\u00e1s dif\u00edcil todav\u00eda, la casa Antonov, &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":14739,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":[]},"categories":[839,3128,3083,624,625],"tags":[],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/10\/antonovmriya1989.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-3PI","jetpack-related-posts":[{"id":1938,"url":"https:\/\/aeropinakes.com\/wordpress\/2007\/12\/15\/el-ruslan-en-libia\/","url_meta":{"origin":14738,"position":0},"title":"Un Ruslan libio","date":"2007","format":false,"excerpt":"\u00a0 \u00a0 Un Antonov An-124 Ruslan de Libyan Arab Air Cargo a finales de la d\u00e9cada de 2000. \u00a0","rel":"","context":"En \u00ab2007\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2014\/12\/antonovruslanlac2007.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":18169,"url":"https:\/\/aeropinakes.com\/wordpress\/1933\/02\/05\/dohuet-en-la-urss\/","url_meta":{"origin":14738,"position":1},"title":"Dohuet en la URSS","date":"1933","format":false,"excerpt":"El \u00fanico ejemplar del Tupolev TB-4, que vol\u00f3 por primera vez el 3 de julio de 1933. Alucinados por el formidable aspecto del TB-3, los planificadores militares sovi\u00e9ticos empezaron a pensar en un gigantesco destructor a\u00e9reo capaz de llevar 25 toneladas de bombas, una cifra disparatada para la \u00e9poca. El\u2026","rel":"","context":"En \u00ab1933\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2021\/02\/tupolevtb4-1933.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7462,"url":"https:\/\/aeropinakes.com\/wordpress\/1979\/06\/04\/otro-modelo-gigante-de-o-k-antonov\/","url_meta":{"origin":14738,"position":2},"title":"Otro modelo gigante de O.K. Antonov","date":"1979","format":false,"excerpt":"\u00a0 Un Antonov An-22 Anteo de Aeroflot. Este gigantesco avi\u00f3n tuvo un papel importante como carguero pesado en la invasi\u00f3n sovi\u00e9tica de Afganist\u00e1n. \u00a0 La Uni\u00f3n Sovi\u00e9tica eligi\u00f3 1979 para abandonar su cautelosa pol\u00edtica internacional. Afganist\u00e1n hab\u00eda salido de la sart\u00e9n brit\u00e1nica al fuego sovi\u00e9tico, pero en 1979 el Kremlin\u2026","rel":"","context":"En \u00ab1979\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/antonoan22vanteoaeroflot1979.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":18190,"url":"https:\/\/aeropinakes.com\/wordpress\/1951\/02\/10\/el-primer-bombardero-intercontinental-sovietico\/","url_meta":{"origin":14738,"position":3},"title":"El primer bombardero intercontinental sovi\u00e9tico","date":"1951","format":false,"excerpt":"El segundo prototipo del Tupolev Tu-85, en 1951. Una vez resuelto lo m\u00e1s urgente, tener un bombardero at\u00f3mico de verdad, lo que se consigui\u00f3 en 1949, los estrategas sovi\u00e9ticos exigieron ahora tener un bombardero at\u00f3mico intercontinental, que pudiera acercarse a las prestaciones del Convair B-36 Peacemaker. La nueva m\u00e1quina deb\u00eda\u2026","rel":"","context":"En \u00ab1951\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2021\/02\/tupolevtu85-1951.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":18162,"url":"https:\/\/aeropinakes.com\/wordpress\/1972\/01\/22\/la-ultima-apuesta-sovietica-por-la-altura-y-la-velocidad\/","url_meta":{"origin":14738,"position":4},"title":"La \u00faltima apuesta sovi\u00e9tica por la altura y la velocidad","date":"1972","format":false,"excerpt":"El \u00fanico prototipo del Sujoi T-4 que vol\u00f3. Lo hizo por primera vez el 22 de agosto de 1972. A comienzos de la d\u00e9cada de 1960 la guerra fr\u00eda estaba al rojo vivo. La crisis de los misiles de Cuba puso al mundo al borde de una guerra nuclear en\u2026","rel":"","context":"En \u00ab1972\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2021\/01\/sujoit4-1972.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8093,"url":"https:\/\/aeropinakes.com\/wordpress\/1960\/07\/08\/el-impresionante-rossiya\/","url_meta":{"origin":14738,"position":5},"title":"El impresionante Rossiya","date":"1960","format":false,"excerpt":"\u00a0 El Tupolev Tu-114 Rossiya hacia 1960. \u00a0 La sociedad sin clases fue la primera en construir un avi\u00f3n con separaci\u00f3n de clases. A mediados de los a\u00f1os 50, muerto Stalin y en plena descongelaci\u00f3n del estalinismo, la Uni\u00f3n Sovi\u00e9tica se sinti\u00f3 dispuesta para demostrar al mundo los avances del\u2026","rel":"","context":"En \u00ab1960\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/07\/tupolevtu1141960.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/14738"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=14738"}],"version-history":[{"count":0,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/14738\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/14739"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=14738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=14738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=14738"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=14738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}