{"id":14676,"date":"1929-10-07T17:55:53","date_gmt":"1929-10-07T17:55:53","guid":{"rendered":"https:\/\/aeropinakes.com\/wordpress\/?p=14676"},"modified":"2018-10-07T19:27:36","modified_gmt":"2018-10-07T17:27:36","slug":"un-avion-mundial-para-un-imperio-planetario","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1929\/10\/07\/un-avion-mundial-para-un-imperio-planetario\/","title":{"rendered":"Un avi\u00f3n mundial para un imperio planetario"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/10\/faireylongrangemonoplane1929.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14677 size-full\" src=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/10\/faireylongrangemonoplane1929.jpg\" alt=\"\" width=\"3156\" height=\"1029\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/10\/faireylongrangemonoplane1929.jpg 3156w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/10\/faireylongrangemonoplane1929-300x98.jpg 300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/10\/faireylongrangemonoplane1929-1024x334.jpg 1024w\" sizes=\"(max-width: 3156px) 100vw, 3156px\" \/><\/a><\/p>\n<h3><\/h3>\n<h3>El Fairey Long-Range Monoplane I en 1929.<\/h3>\n<p>La d\u00e9cada de 1920 fue la edad de oro de los r\u00e9cords a\u00e9reos, y el m\u00e1s sensacional de todos era el de distancia. Los aviadores se empaquetaban en sus estrechas cabinas y se preparaban para pasar muchas horas en el aire mientras mares y tierras se deslizaban bajo su aparato. Despu\u00e9s del extraordinario vuelo en solitario de Charles Lindberg en 1927, 36 horas y 1\/2 en el aire en el trayecto Nueva York &#8211; Par\u00eds, el r\u00e9cord de distancia se qued\u00f3 en casi 6.000 km, y en los diez a\u00f1os siguientes fue batido una y otra vez. Hab\u00eda muchos aviadores dispuestos a pasar a la historia, y no era dif\u00edcil encontrar financiaci\u00f3n. Los aviones eran por lo general modelos civiles o militares est\u00e1ndar capaces de cargar gran cantidad de combustible suplementario, como el Breguet 19 o el Junkers W.33. Las rutas depend\u00edan del pa\u00eds de origen de los aviadores, pero hab\u00eda imanes irresistibles, como el salto del Atl\u00e1ntico, norte o sur (el Pac\u00edfico estaba fuera de las posibilidades de la tecnolog\u00eda de la \u00e9poca). Una elecci\u00f3n obvia del trayecto era enlazar la madre patria con las colonias, como hizo la aviaci\u00f3n francesa con sus posesiones en el AEF (\u00c1frica Ecuatorial Francesa), aunque volar de una tirada de Par\u00eds a Indochina tuvo que esperar.<\/p>\n<p>Si bien la aviaci\u00f3n de r\u00e9cord era en general de iniciativa privada, el caso del Fairey Long-Range Monoplane es singular, pues fue uno de los poqu\u00edsimos aviones dise\u00f1ados especial y oficialmente para volar muy largas distancias. Surgi\u00f3 de una especificaci\u00f3n del Ministerio del Aire brit\u00e1nico de 1927 para un avi\u00f3n postal de muy gran autonom\u00eda. La firma Fairey asumi\u00f3 el encargo y fabric\u00f3 una m\u00e1quina muy aerodin\u00e1mica, con un ala enorme que serv\u00eda de dep\u00f3sito de combustible, capaz de albergar una tripulaci\u00f3n de dos personas en vuelos con una duraci\u00f3n m\u00e1xima estimada de unas 60 horas, suficiente para recorrer m\u00e1s de 8.000 km. El r\u00e9cord mundial de distancia rondaba por entonces esa cifra. El proyecto era completamente militar, a diferencia de la mayor\u00eda de vuelos de r\u00e9cord de su \u00e9poca y pertenec\u00eda a la RAF, en concreto a su\u00a0Long Range\u00a0Development\u00a0Unit (Unidad de Desarrollo de Vuelos de Larga Distancia). La aviaci\u00f3n de muy larga distancia ten\u00eda un inter\u00e9s muy especial para el imperio m\u00e1s grande que ha existido jam\u00e1s.<\/p>\n<p>El propio C.R. Fairey, fundador de la compa\u00f1\u00eda constructora de este singular avi\u00f3n, explic\u00f3 la \u00abacuciante necesidad\u00bb de m\u00e1quinas capaces de volar varios millares de millas, especialmente para el Imperio brit\u00e1nico, en una sesi\u00f3n de la\u00a0Royal Aeronautical Society celebrada en octubre de 1929. El orador resumi\u00f3 la autonom\u00eda normal de los aviones de la \u00e9poca: 400 millas para los cazas, 600 para bombarderos ligeros o 1.200 para transportes e (impl\u00edcitamente) bombarderos pesados \u2013seg\u00fan \u00e9l, todo lo que necesitaba un pa\u00eds para estar completamente protegido del ataque de otros era una franja de oc\u00e9ano de 600 millas de anchura\u2013.<\/p>\n<p>Yendo al grano, C. R. Fairey estim\u00f3 en 2.000 millas la autonom\u00eda necesaria para los aviones de servicio colonial. Pocos aviones de la RAF o Imperial Airways la pose\u00edan en aquella \u00e9poca. El constructor de aviones ofreci\u00f3 una interesante visi\u00f3n del mundo desde el punto de vista de Londres: \u00abEl punto m\u00e1s cercano a Inglaterra que es territorio brit\u00e1nico es Malta, a 1.300 millas de distancia. Otro salto de 1.100 millas lleva al avi\u00f3n a la zona del canal de Suez&#8230; desde donde distancias de entre 1.000 y 1.350 millas nos dejan en la India. Con una m\u00e1quina de 2.000 millas de autonom\u00eda, el correo de la India se podr\u00eda llevar en tres saltos: Londres &#8211; Malta &#8211; Bagdad &#8211; Karachi, con un tiempo total de alrededor de 60 horas\u00bb (1).<\/p>\n<p>El 24 de abril por la ma\u00f1ana el Fairey Long-Range Monoplane despeg\u00f3 del aer\u00f3dromo de Cranwell, a unos 200 km al norte de Londres, uno de los de pista m\u00e1s larga de la RAF. El avi\u00f3n iba tan pesadamente cargado de gasolina que necesit\u00f3 algo m\u00e1s de un kil\u00f3metro para levantar el vuelo. Pas\u00f3 sobre Estambul y a partir de ah\u00ed entr\u00f3 en territorio imperial, pasando sobre Bagdad y sobre Karachi. El objetivo era Bangalore, cuna de la aviaci\u00f3n india, pero vientos desfavorables aconsejaron regresar a Karachi, donde aterrizaron cuando pasaba la hora 50 de vuelo. No se bati\u00f3 el r\u00e9cord mundial de distancia, pero lo importante era la primera conexi\u00f3n directa entre la metr\u00f3poli y la joya de la corona del Imperio, la inmensa y diversa India. Aquello abr\u00eda interesantes posibilidades de control a\u00e9reo colonial de larga distancia. Algunos meses despu\u00e9s, el mismo avi\u00f3n y la misma tripulaci\u00f3n intentaron hacer la otra gran ruta imperial, Londres -Ciudad del Cabo. El aparato se estrell\u00f3 en T\u00fanez por el mal tiempo. Un a\u00f1o despu\u00e9s una versi\u00f3n remozada del Fairey Long-Range Monoplane bati\u00f3 el r\u00e9cord mundial de distancia entre Cranwell y Walvis Bay, entonces en el \u00c1frica del Sudoeste bajo mandato sudafricano y actualmente en Namibia.<\/p>\n<p>1- Flight, 18 de octubre de 1929.<\/p>\n<p>&nbsp;<\/p>\n<p>[codepeople-post-map]<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; El Fairey Long-Range Monoplane I en 1929. La d\u00e9cada de 1920 fue la edad de oro de los r\u00e9cords a\u00e9reos, y el m\u00e1s sensacional &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":14677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":[]},"categories":[709,572,3066,93],"tags":[873],"Asuntos":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/10\/faireylongrangemonoplane1929.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-3OI","jetpack-related-posts":[{"id":1191,"url":"https:\/\/aeropinakes.com\/wordpress\/1931\/09\/01\/long-distance-observation-monoplane\/","url_meta":{"origin":14676,"position":0},"title":"Long-Distance Observation Monoplane","date":"1931","format":false,"excerpt":"Potez 37R2 Military Airplane. A Two-Place Long-Distance Observation Monoplane Aircraft Circulars - National Advisory Committee for Aeronautics - n\u00ba 152 Washington, September, 1931 Retrieved in Internet Archive","rel":"","context":"En \u00ab1931\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/04\/1931potez37naca.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":15476,"url":"https:\/\/aeropinakes.com\/wordpress\/2013\/12\/17\/el-truco-del-generalisimo\/","url_meta":{"origin":14676,"position":1},"title":"El truco del General\u00edsimo","date":"2013","format":false,"excerpt":"En enero de 2013 la Audiencia de Barcelona admiti\u00f3 la demanda de la asociaci\u00f3n Altraitalia (Otra Italia) y dos particulares contra 22 aviadores de la Regia Aeronautica (Aviaci\u00f3n Real) que participaron en los bombardeos de Barcelona de marzo de 1938, que mataron a cientos de personas e hirieron a millares.\u2026","rel":"","context":"En \u00ab1938\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/04\/aviatoridifranco.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":12050,"url":"https:\/\/aeropinakes.com\/wordpress\/1947\/06\/02\/nuestros-aviadores-aseguran-el-prestigio-nacional-y-pacifican-tierras-lejanas\/","url_meta":{"origin":14676,"position":2},"title":"Nuestros aviadores aseguran el prestigio nacional y pacifican tierras lejanas","date":"1947","format":false,"excerpt":"En vista de lo que ocurri\u00f3 siete a\u00f1os despu\u00e9s, en Dien Bien Phu, la leyenda de esta portada de D\u00e9collage resulta siniestramente premonitoria: \"Nuestros aviadores luchan para salvaguardar nuestro prestigio a los ojos del mundo y asegurar la pacificaci\u00f3n de esas tierras lejanas\". Por aquellas fechas, la aviaci\u00f3n francesa en\u2026","rel":"","context":"En \u00ab1947\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/04\/indochine.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8197,"url":"https:\/\/aeropinakes.com\/wordpress\/1937\/08\/10\/la-ruta-de-stalin\/","url_meta":{"origin":14676,"position":3},"title":"La ruta de Stalin","date":"1937","format":false,"excerpt":"\u00a0 Tupolev ANT-25 \"Ruta de Stalin\" \u00a0 En 1937 la aviaci\u00f3n sovi\u00e9tica se coloc\u00f3 a la par de las del resto del mundo gracias a dos vuelos sensacionales entre Europa y Am\u00e9rica por la ruta polar. Utilizando un ANT.25 de un solo motor dise\u00f1ado por A.N. Tupolev, un enorme monoplano\u2026","rel":"","context":"En \u00ab1937\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/08\/tupolevant2519373d.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8708,"url":"https:\/\/aeropinakes.com\/wordpress\/1958\/09\/15\/el-simbolo-aereo-del-franquismo\/","url_meta":{"origin":14676,"position":4},"title":"El s\u00edmbolo a\u00e9reo del franquismo","date":"1958","format":false,"excerpt":"El CASA 352 (Junkers Ju-52) que se puede ver en el Museo del Aire.\u00a0El Ju-52 fue fabricado despu\u00e9s de la guerra civil en Espa\u00f1a, como CASA 352. Durante muchos a\u00f1os fue el principal avi\u00f3n de transporte militar. \u00a0 En Ifni, noviembre de 1957, el ej\u00e9rcito espa\u00f1ol se encontr\u00f3 con \u201celementos\u2026","rel":"","context":"En \u00ab1958\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/09\/CASA352Ju521978.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7113,"url":"https:\/\/aeropinakes.com\/wordpress\/1919\/10\/02\/un-avro-504-para-el-diario-abc\/","url_meta":{"origin":14676,"position":5},"title":"Un Avro 504 para el diario ABC","date":"1919","format":false,"excerpt":"\u00a0 Un Avro 504 decorado especialmente para el servicio de transporte de peri\u00f3dicos. En el otro lado del fuselaje llevaba pintadas las letras capitales de \u201cBlanco y Negro\u201d. \u00a0 El 2 de octubre de 1919, parte de la tirada del diario mon\u00e1rquico ABC fue cargada en un Avro 504 que\u2026","rel":"","context":"En \u00ab1919\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/02\/avro504abc1919.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/14676"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=14676"}],"version-history":[{"count":0,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/14676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/14677"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=14676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=14676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=14676"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=14676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}