{"id":14391,"date":"1980-09-12T19:51:44","date_gmt":"1980-09-12T17:51:44","guid":{"rendered":"https:\/\/aeropinakes.com\/wordpress\/?post_type=reader&#038;p=14391"},"modified":"2019-12-13T19:19:40","modified_gmt":"2019-12-13T18:19:40","slug":"anciana-mineria","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1980\/09\/12\/anciana-mineria\/","title":{"rendered":"Anciana miner\u00eda"},"content":{"rendered":"<h4><a href=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/09\/portman.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14393 size-full\" src=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/09\/portman.jpg\" alt=\"\" width=\"720\" height=\"654\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/09\/portman.jpg 720w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/09\/portman-300x273.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/h4>\n<h4>El vertido de Portm\u00e1n tal como apareci\u00f3 en la secci\u00f3n \u00abEl ecologista furioso\u00bb de la revista El Ecologista &#8211; A\u00f1o 2 N\u00famero 4, febrero de 1980. (<a href=\"http:\/\/prensahistorica.mcu.es\/\">Biblioteca Virtual de Prensa Hist\u00f3rica<\/a>)<\/h4>\n<p>Los programas de Respiro Familiar son a la desesperada. La empresa SARquavitae los anuncia as\u00ed: \u201cDate un respiro. Nosotros lo cuidamos.\u201d Y pone ejemplos de cu\u00e1ndo viene bien un Respiro Familiar, por ejemplo si te vas de viaje y no quieres dejarlo solo en casa, o si te van a operar en un hospital. Pero tambi\u00e9n puede ocurrir que necesites \u201cun descanso en su cuidado diario\u201d o lo peor: \u201cSi la convivencia con tu familiar se hace dif\u00edcil y necesitas unos d\u00edas para ti\u201d. El Complejo Residencial y Sociosanitario de Mayores \u201cLa Miner\u00eda\u201d de Felechosa (Aller) tambi\u00e9n tiene programa de Respiro Familiar, que le viene muy bien para enjugar las p\u00e9rdidas de la instalaci\u00f3n.<\/p>\n<p>La residencia de ancianos es un edificio de acero y cristal con el aspecto de ser la sede de una tecnol\u00f3gica de post\u00edn en Silicon Valley. Tiene 300 plazas, pero apenas ha conseguido ocupar la tercera parte. Fue y es la joya de la corona del Montep\u00edo y Mutualidad de la Miner\u00eda Asturiana (MMMA), una organizaci\u00f3n de socorros mutuos (as\u00ed se dec\u00eda hace tiempo) que ha recibido cuantioso parn\u00e9 de los llamados Fondos Mineros, much\u00edsimo dinero del Estado que viajaba a Asturias para resta\u00f1ar las heridas del declive y cierre de la miner\u00eda del carb\u00f3n. Desgraciadamente alg\u00fan dinero no lleg\u00f3 a su destino y termin\u00f3 donde no deb\u00eda, en dinero negro o en chal\u00e9s pretenciosos con toda la parafernalia de la cutre corrupci\u00f3n a la espa\u00f1ola, es decir, todo-terrenos de lujo, parques de varias hect\u00e1reas, escopetas de caza damasquinadas, rehalas de perros de caza, etc.<\/p>\n<p>El asilo de ancianos de La Felechosa es conocido popularmente como el Macro-geri\u00e1trico. Las tarifas en febrero de 2016 iban de algo m\u00e1s de 1.600 \u20ac al mes en habitaci\u00f3n individual a 1.100 \u20ac en habitaci\u00f3n conjunta, para c\u00f3nyuges, parejas de hecho o parientes consangu\u00edneos. Esto para No Dependientes, los Dependientes pagan m\u00e1s. El Respiro Familiar se puede conseguir desde 55,20 euros al d\u00eda, con pensi\u00f3n completa. Tambi\u00e9n se pueden contratar estancias de fin de semana e incluso por horas, algo que se deber\u00eda llamar \u201cpeque\u00f1o suspiro de alivio familiar\u201d. El centro cuenta con un spa, es decir, un centro hidroter\u00e1pico para tomar las aguas.<\/p>\n<p>Una vez colocado el abuelo en la residencia, el resto de la familia piensa en d\u00f3nde ir de vacaciones y elige el Complejo Residencial La Miner\u00eda en Los Alc\u00e1zares (Murcia), tambi\u00e9n propiedad del MMMA. A diferencia de la residencia de ancianos, que dan la misma guerra en cualquier \u00e9poca del a\u00f1o y cuestan lo mismo en invierno que en verano, aqu\u00ed las tarifas van de 350 \u20ac de octubre a marzo a 1.102 \u20ac en julio y agosto. No se entiende que sea m\u00e1s barato el invierno que el verano teniendo en cuenta que el Residencial est\u00e1 en la orilla del Mar Menor, en el que la temperatura del agua puede alcanzar f\u00e1cilmente los 27 \u00baC en agosto, torradera que se dulcifica mucho en enero. Debe ser como en el viejo chiste anticomunista que anunciaba un primer premio de una semana de estancia en un balneario del Partido y un segundo premio con dos semanas de estancia. Todos los a\u00f1os por Santa B\u00e1rbara se celebra una fiesta minera que re\u00fane a la comunidad asturiana de Murcia, que desfilan vestidos con trajes t\u00edpicos del Principado y de mineros por las calles de Los Alc\u00e1zares.<\/p>\n<p>La cercana y murciana poblaci\u00f3n de La Uni\u00f3n, 1868, es un producto de la Gloriosa Revoluci\u00f3n que destron\u00f3 a Isabel II, cuando Prim naveg\u00f3 desde C\u00e1diz a Barcelona haciendo propaganda subversiva. Fue la uni\u00f3n de tres municipios, El Garbanzal, Herrer\u00edas y Portm\u00e1n. Tiene un centro urbano con algunos edificios modernistas, recuerdo de cuando era un Eldorado minero, productor de plomo, plata y otros productos de mucho valor. Tras un pico de producci\u00f3n durante la Gran Guerra, en la que se usaron billones de balas de plomo, hacia 1925 perdi\u00f3 dos tercios de su poblaci\u00f3n, que pas\u00f3 de 30.000 a 10.000, a medida que las minas se hac\u00edan poco rentables (es decir, se agotaban los yacimientos m\u00e1s baratos de extraer) e iban cerrando.<\/p>\n<p>Hubo un renacimiento minero entre la d\u00e9cada de 1950 y la de 1980, de la mano de la Soci\u00e9t\u00e9 Mini\u00e8re et M\u00e9tallurgique de Pe\u00f1arroya (SMMP), fundada en 1881 (de Pe\u00f1arroya-Pueblonuevo, provincia de C\u00f3rdoba). La SMMP ten\u00eda m\u00e1quinas mucho m\u00e1s potentes que las que ten\u00edan sus empresas antecesoras, y pudo arrancar y triturar cantidades prodigiosas de mineral. El problema es que eso dej\u00f3 muchos millones de metros c\u00fabicos de minerales exprimidos, por as\u00ed decir. A alguien se le ocurri\u00f3 tirarlos a la bah\u00eda de Portm\u00e1n, el Portus magnus romano, un peque\u00f1o pueblo pesquero. Lo que ocurri\u00f3 se puede ver comparando el mapa topogr\u00e1fico nacional 1:50.000 n\u00famero 978 (Llano del Beal) publicado en 1935 con la \u00faltima edici\u00f3n de la hoja. Ambas se pueden descargar gratuitamente en ign.es. A la izquierda del mapa se puede ver como desaparece la bah\u00eda de Portm\u00e1n y a la derecha como aparece la ciudad lineal de la Manga del Mar Menor. La miner\u00eda contin\u00faa en La Uni\u00f3n en forma cultural, con su famoso Festival de cante de las minas y la procesi\u00f3n del Cristo de los mineros en Semana Santa, donde la imagen desfila alumbrada por l\u00e1mparas de acetileno.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El vertido de Portm\u00e1n tal como apareci\u00f3 en la secci\u00f3n \u00abEl ecologista furioso\u00bb de la revista El Ecologista &#8211; A\u00f1o 2 N\u00famero 4, febrero de &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":14393,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":[]},"categories":[830,2187,2193],"tags":[],"Asuntos":[2591,2573],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/09\/portman.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-3K7","jetpack-related-posts":[{"id":9904,"url":"https:\/\/aeropinakes.com\/wordpress\/1936\/04\/04\/rana-dragon-y-rhodesia\/","url_meta":{"origin":14391,"position":0},"title":"RANA, Dragon y Rhodesia","date":"1936","format":false,"excerpt":"\u00a0 Un de Havilland Dragon Rapide de RANA (Rhodesian and Nyasaland Airways) en la segunda mitad de la d\u00e9cada de 1930.\u00a0 \u00a0 Hacia\u00a01935\u00a0Rhodesia del Sur (actual Zimbabue) era una colonia muy prometedora, con una potente miner\u00eda y una no desde\u00f1able agricultura comercial. Era el primer productor mundial de cromo, que\u2026","rel":"","context":"En \u00ab1936\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1936\/04\/dehavillanddragonrapideRANA1936.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14295,"url":"https:\/\/aeropinakes.com\/wordpress\/1966\/09\/08\/tierras-de-cosechadoras\/","url_meta":{"origin":14391,"position":1},"title":"Tierras de cosechadoras","date":"1966","format":false,"excerpt":"\u00a0 7. Andaluc\u00eda y Castilla y Le\u00f3n Los gallegos ennegrecidos por el sol que segaban las cosechas de Castilla fueron sustituidos por cosechadoras John Deere o Claas a partir de la d\u00e9cada de 1960. Las nuevas m\u00e1quinas pod\u00edan procesar una hect\u00e1rea a velocidad del rayo, guardando el grano en un\u2026","rel":"","context":"En \u00ab1966\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/09\/cosechadora.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7796,"url":"https:\/\/aeropinakes.com\/wordpress\/1980\/06\/26\/el-arma-de-destruccion-masiva-de-la-fa-iraqui\/","url_meta":{"origin":14391,"position":2},"title":"El arma de destrucci\u00f3n masiva de la FA iraqu\u00ed","date":"1980","format":false,"excerpt":"\u00a0 Tupolev Tu-22 de la FA iraqu\u00ed (hacia 1980). \u00a0 Con sus m\u00e1s de 40 metros de longitud\u00a0y\u00a0m\u00e1s de 90 toneladas de peso, el bombardero supers\u00f3nico Tu-22 era con mucho el avi\u00f3n m\u00e1s impresionante que hab\u00eda formado parte de la fuerza a\u00e9rea iraqu\u00ed. Se compraron algo m\u00e1s de una docena\u2026","rel":"","context":"En \u00ab1980\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/tupolevtu22fairaqui1980.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9791,"url":"https:\/\/aeropinakes.com\/wordpress\/1936\/03\/21\/aviones-mineros-en-nueva-guinea\/","url_meta":{"origin":14391,"position":3},"title":"Aviones mineros en Nueva Guinea","date":"1936","format":false,"excerpt":"\u00a0 Un Ford Trimotor de Guinea Airways en Nueva Guinea, a mediados de la d\u00e9cada de 1930. \u00a0 La miner\u00eda de oro comenz\u00f3 en Pap\u00faa Nueva Guinea (bajo administraci\u00f3n australiana hasta 1975) hacia 1926 en Wau y Bulolo, al este de la gran isla, y sus promotores se debieron enfrentar\u2026","rel":"","context":"En \u00ab1936\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/03\/fordtrimotorinuevaguinea1936.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":13911,"url":"https:\/\/aeropinakes.com\/wordpress\/1956\/07\/21\/la-ruta-aerea-de-empresa-de-los-nativos-del-tropico\/","url_meta":{"origin":14391,"position":4},"title":"La ruta a\u00e9rea de empresa de los \u00abNativos del Tr\u00f3pico\u00bb","date":"1956","format":false,"excerpt":"Un DC-3 de Wenela (Witwatersrand Native Labour Association) a mediados de la d\u00e9cada de 1950. Wenela Air Service fue la aerol\u00ednea de la Witwatersrand Native Labour Association (WNLA), dedicada a proporcionar trabajadores para la miner\u00eda sudafricana. El transporte a\u00e9reo de los llamados \"Nativos del Tr\u00f3pico\" (Tropical Natives) (1) procedentes de\u2026","rel":"","context":"En \u00ab1960\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/07\/douglasdc3wenela1954.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3748,"url":"https:\/\/aeropinakes.com\/wordpress\/1989\/02\/26\/hispania-y-los-apuros-de-charter\/","url_meta":{"origin":14391,"position":5},"title":"Hispania y los apuros de ch\u00e1rter","date":"1989","format":false,"excerpt":"\u00a0 Un Boeing 737-200 de Hispania a mediados de la d\u00e9cada de 1980. \u00a0 Hispania fue otra de las compa\u00f1\u00edas ch\u00e1rter creadas para trabajar en el f\u00e9rtil campo de los flujos tur\u00edsticos desde Europa central y occidental hacia las costas del Mediterr\u00e1neo. Estaba basada en Mallorca, como Spantax, y la\u2026","rel":"","context":"En \u00ab1989\u00bb","img":{"alt_text":"boeing737hispania1987","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/02\/boeing737hispania1987.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/14391"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=14391"}],"version-history":[{"count":1,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/14391\/revisions"}],"predecessor-version":[{"id":17092,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/14391\/revisions\/17092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/14393"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=14391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=14391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=14391"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=14391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}