{"id":13598,"date":"1900-06-28T19:15:03","date_gmt":"1900-06-28T19:15:03","guid":{"rendered":"https:\/\/aeropinakes.com\/wordpress\/?post_type=reader&#038;p=13598"},"modified":"2019-12-13T18:24:32","modified_gmt":"2019-12-13T17:24:32","slug":"la-forja-del-connacional","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1900\/06\/28\/la-forja-del-connacional\/","title":{"rendered":"La forja del connacional"},"content":{"rendered":"<h4>\n<a href=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/Vive_la_France.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13599 size-full\" src=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/Vive_la_France.jpg\" alt=\"\" width=\"1372\" height=\"871\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/Vive_la_France.jpg 1372w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/Vive_la_France-300x190.jpg 300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/Vive_la_France-1024x650.jpg 1024w\" sizes=\"(max-width: 1372px) 100vw, 1372px\" \/><\/a>Una tarjeta postal muestra unos ni\u00f1os provistos de dos s\u00edmbolos nacionales importantes, la bandera y el gorro militar. Impresa en Alsacia en 1919. Gaspard: Vive la France! (1919). Tarjeta postal. M. Tournier Editeur (Mulhouse) &#8211; <strong><a href=\"https:\/\/gallica.bnf.fr\/\">Gallica\u00a0<\/a><\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p>Los ferrocarriles fueron importantes. Gracias a una imaginativa aplicaci\u00f3n de la m\u00e1quina de vapor al transporte, para lo que hubo que hacerla m\u00e1s compacta, manejable y capaz de soportar el traqueteo, se pudo contar por primer vez con un canal de transporte terrestre de alta velocidad y muy alta capacidad, en t\u00e9rminos de enviar toneladas de mercanc\u00edas o miles de pasajeros de un lado a otro. Al mismo tiempo que las redes de ferrocarriles cambiaban profundamente los ecosistemas de las regiones que surcaban, un tipo de tecnolog\u00eda paralela cre\u00f3 el estado naci\u00f3n compacto tal y como lo conocemos.<\/p>\n<p>Un elemento fundamental en el proceso fue la consolidaci\u00f3n de una serie de artefactos, principalmente el estado, la naci\u00f3n, el pueblo, la raza, el territorio y el idioma, en una sola unidad, que se pod\u00eda definir con una sola palabra, con una marca inequ\u00edvoca. Hubo que trabajar muy duro para conseguirlo, pues todo estaba por hacer en la Europa de mediados del siglo XIX. Definir con claridad un estado sobre un territorio perfectamente delimitado era la parte m\u00e1s f\u00e1cil. Innumerables disputas fronterizas se resolvieron en buena forma, tras mucho trabajo diplom\u00e1tico y topogr\u00e1fico, con una precisa delimitaci\u00f3n de la l\u00ednea imaginaria de la frontera. Sirva de ejemplo el Arreglo de L\u00edmites firmado en Bayona el 11 de julio de 1868 entre Espa\u00f1a y Francia, que culmin\u00f3 m\u00e1s de diez a\u00f1os de trabajo e indic\u00f3 sin posibilidad de confusi\u00f3n si tal o cual piedra de la divisoria pirenaica deb\u00eda considerarse legalmente como espa\u00f1ola y francesa. Esta es una frontera muy resistente, que en realidad no ha cambiado desde finales del siglo XVII, pero las llanuras europeas han conocido fronteras muy fluctuantes, el gran ejemplo aqu\u00ed es Alemania.<\/p>\n<p>Sobre este territorio tan exactamente delimitado se superpuso la naci\u00f3n y el pueblo, que ven\u00edan en el mismo paquete. En ocasiones se le a\u00f1adi\u00f3 otro atributo, la raza. Todo lo anterior se pod\u00eda hacer mediante declaraciones m\u00e1s o menos altisonantes y firmando documentos debidamente legalizados, pero la cuesti\u00f3n del idioma y las costumbres eran huesos m\u00e1s dif\u00edciles de roer. El idioma en particular dio mucho trabajo. Hubo que inventar el idioma est\u00e1ndar del estado naci\u00f3n, que cada pa\u00eds sac\u00f3 de alg\u00fan dep\u00f3sito geogr\u00e1fico o hist\u00f3rico de pureza imaginaria, por ejemplo el griego cl\u00e1sico (katarevousa) para la nueva Grecia o el castellano de Valladolid para la nueva Espa\u00f1a. Italia utiliz\u00f3 el toscano, Francia una de las lenguas de o\u00edl. Pero eso no era todo. Hab\u00eda que definir con bastante detalle las caracter\u00edsticas culturales propias de cada estado naci\u00f3n, es decir, qu\u00e9 deb\u00eda saber un buen alem\u00e1n o un buen espa\u00f1ol para considerarse como tal. Hab\u00eda cosas obvias (el idioma est\u00e1ndar, los s\u00edmbolos nacionales) y otras menos evidentes, como los deberes con respecto a la Patria. La red de escuelas y el Ej\u00e9rcito se pusieron manos a la obra y consiguieron moldear a millones, de manera que a comienzos del siglo XX el proceso ya estaba casi completado. Fue entonces cuando se di\u00f3 la alarma ante la desaparici\u00f3n de las culturas regionales \u2013que tambi\u00e9n formaban parte del cuerpo de la naci\u00f3n\u2013 y se plante\u00f3 su conservaci\u00f3n como folklore.<\/p>\n<p>El estado naci\u00f3n ya estaba listo: compacto, indestructible, eterno, con un origen lejan\u00edsimo y un futuro ilimitado. Hoy en d\u00eda somos poco conscientes del poder omn\u00edmodo de estas categor\u00edas mentales, a pesar de que organizan casi m\u00e1s que cualquier otra nuestro pensamiento. Esta categorizaci\u00f3n se pod\u00eda hacer de muchas maneras, desde la afirmaci\u00f3n altiva \u201cRule, Britania\u201d, \u201cla France eternelle\u201d o \u201cDem Deutschen Volke\u201d hasta la definici\u00f3n medio triste medio jocosa de un conocido pol\u00edtico de la Restauraci\u00f3n \u201ces espa\u00f1ol aquel que no puede ser otra cosa\u201d. Era el estado naci\u00f3n org\u00e1nico, un microcosmos completo capaz de funcionar por s\u00ed mismo, de abarcar el mundo entero si fuera necesario. El estado naci\u00f3n asigna a cada uno de sus miembros (en el sentido de \u201ccomuni\u00f3n\u201d) un valor no buscado, eterno y garantizado contra toda merma. Por lo tanto, escapa a las fortunas del azar o la habilidad, o a la selecci\u00f3n natural, a diferencia de la fortuna personal o al valor de las empresas. Como dijo De Gaulle, puede perder una batalla, pero no puede perder la guerra.<\/p>\n<p>La tarea \u00edmproba de consolidar esta idea en las mentes de los millones de ciudadanos de los estados se llev\u00f3 a cabo utilizando todos los recursos de la comunicaci\u00f3n: fue preciso crear logotipos, lemas, sl\u00f3ganes, historias deformadas o simplemente inventadas. La escolarizaci\u00f3n obligatoria cumpli\u00f3 un papel fundamental, pero tambi\u00e9n las canciones populares, los chistes, la gastronom\u00eda y el tabaco. La tarea se llev\u00f3 a cabo con tanto \u00e9xito que a\u00fan hoy los supermercados de Hondarribia se diferencian de los de Hendaia en que unos exhiben latas de cocido y los otros de cassoulet, y unos venden Ducados y los otros Gauloises. Es la verdadera esencia de las dos naciones, la espa\u00f1ola y la francesa, que llega hasta sus respectivas y hoy por hoy inoperativas fronteras, como llega hasta el \u00faltimo rinc\u00f3n de su territorio. En esta perspectiva, la presencia del idioma espa\u00f1ol o el franc\u00e9s o de la Guardia Civil o la PAF (Police de l\u2019Air et des Fonti\u00e8res) resultan aspectos secundarios.<\/p>\n<p>Los nuevos estados naci\u00f3n ya no pod\u00edan tener la manga ancha de anta\u00f1o. Ahora era necesaria una identificaci\u00f3n inequ\u00edvoca de cada connacional para uso interno, una marca de reconocimiento a ser posible con un n\u00famero correlativo. La tecnolog\u00eda necesaria fue proporcionada por los nuevos sistemas de ficheros y por la fotograf\u00eda. La fotograf\u00eda permit\u00eda la identificaci\u00f3n de manera mucho m\u00e1s completa que el viejo sistema de se\u00f1as personales. Fue utilizada por primera vez para la identificaci\u00f3n de personas en sanatorios psiqui\u00e1tricos ingleses hacia 1850 (1). No obstante, el sistema anglosaj\u00f3n no adopt\u00f3 un sistema expl\u00edcito de documento nacional de identidad, cosa que s\u00ed hicieron muchos estados, como el espa\u00f1ol. El DNI tiene su origen en la necesidad de identificar a las personas por m\u00e9todos fotogr\u00e1ficos en un pa\u00eds atestado de delincuentes potenciales. La identificaci\u00f3n fotogr\u00e1fica se utiliz\u00f3 por primera vez en la represi\u00f3n del bandolerismo andaluz, a finales del siglo XIX, y despu\u00e9s se extendi\u00f3 a toda la poblaci\u00f3n espa\u00f1ola, incluyendo huellas dactilares y la exhibici\u00f3n de la oreja derecha, dos herencias del bertillonaje (el m\u00e9todo que usaba la polic\u00eda hacia 1900 para catalogar las se\u00f1as personales de los delincuentes, antes del empleo de las huellas digitales) y de los m\u00e9todos de Lombroso, que pretend\u00edan identificar al criminal antes de que cometiera un delito analizando los rasgos de su rostro.<\/p>\n<p>El documento nacional de identidad era para consumo interno, y fue necesario hacer una versi\u00f3n especial, m\u00e1s solemne todav\u00eda, para que el connacional pudiera identificarse si quer\u00eda viajar al resto del mundo. El pasaporte moderno es la gran etiqueta de calidad humana. Hay listas semioficiales de calidad de pasaportes, medida en n\u00famero de pa\u00edses que dejan pasar libremente a su portador sin hacer preguntas (es decir, exigirle visado). El \u00edndice de Restricciones de Visa Henley &amp; Partners 2017 establece como los mejores pasaportes del mundo los de Alemania y Singapur (159 pa\u00edses de libre acceso) y como el peor el de Afganist\u00e1n (s\u00f3lo 22 pa\u00edses no hacen preguntas cuando un afgano se acerca sus fronteras). Cuando un inmigrante ilegal compra u obtiene por cualquier medio ilegal un pasaporte de calidad, se produce el mismo proceso que cuando oscuras f\u00e1bricas del tercer mundo producen versiones falsificadas de relojes de Cartier o de zapatillas Adidas. Los pasaportes tradicionales (as\u00ed en plural) eran muy distintos, eran salvoconductos que se conced\u00edan a los caballeros para que se pudieran mover a placer sobre cualquier territorio, y los hab\u00eda de diferentes calidades seg\u00fan si los firmaba el ministro, el gobernador o un simple alcalde.<\/p>\n<p>1- Naomi Rosenblum: Une Histoire Mondiale de la Photographie. \u00c9ditions Abbeville. Paris, 1992.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Una tarjeta postal muestra unos ni\u00f1os provistos de dos s\u00edmbolos nacionales importantes, la bandera y el gorro militar. Impresa en Alsacia en 1919. Gaspard: Vive &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":13599,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":[]},"categories":[3361,63],"tags":[],"Asuntos":[2478,2602],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/Vive_la_France.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-3xk","jetpack-related-posts":[{"id":2684,"url":"https:\/\/aeropinakes.com\/wordpress\/1926\/01\/06\/una-red-pionera-de-transporte-aereo-en-el-altiplano\/","url_meta":{"origin":13598,"position":0},"title":"Una red pionera de transporte a\u00e9reo en el altiplano","date":"1926","format":false,"excerpt":"\u00a0 Junkers F.13 \"Illimani\" del Lloyd A\u00e9reo Boliviano, a finales de la d\u00e9cada de 1920. \u00a0 Un pa\u00eds de m\u00e1s de un mill\u00f3n de kil\u00f3metros cuadrados de extensi\u00f3n y con pocas carreteras y ferrocarriles deber\u00eda ser un lugar prometedor para la aviaci\u00f3n de transporte, y as\u00ed sucede actualmente en Bolivia.\u2026","rel":"","context":"En \u00ab1926\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/01\/junkersf13lab1926.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8166,"url":"https:\/\/aeropinakes.com\/wordpress\/1978\/08\/09\/yakovlev-yak-42-disenado-para-el-trafico-interior-de-la-urss\/","url_meta":{"origin":13598,"position":1},"title":"Yakovlev Yak-42: dise\u00f1ado para el tr\u00e1fico interior de la URSS","date":"1978","format":false,"excerpt":"\u00a0 Tras treinta a\u00f1os de dedicaci\u00f3n a los aviones militares, la oficina de dise\u00f1o de A.S. Yakovlev comenz\u00f3 a trabajar en aviones de pasajeros en la d\u00e9cada de 1960. El Yak-40 vol\u00f3 en 1968 y el Yak-42, m\u00e1s grande y de mayor autonom\u00eda, diez a\u00f1os despu\u00e9s. Ambos modelos respond\u00edan a\u2026","rel":"","context":"En \u00ab1978\u00bb","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10929,"url":"https:\/\/aeropinakes.com\/wordpress\/1937\/06\/14\/los-tentaculos-del-pulpo\/","url_meta":{"origin":13598,"position":2},"title":"Los tent\u00e1culos del pulpo","date":"1937","format":false,"excerpt":"Gu\u00eda Michelin para Espa\u00f1a y Portugal para 1936. \u00a0 Si los obreros se comportan en las obras del ferrocarril como nuestros soldados en el frente, Madrid ser\u00e1 abastecido normalmente dentro de 40 d\u00edas \u00a1TODOS A LAS OBRAS DEL FERROCARRIL! Estampa, 19 de junio de 1937 \u00a0 El llamado algo pomposamente\u2026","rel":"","context":"En \u00ab1937\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1937\/06\/mapamichelin1936.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4845,"url":"https:\/\/aeropinakes.com\/wordpress\/1911\/09\/04\/roubaix-1911\/","url_meta":{"origin":13598,"position":3},"title":"Roubaix 1911","date":"1911","format":false,"excerpt":"Tarjeta postal recuerdo de las Fiestas A\u00e9reas de Roubaix (1911) Biblioth\u00e8que Num\u00e9rique de Roubaix\u00a0(v\u00eda Gallica) [codepeople-post-map cat=\"-1\"]","rel":"","context":"En \u00ab1911\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/roubaix1911.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4847,"url":"https:\/\/aeropinakes.com\/wordpress\/1952\/09\/04\/so-30-p-bretagne\/","url_meta":{"origin":13598,"position":4},"title":"SO 30 P Bretagne","date":"1952","format":false,"excerpt":"Una estupenda ilustraci\u00f3n del\u00a0SO 30 P Bretagne,\u00a0\u00a0obra de\u00a0Alain Gibergues, en una tarjeta postal fechada en 1952. Trouv\u00e9 dans: Aviation Commerciale \u2013 4\u00e8me partie Pierre Jarrige http:\/\/www.aviation-algerie.com","rel":"","context":"En \u00ab1952\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/09\/airalgerie3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2688,"url":"https:\/\/aeropinakes.com\/wordpress\/1919\/01\/06\/junkers-f-13-el-primer-avion-comercial-de-la-historia\/","url_meta":{"origin":13598,"position":5},"title":"Junkers F.13: el primer avi\u00f3n comercial de la historia","date":"1919","format":false,"excerpt":"\u00a0 Un Junkers F.13 yemen\u00ed en 1926, todav\u00eda con la matr\u00edcula alemana. \u00a0 Todo empez\u00f3 en 1915, \u00a0cuando el ingeniero Hugo Junkers present\u00f3 su primer modelo de avi\u00f3n, el J1, un monoplano completamente met\u00e1lico sin cables ni riostras por ninguna parte, solamente alas unidas s\u00f3lidamente a un fuselaje. En 1919\u2026","rel":"","context":"En \u00ab1919\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1919\/01\/junkersf13yemen1926.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/13598"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=13598"}],"version-history":[{"count":1,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/13598\/revisions"}],"predecessor-version":[{"id":16692,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/13598\/revisions\/16692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/13599"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=13598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=13598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=13598"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=13598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}