{"id":13499,"date":"1964-06-21T18:27:32","date_gmt":"1964-06-21T17:27:32","guid":{"rendered":"https:\/\/aeropinakes.com\/wordpress\/?post_type=material&#038;p=13499"},"modified":"2019-12-13T19:10:29","modified_gmt":"2019-12-13T18:10:29","slug":"la-ezpata-dantza-origen-del-lema-de-la-legion-espanola","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1964\/06\/21\/la-ezpata-dantza-origen-del-lema-de-la-legion-espanola\/","title":{"rendered":"La ezpata-dantza, origen del lema de la Legi\u00f3n espa\u00f1ola"},"content":{"rendered":"<p><a href=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/vizcaya1964004.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13500 size-full\" src=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/vizcaya1964004.jpg\" alt=\"\" width=\"1800\" height=\"1785\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/vizcaya1964004.jpg 1800w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/vizcaya1964004-150x150.jpg 150w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/vizcaya1964004-300x298.jpg 300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/vizcaya1964004-1024x1015.jpg 1024w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/vizcaya1964004-100x100.jpg 100w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/vizcaya1964004-50x50.jpg 50w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/p>\n<p>Un grupo de danzantes de lo que parece una versi\u00f3n de la ezpatadantza (danza de las espadas), foto (probablemente de la d\u00e9cada de 1930) publicada en el volumen dedicado a Vizacaya de la serie <em>Espa\u00f1a en paz<\/em> (1964). El franquismo abominaba del separatismo vasco, pero segu\u00eda considerando a la raza vasca, incluyendo Navarra, como la variedad humana de mejor calidad de la naci\u00f3n. Todo este asunto de las danzas varoniles y guerreras vascas parece ser que fue un invento de Sabino Arana, que la vio representar por primera vez en Durango en 1886 y la convirti\u00f3 en poco menos que la danza oficial del nacionalismo vasco, por su car\u00e1cter \u00abviril y majestuoso\u00bb (1). As\u00ed que en en 1932 se cre\u00f3 la<em>\u00a0Bizkaiko Ezpatadantzari Batza<\/em>, o Asociaci\u00f3n de Ezpatadantzaris de Vizcaya, y se crearon cientos de agrupaciones que a veces hac\u00edan grandes interpretaciones colectivas (la foto de arriba es probablemente de una de ellas). El franquismo enfoc\u00f3 el asunto como el compartimento provincial vizca\u00edno del rico acervo folkl\u00f3rico espa\u00f1ol, en teor\u00eda en manos de la Secci\u00f3n Femenina, el Frente de Juventudes y Educaci\u00f3n y Descanso, aunque en Vizcaya tambi\u00e9n hab\u00eda muchos grupos no oficiales. M\u00e1s curiosa es la relaci\u00f3n que se estableci\u00f3 entre la ezpata-dantza y el lema de la Legi\u00f3n espa\u00f1ola, \u00a1Viva la Muerte!, creada por don Dar\u00edo de Areitio en base a elucubraciones sobre el remoto origen de esta danza en las guerras de los vascones contra los romanos en Cantabria, interpret\u00e1ndola como un homenaje ritual a los guerreros muertos en combate (1).<\/p>\n<p>1- <a href=\"http:\/\/aunamendi.eusko-ikaskuntza.eus\/es\/ezpata-dantza\/ar-152129\/\">Au\u00f1amendi Eusko Entziklopedia, \u00abEzpata-dantza\u00bb<\/a><br \/>\n2- Vizcaya. Espa\u00f1a en Paz. Publicaciones espa\u00f1olas, Madrid, 1964.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Un grupo de danzantes de lo que parece una versi\u00f3n de la ezpatadantza (danza de las espadas), foto (probablemente de la d\u00e9cada de 1930) publicada &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":13500,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":[]},"categories":[814,3246],"tags":[],"Asuntos":[2671],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/vizcaya1964004.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-3vJ","jetpack-related-posts":[{"id":13434,"url":"https:\/\/aeropinakes.com\/wordpress\/1964\/06\/16\/normalizacion-folclorica-de-las-provincias-con-algun-gazapo\/","url_meta":{"origin":13499,"position":0},"title":"Normalizaci\u00f3n folcl\u00f3rica de las provincias, con alg\u00fan gazapo","date":"1964","format":false,"excerpt":"Una imagen del disco impreso de pl\u00e1stico incluido en el volumen \"Vizcaya\" de los editados, uno por provincia, para conmemorar los \"25 a\u00f1os de paz\" en 1964, el a\u00f1o cumbre del franquismo. Cada libro inclu\u00eda, adem\u00e1s de muchas fotograf\u00edas y gr\u00e1ficos, un disco con m\u00fasica popular de la provincia y\u2026","rel":"","context":"En \u00ab1964\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/06\/musicadevasconia.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":17541,"url":"https:\/\/aeropinakes.com\/wordpress\/1936\/05\/01\/el-combinado-astur-vasco\/","url_meta":{"origin":13499,"position":1},"title":"El combinado astur-vasco","date":"1936","format":false,"excerpt":"El Eco Patronal, mayo de 1936","rel":"","context":"En \u00ab1936\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/12\/altoshornosdevizcaya.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14591,"url":"https:\/\/aeropinakes.com\/wordpress\/2018\/09\/26\/el-limite-vasco-de-la-civilizacion\/","url_meta":{"origin":13499,"position":2},"title":"El l\u00edmite vasco de la civilizaci\u00f3n","date":"2018","format":false,"excerpt":"Foto: de Google Maps. Saliendo de Muskiz hacia el oeste se llega enseguida a un cartel verde con letras blancas que dice \u201cComunidad de Cantabria\u201d y debajo \u201cProvincia de Cantabria\u201d para que no haya dudas. El paisaje es el mismo y la autov\u00eda de cuatro carriles te deja en Castro\u2026","rel":"","context":"En \u00ab2018\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2018\/09\/cantabria.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8581,"url":"https:\/\/aeropinakes.com\/wordpress\/1937\/09\/03\/aviones-de-estonia-para-la-republica-de-euskadi\/","url_meta":{"origin":13499,"position":3},"title":"Aviones de Estonia para la rep\u00fablica de Euzkadi","date":"1937","format":false,"excerpt":"Un Potez 25 estonio adquirido por el Gobierno vasco en Asturias, verano de 1937. \u00a0 Tan desesperada era la necesidad de aviones en la zona republicana durante la guerra civil, que el gobierno vasco no dud\u00f3 en comprar al gobierno estonio ocho o diez vetustos Potez 25 excedentes de su\u2026","rel":"","context":"En \u00ab1937\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/09\/potez25gobiernovascoasturias1937.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":15460,"url":"https:\/\/aeropinakes.com\/wordpress\/1937\/08\/25\/el-pais-imposible-hegoalde\/","url_meta":{"origin":13499,"position":4},"title":"El pa\u00eds imposible: Hegoalde","date":"1937","format":false,"excerpt":"\"Pamplona, 9.11.1937. Se\u00f1oritas vestidas con el traje t\u00edpico de la regi\u00f3n de Navarra en el d\u00eda de la Misa celebrada en honor de las Brigadas de Navarra e imposici\u00f3n de la Cruz Laureada de San Fernando a la provincia.\" Reportaje fotogr\u00e1fico Delespro. Delegaci\u00f3n del Estado para Prensa y Propaganda. Biblioteca\u2026","rel":"","context":"En \u00ab1937\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/08\/mujerestrajetipiconavarra.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":10933,"url":"https:\/\/aeropinakes.com\/wordpress\/1937\/05\/04\/los-puentes-de-bilbao\/","url_meta":{"origin":13499,"position":5},"title":"Los puentes de Bilbao","date":"1937","format":false,"excerpt":"Estampa, 17 de abril de 1937. Biblioteca Nacional, Hemeroteca Digital (ver reportaje completo abajo) \u00a0 Al ser ocupada el d\u00eda 12 de mayo de 1937 la ermita de Santa Cruz de Rigoitia por la 5\u00aa Brigada de Navarra, un grito de asombro se escap\u00f3 de todas las gargantas. A una\u2026","rel":"","context":"En \u00ab1937\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1937\/05\/17-abril-1937estampainserto.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/13499"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=13499"}],"version-history":[{"count":1,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/13499\/revisions"}],"predecessor-version":[{"id":17333,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/13499\/revisions\/17333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/13500"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=13499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=13499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=13499"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=13499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}