{"id":12328,"date":"1939-12-31T18:14:31","date_gmt":"1939-12-31T18:14:31","guid":{"rendered":"https:\/\/aeropinakes.com\/wordpress\/?post_type=material&#038;p=12328"},"modified":"2019-12-09T19:28:31","modified_gmt":"2019-12-09T18:28:31","slug":"la-raza-superior-vista-por-ella-misma","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1939\/12\/31\/la-raza-superior-vista-por-ella-misma\/","title":{"rendered":"La raza superior, vista por ella misma"},"content":{"rendered":"<p><a href=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/12\/1939-may-alemania.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-12329 size-full\" src=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/12\/1939-may-alemania.jpg\" alt=\"\" width=\"801\" height=\"1203\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/12\/1939-may-alemania.jpg 801w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/12\/1939-may-alemania-200x300.jpg 200w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/12\/1939-may-alemania-682x1024.jpg 682w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/a>\u00abJoven campesina en el Burgo de Neuhaus\u00bb es el t\u00edtulo de esta ilustraci\u00f3n que consigue transmitir, sin cruces gamadas ni parafernalia nazi de ninguna clase, la imagen de la raza aria tal como era vista por la ideolog\u00eda nacional-socialista. Adem\u00e1s, tambi\u00e9n es una versi\u00f3n alemana de la costumbre de presentar bellas mujeres del pa\u00eds como reclamo tur\u00edstico. \u00abAlemania\u00bb era la revista tur\u00edstica oficial germana, publicada en varios idiomas. Tres meses despu\u00e9s de la publicaci\u00f3n de este n\u00famero, el turismo pr\u00e1cticamente despareci\u00f3 del continente europeo, al menos en su versi\u00f3n no militar.<\/p>\n<p>Alemania, mayo de 1939<br \/>\nHemeroteca Municipal de Madrid<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00abJoven campesina en el Burgo de Neuhaus\u00bb es el t\u00edtulo de esta ilustraci\u00f3n que consigue transmitir, sin cruces gamadas ni parafernalia nazi de ninguna clase, &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":12329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":[]},"categories":[661,526],"tags":[],"Asuntos":[2568,2648],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/12\/1939-may-alemania.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-3cQ","jetpack-related-posts":[{"id":1286,"url":"https:\/\/aeropinakes.com\/wordpress\/1939\/08\/13\/cultura-e-industria-del-bombardeo-aereo-en-alemania\/","url_meta":{"origin":12328,"position":0},"title":"Cultura e industria del bombardeo a\u00e9reo en Alemania","date":"1939","format":false,"excerpt":"Publicado en el Luftschutz Taschenkalender 1939 (Almanaque de bolsillo de la Defensa Antia\u00e9rea 1939), estos dos anuncios muestran sirenas de alarma Siemens y l\u00e1mparas de oscurecimiento Osram. Luftschutz, comp\u00e1rese con Schutz Engel (\u00c1ngel de la Guarda), era el nombre de\u00a0la enorme organizaci\u00f3n civil de defensa contra bombardeos alemana. \u00a0 Encontrado\u2026","rel":"","context":"En \u00ab1939\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/08\/alarma.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7721,"url":"https:\/\/aeropinakes.com\/wordpress\/1939\/06\/22\/el-primer-jet\/","url_meta":{"origin":12328,"position":1},"title":"El primer avi\u00f3n jet","date":"1939","format":false,"excerpt":"\u00a0 El Heinkel 178, el primer avi\u00f3n jet que vol\u00f3 en el mundo, en agosto de 1939, justo una semana antes de la invasi\u00f3n de Polonia por las fuerzas de la Alemania nazi. \u00a0 El motor \"jet\" resultaba muy prometedor para la aviaci\u00f3n, al utilizar el empuje limpio de un\u2026","rel":"","context":"En \u00ab1939\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/06\/heinkelhe1781939.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14911,"url":"https:\/\/aeropinakes.com\/wordpress\/1938\/12\/17\/alemania-1933-1945-la-biologia-en-el-poder\/","url_meta":{"origin":12328,"position":2},"title":"Alemania, 1933-1945: la biolog\u00eda en el poder","date":"1938","format":false,"excerpt":"\u00a0 Adolf Wissel: Kalenberg Bauernfamilie (1939). Museo de historia alemana de Berl\u00edn. En 1933 el NSDAP alcanzaba el poder en Alemania. Fue la primera vez que la Biolog\u00eda Racial (Rassenbiologie) determinaba de ra\u00edz la pol\u00edtica de un pa\u00eds, aunque algunos estados de los Estados Unidos y Suecia estuvieron cerca en\u2026","rel":"","context":"En \u00ab1938\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1938\/12\/familia.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11193,"url":"https:\/\/aeropinakes.com\/wordpress\/1939\/09\/28\/otros-seis-anos-de-guerra\/","url_meta":{"origin":12328,"position":3},"title":"Otros seis a\u00f1os de guerra","date":"1939","format":false,"excerpt":"\u00a0 \u201cEl Canciller de Alemania\u2026 ardientemente desea la paz para su naci\u00f3n, con la verticalidad de intenci\u00f3n que le caracteriza\u201d(1). Con este s\u00edmil postural recibi\u00f3 la prensa espa\u00f1ola la desconcertante noticia del pacto germano-sovi\u00e9tico de finales de agosto de 1939. No hac\u00eda cinco meses que hab\u00eda terminado la guerra de\u2026","rel":"","context":"En \u00ab1939\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1939\/09\/1942-07-27-laprensavig.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1173,"url":"https:\/\/aeropinakes.com\/wordpress\/1939\/04\/25\/junkers-ju-52-nacionalistas\/","url_meta":{"origin":12328,"position":4},"title":"Junkers Ju-52 nacionalistas","date":"1939","format":false,"excerpt":"Junkers JU-52 de la aviaci\u00f3n nacional pocos d\u00edas despu\u00e9s del fin de la guerra civil (25 de abril de 1939) Estanislao Abell\u00e1n Agius: Los Junkers Ju-52\/3m en Espa\u00f1a Aeroplano, n\u00ba 15, 1997 El Ju-52 era descendiente directo del revolucionario F-13 y como \u00e9l era todo met\u00e1lico, monoplano y resistente como\u2026","rel":"","context":"En \u00ab1939\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/04\/1939ju52.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":10936,"url":"https:\/\/aeropinakes.com\/wordpress\/1942\/08\/19\/la-guerra-de-los-800-000-aviones\/","url_meta":{"origin":12328,"position":5},"title":"La guerra de los 800.000 aviones","date":"1942","format":false,"excerpt":"789.673 aparatos es la cifra total de producci\u00f3n de aviones de cualquier tipo por parte de las principales potencias de la segunda guerra mundial: Estados Unidos, Gran Breta\u00f1a, URSS, Alemania y Jap\u00f3n (1). Sumando la producci\u00f3n de Francia, Italia y otras potencias menores se superar\u00edan holgadamente los 800.000 aparatos. En\u2026","rel":"","context":"En \u00ab1943\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1942\/08\/produccionavionessgm.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/12328"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=12328"}],"version-history":[{"count":1,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/12328\/revisions"}],"predecessor-version":[{"id":16427,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/12328\/revisions\/16427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/12329"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=12328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=12328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=12328"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=12328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}