{"id":12003,"date":"1941-05-26T17:34:24","date_gmt":"1941-05-26T16:34:24","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?post_type=material&#038;p=12003"},"modified":"2019-12-12T19:34:49","modified_gmt":"2019-12-12T18:34:49","slug":"comienzos-de-la-era-del-petroleo","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1941\/05\/26\/comienzos-de-la-era-del-petroleo\/","title":{"rendered":"Comienzos de la era del petr\u00f3leo"},"content":{"rendered":"<p><a href=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/11\/seleccusa-esp1941-nov027.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11980 size-full\" src=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/11\/seleccusa-esp1941-nov027.jpg\" alt=\"\" width=\"1300\" height=\"1921\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/11\/seleccusa-esp1941-nov027.jpg 1300w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/11\/seleccusa-esp1941-nov027-203x300.jpg 203w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/11\/seleccusa-esp1941-nov027-693x1024.jpg 693w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/11\/seleccusa-esp1941-nov027-406x600.jpg 406w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/><\/a><\/p>\n<p>Muy lejos todav\u00eda de las im\u00e1genes peyorativas del estilo de \u00abpatatas hechas con petr\u00f3leo\u00bb o de la lucha contra el calentamiento global derivado de la quema de combustibles f\u00f3siles, el petr\u00f3leo muestra su marcha ascendente imparable en un anuncio de 1941, cuando la petrolizaci\u00f3n de la agricultura apenas se estaba completando en Estados Unidos y en el resto del mundo se ve\u00eda todav\u00eda muy lejana. El anuncio usa un argumento que se repetir\u00eda mucho despu\u00e9s: el petr\u00f3leo como panacea universal (combustible, iluminaci\u00f3n, materia prima universal, fuente de medicinas, etc.)<\/p>\n<p>&nbsp;<\/p>\n<p>Selecciones del Reader&#8217;s Digest (USA, edici\u00f3n en espa\u00f1ol) noviembre de 1941<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Muy lejos todav\u00eda de las im\u00e1genes peyorativas del estilo de \u00abpatatas hechas con petr\u00f3leo\u00bb o de la lucha contra el calentamiento global derivado de la &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":11980,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":[]},"categories":[663],"tags":[],"Asuntos":[2551,2645],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/11\/seleccusa-esp1941-nov027.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-37B","jetpack-related-posts":[{"id":11926,"url":"https:\/\/aeropinakes.com\/wordpress\/1947\/11\/09\/cuando-el-petroleo-contribuia-a-la-felicidad-y-el-bienestar-de-la-humanidad\/","url_meta":{"origin":12003,"position":0},"title":"Cuando el petr\u00f3leo contribu\u00eda a la felicidad y el bienestar de la humanidad","date":"1947","format":false,"excerpt":"Justo medio siglo antes de la firma del protocolo de Kioto para luchar contra el cambio clim\u00e1tico y por ende reducir el consumo de combustibles f\u00f3siles, este anuncio de la Standard Oil de Brasil enfatiza las virtudes del petr\u00f3leo como panacea universal. Sele\u00e7oes do Reader's Digest (ed brasile\u00f1a) noviembre de\u2026","rel":"","context":"En \u00ab1947\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/11\/selec\u0327oesdoreadersdigestnov1947.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11961,"url":"https:\/\/aeropinakes.com\/wordpress\/1938\/11\/11\/la-campsa-republicana-promete-rios-de-petroleo\/","url_meta":{"origin":12003,"position":1},"title":"La CAMPSA republicana promete r\u00edos de petr\u00f3leo","date":"1938","format":false,"excerpt":"Un sugerente anuncio de CAMPSA publicado en la revista oficial de la aviaci\u00f3n republicana. El verano de 1936 CAMPSA (Compa\u00f1\u00eda Arrendataria del Monopolio de Petr\u00f3leos, SA) se parti\u00f3 en dos, la CAMPSA nacional y la republicana. Ambas funcionaron bien en la tarea de abastecer de combustibles petr\u00f3l\u00edferos a los dos\u2026","rel":"","context":"En \u00ab1938\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/11\/unriodepetroleo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":15180,"url":"https:\/\/aeropinakes.com\/wordpress\/1954\/02\/23\/el-franquismo-empieza-a-surfear-sobre-una-ola-de-petroleo\/","url_meta":{"origin":12003,"position":2},"title":"El franquismo empieza a surfear sobre una ola de petr\u00f3leo","date":"1954","format":false,"excerpt":"Vidaurreta y C\u00eda llevaba d\u00e9cadas importando y fabricando maquinaria agr\u00edcola, como los tractores CASE norteamericanos, cuando public\u00f3 este anuncio, un a\u00f1o despu\u00e9s de la firma de los acuerdos Espa\u00f1a - Estados Unidos. Fue una de las primeras se\u00f1ales de la acelerada petrolizaci\u00f3n que sufrir\u00eda el pa\u00eds en los veinte a\u00f1os\u2026","rel":"","context":"En \u00ab1954\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2019\/02\/1954-07-27-abc.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":18723,"url":"https:\/\/aeropinakes.com\/wordpress\/2025\/11\/16\/el-movimiento-nacional-surfea-sobre-una-ola-de-petroleo\/","url_meta":{"origin":12003,"position":3},"title":"El Movimiento Nacional surfea sobre una ola de petr\u00f3leo","date":"2025","format":false,"excerpt":"La refiner\u00eda de Escombreras, en el libro de propaganda Espa\u00f1a (1962). El Instituto Nacional de Industria public\u00f3 tres extra\u00f1as fotograf\u00edas en su memoria de 1950 (1). En ellas se ve un paisaje des\u00e9rtico con grandes estructuras circulares marcadas sobre el terreno. Los pies de las fotos revelan el misterio: no\u2026","rel":"","context":"En \u00abBlog\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2025\/11\/1962-refineriadeescombreras.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8613,"url":"https:\/\/aeropinakes.com\/wordpress\/1973\/09\/06\/air-spain-tropieza-con-el-petroleo\/","url_meta":{"origin":12003,"position":4},"title":"Air Spain tropieza con el petr\u00f3leo","date":"1973","format":false,"excerpt":"\u00a0 Un Douglas DC-8 de Air Spain con su colorida nueva librea (1973). \u00a0 En 1971 Air Spain consigui\u00f3 su primer DC-8, que superaba de largo en velocidad y tama\u00f1o a los Bristol Britannia que hasta entonces hab\u00edan formado su flota. Por desgracia, tambi\u00e9n era un avi\u00f3n muy sediento de\u2026","rel":"","context":"En \u00ab1973\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2016\/09\/douglasdc8airspain1973.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3931,"url":"https:\/\/aeropinakes.com\/wordpress\/1973\/03\/01\/la-aviacion-de-ypf\/","url_meta":{"origin":12003,"position":5},"title":"La aviaci\u00f3n de YPF","date":"1973","format":false,"excerpt":"- Un Avro 748 de YPF a mediados de la d\u00e9cada de 1970. A mediados de la d\u00e9cada de 1960, Yacimientos Petrol\u00edferos Fiscales, la compa\u00f1\u00eda petrolera nacional argentina, comenz\u00f3 a desarrollar una divisi\u00f3n de transporte a\u00e9reo, adquiriendo entre otros algunos Twin Otter. En 1973 recibi\u00f3 algunos Avro 748 de Aerol\u00edneas\u2026","rel":"","context":"En \u00ab1973\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1973\/03\/avrohs748ypf1976.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/12003"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=12003"}],"version-history":[{"count":2,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/12003\/revisions"}],"predecessor-version":[{"id":17491,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/12003\/revisions\/17491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/11980"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=12003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=12003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=12003"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=12003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}