{"id":11953,"date":"1936-11-11T17:18:17","date_gmt":"1936-11-11T17:18:17","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?post_type=material&#038;p=11953"},"modified":"2019-12-06T17:46:07","modified_gmt":"2019-12-06T16:46:07","slug":"la-tentativa-marxista-se-disipara-como-esta-humareda-negra","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1936\/11\/11\/la-tentativa-marxista-se-disipara-como-esta-humareda-negra\/","title":{"rendered":"\u00abLa tentativa marxista se disipar\u00e1 como esta humareda negra\u00bb"},"content":{"rendered":"<p><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/11\/malagaarde.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11954 size-full\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/11\/malagaarde.jpg\" alt=\"\" width=\"1000\" height=\"911\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/11\/malagaarde.jpg 1000w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/11\/malagaarde-300x273.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p><em>Ilustra\u00e7ao<\/em>, una de las revistas de mayor circulaci\u00f3n del Portugal del Estado Novo (denominaci\u00f3n oficial de la dictadura de Salazar) aprovecha la foto de una impresionante columna de humo negro \u2013creada por los bombarderos nacionalistas en los dep\u00f3sitos de CAMPSA de M\u00e1laga\u2013 para hacer un s\u00edmil algo embarullado entre la humareda y la Rep\u00fablica espa\u00f1ola: \u00abLa tentativa marxista se disipar\u00e1 como este humo negro de luto&#8230; cuando Espa\u00f1a vuelva a ser la Espa\u00f1a de siempre\u00bb. Pocos meses despu\u00e9s, en febrero de 1937, M\u00e1laga cay\u00f3 en manos del ej\u00e9rcito nacional, en una acci\u00f3n en la que participaron muchas unidades\u00a0 italianas.<\/p>\n<p>Ilustra\u00e7ao (Lisboa) 16 de septiembre de 1936. Hemeroteca Municipal de Lisboa.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ilustra\u00e7ao, una de las revistas de mayor circulaci\u00f3n del Portugal del Estado Novo (denominaci\u00f3n oficial de la dictadura de Salazar) aprovecha la foto de una &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":11954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":[]},"categories":[791,3216],"tags":[],"Asuntos":[2520,2540,2645],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/11\/malagaarde.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-36N","jetpack-related-posts":[{"id":132,"url":"https:\/\/aeropinakes.com\/wordpress\/1936\/12\/01\/ilustracao-lisboa-1-de-diciembre-de-1936\/","url_meta":{"origin":11953,"position":0},"title":"El aer\u00f3dromo de Getafe","date":"1936","format":false,"excerpt":"Ilustra\u00e7ao (Lisboa) 1 de diciembre de 1936 Hemeroteca Digital de Lisboa","rel":"","context":"En \u00ab1936\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2013\/06\/tumblr_mo8q91odbv1rbnd77o1_1280.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":111,"url":"https:\/\/aeropinakes.com\/wordpress\/1918\/01\/07\/lisboa-vista-de-aeroplano-ilustracao-portugueza\/","url_meta":{"origin":11953,"position":1},"title":"Lisboa vista de Aeroplano","date":"1918","format":false,"excerpt":"Lisboa vista de Aeroplano Ilustra\u00e7ao Portugueza - 7 de enero de 1918 Hemeroteca Municipal de Lisboa [codepeople-post-map cat=\"-1\"]","rel":"","context":"En \u00ab1918\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1918\/01\/lisboavistadeaeroplano.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1119,"url":"https:\/\/aeropinakes.com\/wordpress\/1924\/04\/02\/malaga-le-fort\/","url_meta":{"origin":11953,"position":2},"title":"Malaga &#8211; Le fort","date":"1924","format":false,"excerpt":"\u00a0 El castillo de M\u00e1laga visto desde un aeroplano L\u2019Ann\u00e9e A\u00e9ronautique 1923-1924 Gallica","rel":"","context":"En \u00ab1924\u00bb","img":{"alt_text":"malagaok","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/04\/malagaok.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":966,"url":"https:\/\/aeropinakes.com\/wordpress\/1925\/05\/30\/vista-area-de-malaga\/","url_meta":{"origin":11953,"position":3},"title":"Vista \u00e1rea de M\u00e1laga","date":"1925","format":false,"excerpt":"M\u00e1laga vista desde un aeroplano La Esfera, 30 de mayo de 1925 Biblioteca virtual de prensa hist\u00f3rica","rel":"","context":"En \u00ab1925\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/03\/1925-may-30-laesfera.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":976,"url":"https:\/\/aeropinakes.com\/wordpress\/1925\/08\/01\/vista-aerea-del-puerto-de-malaga\/","url_meta":{"origin":11953,"position":4},"title":"Vista a\u00e9rea del puerto de M\u00e1laga","date":"1925","format":false,"excerpt":"Andaluc\u00eda, Revista Ilustrada - \u00d3rgano regional del turismo 1 de agosto de 1925 Biblioteca virtual de prensa hist\u00f3rica","rel":"","context":"En \u00ab1925\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/03\/1925-ago-1-andalucia-revista-ilustrada-orgregdel-turismo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6887,"url":"https:\/\/aeropinakes.com\/wordpress\/1949\/11\/11\/toreros-y-furgonetas-aereas-cana\/","url_meta":{"origin":11953,"position":5},"title":"Toreros y furgonetas a\u00e9reas: CANA","date":"1949","format":false,"excerpt":"\u00a0 Uno de los tres Miles Aerovan con los que cont\u00f3 CANA en 1949, el \u00faltimo a\u00f1o de actividad de la compa\u00f1\u00eda. \u00a0 En 1949 Gerald Brenan volvi\u00f3 a Espa\u00f1a, pa\u00eds que no visitaba desde que se march\u00f3 como pudo de M\u00e1laga en los sangrientos d\u00edas de 1936. Describe como\u2026","rel":"","context":"En \u00ab1949\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2015\/11\/milesaerovancana1949.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/11953"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=11953"}],"version-history":[{"count":1,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/11953\/revisions"}],"predecessor-version":[{"id":16733,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/11953\/revisions\/16733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/11954"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=11953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=11953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=11953"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=11953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}