{"id":11267,"date":"1936-07-25T10:11:10","date_gmt":"1936-07-25T10:11:10","guid":{"rendered":"http:\/\/aeropinakes.com\/wordpress\/?post_type=material&#038;p=11267"},"modified":"2019-12-07T09:51:34","modified_gmt":"2019-12-07T08:51:34","slug":"25-de-julio-de-1936","status":"publish","type":"post","link":"https:\/\/aeropinakes.com\/wordpress\/1936\/07\/25\/25-de-julio-de-1936\/","title":{"rendered":"25 de julio de 1936"},"content":{"rendered":"<p><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/09\/prensa_0078.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11268 size-full\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/09\/prensa_0078.jpg\" alt=\"prensa_0078\" width=\"3200\" height=\"4440\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/09\/prensa_0078.jpg 3200w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/09\/prensa_0078-216x300.jpg 216w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/09\/prensa_0078-768x1066.jpg 768w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/09\/prensa_0078-738x1024.jpg 738w\" sizes=\"(max-width: 3200px) 100vw, 3200px\" \/><\/a><a href=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/09\/prensa_0486.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11269 size-full\" src=\"http:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/09\/prensa_0486.jpg\" alt=\"prensa_0486\" width=\"1878\" height=\"2635\" srcset=\"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/09\/prensa_0486.jpg 1878w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/09\/prensa_0486-214x300.jpg 214w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/09\/prensa_0486-768x1078.jpg 768w, https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/09\/prensa_0486-730x1024.jpg 730w\" sizes=\"(max-width: 1878px) 100vw, 1878px\" \/><\/a>Dos portadas de peri\u00f3dicos del 25 de julio de 1936, una de Alicante y otra de Palencia.<br \/>\nDe la hemeroteca del Ministerio de Cultura, <a href=\"http:\/\/prensahistorica.mcu.es\/\">prensa hist\u00f3rica.<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Dos portadas de peri\u00f3dicos del 25 de julio de 1936, una de Alicante y otra de Palencia. De la hemeroteca del Ministerio de Cultura, prensa &hellip; <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":11269,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":[]},"categories":[791,3230,2197,3212],"tags":[],"Asuntos":[2661,2660],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/09\/prensa_0486.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7HKWx-2VJ","jetpack-related-posts":[{"id":11686,"url":"https:\/\/aeropinakes.com\/wordpress\/1936\/07\/22\/tres-bandos-de-declaracion-del-estado-de-guerra-julio-de-1936\/","url_meta":{"origin":11267,"position":0},"title":"Tres bandos de declaraci\u00f3n del Estado de Guerra, julio de 1936","date":"1936","format":false,"excerpt":"1. La Gaceta de Tenerife, 19 de julio de 1936 2. El D\u00eda de Palencia, 22 de julio de 1936 3. Odiel (Huelva), 30 de julio de 1936","rel":"","context":"En \u00ab1936\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/10\/bandohuelva.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":18311,"url":"https:\/\/aeropinakes.com\/wordpress\/1937\/01\/01\/pijamas-para-la-guerra-total\/","url_meta":{"origin":11267,"position":1},"title":"Pijamas para la guerra total","date":"1937","format":false,"excerpt":"El D\u00eda de Alicante, 2 de octubre de 1936 La Voz, 12 de octubre de 1936 Labor (Soria) 1 de marzo de 1937 Azul (C\u00f3rdoba), 29 de abril de 1937 Bolet\u00edn Oficial de la Provincia de Soria, 9 de noviembre de 1937 Ministerio de Cultura \u2013 Biblioteca Virtual de Prensa\u2026","rel":"","context":"En \u00ab1936\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2021\/11\/1937-04-29-azulcordoba.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11726,"url":"https:\/\/aeropinakes.com\/wordpress\/1936\/07\/30\/la-recogida-de-la-cosecha-en-julio-de-1936\/","url_meta":{"origin":11267,"position":2},"title":"Mulas y algo de maquinaria: la recogida de la cosecha en julio de 1936","date":"1936","format":false,"excerpt":"Ahora (Madrid), 30 de julio de 1936- Biblioteca Nacional de Espa\u00f1a.","rel":"","context":"En \u00ab1936\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/10\/ahoramadrid30jul1936.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":12207,"url":"https:\/\/aeropinakes.com\/wordpress\/2017\/07\/19\/el-19-de-julio-de-1936-en-barcelona\/","url_meta":{"origin":11267,"position":3},"title":"El 19 de julio de 1936 en Barcelona","date":"2017","format":false,"excerpt":"Cr\u00f3nica, 2 de agosto de 1936 Biblioteca Nacional de Espa\u00f1a \u2013 Hemeroteca Digital","rel":"","context":"En \u00ab1936\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/1936\/07\/barcelonajulio1936.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11141,"url":"https:\/\/aeropinakes.com\/wordpress\/1936\/07\/21\/los-oficiales-leales-ensenan-a-los-obreros-el-funcionamiento-de-los-fusiles\/","url_meta":{"origin":11267,"position":4},"title":"Los oficiales leales ense\u00f1an a los obreros el funcionamiento de los fusiles","date":"1936","format":false,"excerpt":"El Liberal (Madrid) 21 de julio de 1936","rel":"","context":"En \u00ab1936\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/09\/21-julio-1936-elliberalmadrid.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11682,"url":"https:\/\/aeropinakes.com\/wordpress\/1936\/07\/19\/bandos-como-declarar-el-estado-de-guerra\/","url_meta":{"origin":11267,"position":5},"title":"Bandos: c\u00f3mo declarar el Estado de Guerra","date":"1936","format":false,"excerpt":"(Click en la imagen para ver el texto completo) \u00a0 Don Francisco Franco Bahomonde, General de Divisi\u00f3n comandante militar de las islas Canarias. HAGO SABER: Que de conformidad con lo prevenido en el art\u00edculo 36 y sus concordantes 7, n\u00famero 12, 9, n\u00famero 3 y 171 del C\u00f3digo de Justicia\u2026","rel":"","context":"En \u00ab1936\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aeropinakes.com\/wordpress\/wp-content\/uploads\/2017\/10\/bandofrancoexcerpt.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/11267"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/comments?post=11267"}],"version-history":[{"count":1,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/11267\/revisions"}],"predecessor-version":[{"id":16749,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts\/11267\/revisions\/16749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media\/11269"}],"wp:attachment":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/media?parent=11267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/categories?post=11267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/tags?post=11267"},{"taxonomy":"asunto","embeddable":true,"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos?post=11267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}