{"id":2670,"count":2,"description":"","link":"https:\/\/aeropinakes.com\/wordpress\/asunto\/fiestas\/","name":"Fiestas","slug":"fiestas","taxonomy":"asunto","meta":[],"_links":{"self":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos\/2670"}],"collection":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/Asuntos"}],"about":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/taxonomies\/asunto"}],"wp:post_type":[{"href":"https:\/\/aeropinakes.com\/wordpress\/wp-json\/wp\/v2\/posts?Asuntos=2670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}